{"id":1212,"date":"2018-03-15T15:16:20","date_gmt":"2018-03-15T18:16:20","guid":{"rendered":"http:\/\/www.sabra.org.br\/site\/?p=1212"},"modified":"2025-04-20T19:13:32","modified_gmt":"2025-04-20T22:13:32","slug":"edital-para-a-orquestra-sinfonica-de-betim-2018","status":"publish","type":"post","link":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/","title":{"rendered":"Edital para a Orquestra Sinf\u00f4nica de Betim 2018"},"content":{"rendered":"<p>Est\u00e1 dispon\u00edvel o Edital de sele\u00e7\u00e3o de candidatos para preenchimento de vagas para a Orquestra Sinf\u00f4nica de Betim em 2018. <a href=\"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2018\/03\/EDITAL_001_2018_OSBetim2018.pdf\" target=\"_blank\" rel=\"noopener\"><em>Download<\/em><\/a><\/p>\n<p>A Orquestra Sinf\u00f4nica de Betim teve o in\u00edcio de suas atividades em 2014 como uma Orquestra de C\u00e2mara, formada exclusivamente por instrumentos de corda. Em 2015 foram abertas vagas para os naipes de madeiras, metais e percuss\u00e3o, proporcionando a forma\u00e7\u00e3o sinf\u00f4nica.<\/p>\n<p>A iniciativa de constitui\u00e7\u00e3o da Orquestra Sinf\u00f4nica de Betim prop\u00f5e a supera\u00e7\u00e3o das dificuldades encontradas no Brasil para a forma\u00e7\u00e3o de conjuntos musicais est\u00e1veis e duradouros. Al\u00e9m de permitir o acesso a um bem cultural que se encontra fora do alcance da maior parte da popula\u00e7\u00e3o, o projeto proporciona o aprimoramento t\u00e9cnico e art\u00edstico de jovens m\u00fasicos, criando perspectivas de profissionaliza\u00e7\u00e3o e gera\u00e7\u00e3o de renda. Neste sentido, a realiza\u00e7\u00e3o de centenas de concertos p\u00fablicos gratuitos da Orquestra e Corais envolvidos nos \u00faltimos anos beneficiaram a mais de 80 mil pessoas, especialmente crian\u00e7as, professores e funcion\u00e1rios da rede p\u00fablica municipal de Betim. S\u00e3o tamb\u00e9m beneficiados 74 jovens m\u00fasicos que al\u00e9m de uma bolsa incentivo, recebem orienta\u00e7\u00e3o t\u00e9cnica e art\u00edstica de profissionais atuantes nas Orquestras Sinf\u00f4nica de Minas Gerais e Filarm\u00f4nica de Minas Gerais e do Centro de Forma\u00e7\u00e3o Art\u00edstica da Funda\u00e7\u00e3o Cl\u00f3vis Salgado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 dispon\u00edvel o Edital de sele\u00e7\u00e3o de candidatos para preenchimento de vagas para a Orquestra Sinf\u00f4nica de Betim em 2018. Download A Orquestra Sinf\u00f4nica de&hellip;<\/p>\n","protected":false},"author":39,"featured_media":347,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4],"tags":[15,8,16,12,11,9],"class_list":["post-1212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-assistencia-social","tag-canto-coral","tag-musicalizacao-infantil","tag-oficina-musical-sabra","tag-orquestra-sinfonica-de-betim","tag-sociedade-artistica-brasileira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Edital para a Orquestra Sinf\u00f4nica de Betim 2018 - SABRA - Sociedade Art\u00edstica Brasileira<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edital para a Orquestra Sinf\u00f4nica de Betim 2018 - SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"og:description\" content=\"Est\u00e1 dispon\u00edvel o Edital de sele\u00e7\u00e3o de candidatos para preenchimento de vagas para a Orquestra Sinf\u00f4nica de Betim em 2018. Download A Orquestra Sinf\u00f4nica de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabrabrasil\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-15T18:16:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-20T22:13:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2016\/05\/miniatura-754A1478.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"224\" \/>\n\t<meta property=\"og:image:height\" content=\"149\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:site\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/edital-para-a-orquestra-sinfonica-de-betim-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/edital-para-a-orquestra-sinfonica-de-betim-2018\\\/\"},\"author\":{\"name\":\"M\u00e1rcio Miranda Pontes\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\"},\"headline\":\"Edital para a Orquestra Sinf\u00f4nica de Betim 2018\",\"datePublished\":\"2018-03-15T18:16:20+00:00\",\"dateModified\":\"2025-04-20T22:13:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/edital-para-a-orquestra-sinfonica-de-betim-2018\\\/\"},\"wordCount\":247,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/edital-para-a-orquestra-sinfonica-de-betim-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/miniatura-754A1478.jpg\",\"keywords\":[\"Assist\u00eancia social\",\"Canto Coral\",\"Musicaliza\u00e7\u00e3o Infantil\",\"Oficina Musical SABRA\",\"Orquestra Sinf\u00f4nica de Betim\",\"Sociedade Art\u00edstica Brasileira\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/edital-para-a-orquestra-sinfonica-de-betim-2018\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/edital-para-a-orquestra-sinfonica-de-betim-2018\\\/\",\"name\":\"Edital para a Orquestra Sinf\u00f4nica de Betim 2018 - SABRA - Sociedade Art\u00edstica Brasileira\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/edital-para-a-orquestra-sinfonica-de-betim-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/edital-para-a-orquestra-sinfonica-de-betim-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/miniatura-754A1478.jpg\",\"datePublished\":\"2018-03-15T18:16:20+00:00\",\"dateModified\":\"2025-04-20T22:13:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/edital-para-a-orquestra-sinfonica-de-betim-2018\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/edital-para-a-orquestra-sinfonica-de-betim-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/edital-para-a-orquestra-sinfonica-de-betim-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/miniatura-754A1478.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/miniatura-754A1478.jpg\",\"width\":224,\"height\":149,\"caption\":\"Sociedade Art\u00edstica Brasileira SABRA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/edital-para-a-orquestra-sinfonica-de-betim-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Edital para a Orquestra Sinf\u00f4nica de Betim 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"name\":\"SABRA - Sociedade Art\u00edstica Brasileira\",\"description\":\"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\",\"name\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\",\"alternateName\":\"SABRA\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"width\":400,\"height\":128,\"caption\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sabrabrasil\",\"https:\\\/\\\/x.com\\\/ContatoSabra\",\"https:\\\/\\\/www.instagram.com\\\/sabrabrasil\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/25002088\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/sociedadeartisticabrasileira\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/sabrabrasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\",\"name\":\"M\u00e1rcio Miranda Pontes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"caption\":\"M\u00e1rcio Miranda Pontes\"},\"sameAs\":[\"http:\\\/\\\/www.sabra.org.br\"],\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/author\\\/marcio-miranda-pontes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Edital para a Orquestra Sinf\u00f4nica de Betim 2018 - SABRA - Sociedade Art\u00edstica Brasileira","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/","og_locale":"pt_BR","og_type":"article","og_title":"Edital para a Orquestra Sinf\u00f4nica de Betim 2018 - SABRA - Sociedade Art\u00edstica Brasileira","og_description":"Est\u00e1 dispon\u00edvel o Edital de sele\u00e7\u00e3o de candidatos para preenchimento de vagas para a Orquestra Sinf\u00f4nica de Betim em 2018. Download A Orquestra Sinf\u00f4nica de&hellip;","og_url":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/","og_site_name":"SABRA - Sociedade Art\u00edstica Brasileira","article_publisher":"https:\/\/www.facebook.com\/sabrabrasil","article_published_time":"2018-03-15T18:16:20+00:00","article_modified_time":"2025-04-20T22:13:32+00:00","og_image":[{"width":224,"height":149,"url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2016\/05\/miniatura-754A1478.jpg","type":"image\/jpeg"}],"author":"M\u00e1rcio Miranda Pontes","twitter_card":"summary_large_image","twitter_creator":"@ContatoSabra","twitter_site":"@ContatoSabra","twitter_misc":{"Escrito por":"M\u00e1rcio Miranda Pontes","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/#article","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/"},"author":{"name":"M\u00e1rcio Miranda Pontes","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2"},"headline":"Edital para a Orquestra Sinf\u00f4nica de Betim 2018","datePublished":"2018-03-15T18:16:20+00:00","dateModified":"2025-04-20T22:13:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/"},"wordCount":247,"commentCount":0,"publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2016\/05\/miniatura-754A1478.jpg","keywords":["Assist\u00eancia social","Canto Coral","Musicaliza\u00e7\u00e3o Infantil","Oficina Musical SABRA","Orquestra Sinf\u00f4nica de Betim","Sociedade Art\u00edstica Brasileira"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/","url":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/","name":"Edital para a Orquestra Sinf\u00f4nica de Betim 2018 - SABRA - Sociedade Art\u00edstica Brasileira","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/#primaryimage"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2016\/05\/miniatura-754A1478.jpg","datePublished":"2018-03-15T18:16:20+00:00","dateModified":"2025-04-20T22:13:32+00:00","breadcrumb":{"@id":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/#primaryimage","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2016\/05\/miniatura-754A1478.jpg","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2016\/05\/miniatura-754A1478.jpg","width":224,"height":149,"caption":"Sociedade Art\u00edstica Brasileira SABRA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.sabra.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Edital para a Orquestra Sinf\u00f4nica de Betim 2018"}]},{"@type":"WebSite","@id":"https:\/\/www.sabra.org.br\/site\/#website","url":"https:\/\/www.sabra.org.br\/site\/","name":"SABRA - Sociedade Art\u00edstica Brasileira","description":"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico","publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sabra.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.sabra.org.br\/site\/#organization","name":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA","alternateName":"SABRA","url":"https:\/\/www.sabra.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","width":400,"height":128,"caption":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabrabrasil","https:\/\/x.com\/ContatoSabra","https:\/\/www.instagram.com\/sabrabrasil\/","https:\/\/www.linkedin.com\/company\/25002088\/","https:\/\/br.pinterest.com\/sociedadeartisticabrasileira\/","https:\/\/www.youtube.com\/c\/sabrabrasil"]},{"@type":"Person","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2","name":"M\u00e1rcio Miranda Pontes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","caption":"M\u00e1rcio Miranda Pontes"},"sameAs":["http:\/\/www.sabra.org.br"],"url":"https:\/\/www.sabra.org.br\/site\/author\/marcio-miranda-pontes\/"}]}},"jetpack_featured_media_url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2016\/05\/miniatura-754A1478.jpg","jetpack_shortlink":"https:\/\/wp.me\/p95j2Z-jy","jetpack-related-posts":[{"id":1712,"url":"https:\/\/www.sabra.org.br\/site\/orquestra-sinfonica-de-betim-2019\/","url_meta":{"origin":1212,"position":0},"title":"Edital do curso Orquestra Sinf\u00f4nica em Betim 2019","author":"M\u00e1rcio Miranda Pontes","date":"22 de janeiro de 2019","format":false,"excerpt":"Est\u00e1 dispon\u00edvel o Edital de sele\u00e7\u00e3o de candidatos para preenchimento de vagas para o Curso de Orquestra Sinf\u00f4nica em Betim - 2019. A Orquestra Sinf\u00f4nica de Betim teve o in\u00edcio de suas atividades em 2014 como uma Orquestra de C\u00e2mara, formada exclusivamente por instrumentos de corda. Em 2015 foram abertas\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/www.sabra.org.br\/site\/category\/noticias\/"},"img":{"alt_text":"Orquestra Sinf\u00f4nica de Betim","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2017\/12\/OSBetim.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2017\/12\/OSBetim.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2017\/12\/OSBetim.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2017\/12\/OSBetim.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":403,"url":"https:\/\/www.sabra.org.br\/site\/edital-para-a-orquestra-sinfonica-de-betim-2017\/","url_meta":{"origin":1212,"position":1},"title":"Edital para a Orquestra Sinf\u00f4nica de Betim 2017","author":"M\u00e1rcio Miranda Pontes","date":"30 de novembro de 2016","format":false,"excerpt":"Est\u00e1 dispon\u00edvel o Edital de sele\u00e7\u00e3o de candidatos para preenchimento de vagas para a Orquestra Sinf\u00f4nica de Betim em 2017. \u00a0\u00a0Download A Orquestra Sinf\u00f4nica de Betim teve o in\u00edcio de suas atividades em 2014 como uma Orquestra de C\u00e2mara, formada exclusivamente por instrumentos de corda. Em 2015 foram abertas vagas\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/www.sabra.org.br\/site\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6773,"url":"https:\/\/www.sabra.org.br\/site\/orquestra2023\/","url_meta":{"origin":1212,"position":2},"title":"Orquestra Sinf\u00f4nica de Betim 2023","author":"M\u00e1rcio Miranda Pontes","date":"21 de mar\u00e7o de 2023","format":false,"excerpt":"A Sociedade Art\u00edstica Brasileira (SABRA) est\u00e1 com vagas abertas para o curso de Orquestra Sinf\u00f4nica. S\u00e3o 55 vagas abertas, sendo 53 para instrumentistas e duas para assistente de produ\u00e7\u00e3o. Podem participar candidatos com 16 anos ou mais, que morem na Regi\u00e3o Metropolitana de Belo Horizonte. \u00c9 preciso comprovar conhecimento dos\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/www.sabra.org.br\/site\/category\/noticias\/"},"img":{"alt_text":"orquestra-sinf\u00f4nica-sabra-betim-escola-m\u00fasica","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/Orquestra-Sinfonica-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/Orquestra-Sinfonica-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/Orquestra-Sinfonica-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/Orquestra-Sinfonica-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/Orquestra-Sinfonica-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/Orquestra-Sinfonica-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":4747,"url":"https:\/\/www.sabra.org.br\/site\/edital-metais-2022\/","url_meta":{"origin":1212,"position":3},"title":"Vagas para metais no Curso Orquestra Sinf\u00f4nica de Betim","author":"M\u00e1rcio Miranda Pontes","date":"22 de fevereiro de 2022","format":false,"excerpt":"Edital Orquestra Sinf\u00f4nica de Betim com vagas para Trompas, Trombones e Assistente de Produ\u00e7\u00e3o.","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/www.sabra.org.br\/site\/category\/noticias\/"},"img":{"alt_text":"vaga-metal-trompa-trombone","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/02\/horn-g0606b8ae2_1280.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/02\/horn-g0606b8ae2_1280.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/02\/horn-g0606b8ae2_1280.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/02\/horn-g0606b8ae2_1280.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/02\/horn-g0606b8ae2_1280.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4787,"url":"https:\/\/www.sabra.org.br\/site\/resultado-edital-010-2022-orquestra-sinfonica\/","url_meta":{"origin":1212,"position":4},"title":"Resultado Edital 010\/2022 &#8211; Orquestra Sinf\u00f4nica","author":"M\u00e1rcio Miranda Pontes","date":"2 de mar\u00e7o de 2022","format":false,"excerpt":"Confira o resultado do Edital 010\/2022 e veja a lista dos aprovados para o curso da Orquestra Sinf\u00f4nica de Betim.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"sabra-m\u00fasica-sinestesia-experi\u00eancias-sensoriais-sentidos-sinest\u00e9sica-associados-cor-exploraremos-musical-percep\u00e7\u00f5es-resultado-edital","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2024\/04\/a-conexao-entre-a-musica-e-as-experiencias-sensoriais-na-sinestesia-20240229111914.jpg-jpg.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2024\/04\/a-conexao-entre-a-musica-e-as-experiencias-sensoriais-na-sinestesia-20240229111914.jpg-jpg.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2024\/04\/a-conexao-entre-a-musica-e-as-experiencias-sensoriais-na-sinestesia-20240229111914.jpg-jpg.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2024\/04\/a-conexao-entre-a-musica-e-as-experiencias-sensoriais-na-sinestesia-20240229111914.jpg-jpg.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4251,"url":"https:\/\/www.sabra.org.br\/site\/orquestra-4\/","url_meta":{"origin":1212,"position":5},"title":"Aprovados para vagas suplementares no Curso \u201cOrquestra Sinf\u00f4nica de Betim\u201d 2021","author":"M\u00e1rcio Miranda Pontes","date":"14 de outubro de 2021","format":false,"excerpt":"A SOCIEDADE ART\u00cdSTICA BRASILEIRA \u2013 SABRA, parabeniza todos os candidatos e candidatas participantes no processo seletivo para as vagas no curso da Orquestra Sinf\u00f4nica de Betim e publica, como previsto no Edital de Sele\u00e7\u00e3o 010\/2021, a lista dos aprovados para o ano de 2021. Os candidatos e candidatas aprovados dever\u00e3o\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/www.sabra.org.br\/site\/category\/noticias\/"},"img":{"alt_text":"orquestra-m\u00fasica-tipo","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/05\/saiba-quais-sao-os-tipos-de-orquestra-existem-20210203092956.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/05\/saiba-quais-sao-os-tipos-de-orquestra-existem-20210203092956.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/05\/saiba-quais-sao-os-tipos-de-orquestra-existem-20210203092956.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/05\/saiba-quais-sao-os-tipos-de-orquestra-existem-20210203092956.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/1212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/comments?post=1212"}],"version-history":[{"count":0,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/1212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media\/347"}],"wp:attachment":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media?parent=1212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/categories?post=1212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/tags?post=1212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}