{"id":1407,"date":"2018-08-17T08:54:26","date_gmt":"2018-08-17T11:54:26","guid":{"rendered":"http:\/\/www.sabra.org.br\/site\/?p=1407"},"modified":"2025-04-20T19:14:22","modified_gmt":"2025-04-20T22:14:22","slug":"projetos-artisticos-evolucao-criatividade","status":"publish","type":"post","link":"https:\/\/www.sabra.org.br\/site\/projetos-artisticos-evolucao-criatividade\/","title":{"rendered":"Projetos art\u00edsticos: A evolu\u00e7\u00e3o da criatividade"},"content":{"rendered":"<h4>A forma\u00e7\u00e3o da criatividade<\/h4>\n<p>Muito se \u00e9 falado sobre a natureza da criatividade. Diversos autores defendem se a crian\u00e7a nasce com um talento ou n\u00e3o, enquanto outros contestam afirmando que a criatividade \u00e9 algo que pode ser aprendido. O que se sabe com certeza \u00e9 que as<a href=\"https:\/\/www.sabra.org.br\/site\/ciencia-bebes-que-ouvem-musica-classica-ficam-mesmo-mais-inteligentes\/\" target=\"_blank\" rel=\"noopener\"> experi\u00eancias da crian\u00e7a<\/a> influenciam diretamente no seu desenvolvimento; por consequ\u00eancia, \u00e9 poss\u00edvel estimular elas a passarem mais tempo tentando inovar e menos tempo imitando.<\/p>\n<p>A educa\u00e7\u00e3o musical \u00e9 um problema, pois n\u00e3o se conhecem completamente as bases que fazem um indiv\u00edduo aprender com facilidade a desenvolver o seu ouvido para m\u00fasico enquanto outros ficam estagnados, mas podemos afirmar que a escola tem um papel fundamental, e, infelizmente, a realidade que encontramos nas escolas \u00e9 de que essa \u00e1rea do conhecimento \u00e9 deixada de um pouco de lado. Uma crian\u00e7a que teria um talento em potencial pode ser desestimulada com essa falta de incentivo.<\/p>\n<p>O ser humano aprende atrav\u00e9s da imita\u00e7\u00e3o: o beb\u00ea ouve as palavras dos pais e as repete. Conforme o tempo passa mais palavras ele ouve, mais frases s\u00e3o constru\u00eddas, e mais ele passa a entender como a l\u00edngua funciona. Assim \u00e9 a criatividade. Quanto mais a crian\u00e7a conhece as diferentes nuances musicais, \u00e9 estimulada a tocar instrumentos e a conhecer diferentes g\u00eaneros, mais o seu repert\u00f3rio de pesquisa cresce. Estimulando a crian\u00e7a a se relacionar com o ambiente e com a m\u00fasica, mais ela poder\u00e1 ligar pontos por si s\u00f3, criando caminhos que ningu\u00e9m nunca antes imaginou ser poss\u00edveis.<\/p>\n<h4>A import\u00e2ncia da m\u00fasica para a crian\u00e7a<\/h4>\n<p>A paix\u00e3o por essa arte pode surgir em qualquer idade, e o est\u00edmulo pode levar a todos os caminhos imagin\u00e1veis. No passado era comum encontrar crian\u00e7as no coral da igreja; essas crian\u00e7as eram tidas como talentos, e realmente eram, pois nelas foi poss\u00edvel desenvolver a voz de uma maneira que se alcan\u00e7asse um outro mundo, elevando as pessoas. Fora do aspecto religioso, a m\u00fasica continua tendo esse car\u00e1ter, ela surgiu para encantar atrav\u00e9s dos ouvidos.<\/p>\n<p>Uma <a href=\"https:\/\/super.abril.com.br\/mundo-estranho\/qual-a-diferenca-entre-orquestra-sinfonica-filarmonica-e-de-camara\/\" target=\"_blank\" rel=\"noopener\">orquestra sinf\u00f4nica<\/a>, composta por in\u00fameros instrumentos sendo tocados ao mesmo tempo, teria tudo para simplesmente ser uma confus\u00e3o, mas por que n\u00e3o \u00e9? Porque o maestro tem, na hora de escrever, todos os sons em sua cabe\u00e7a. Sons que j\u00e1 conhece, mas que agrupa de diferentes maneiras at\u00e9 criar algo \u00fanico, diferindo absolutamente de tudo o que j\u00e1 visto.<\/p>\n<p>A ci\u00eancia n\u00e3o tem uma conclus\u00e3o sobre como induzir a criatividade em um indiv\u00edduo, mas uma das poucas certezas \u00e9 a pesquisa. Quando maior for o repert\u00f3rio, maiores ser\u00e3o os resultados obtidos. A m\u00fasica \u00e9 um dos componentes fundamentais para criar um adulto que entende o mundo, consegue fazer as liga\u00e7\u00f5es necess\u00e1rias entre os fatos, e principalmente, que possui um talento para uma arte que jamais ser\u00e1 deixada para tr\u00e1s.<\/p>\n<p>A criatividade deve ser alimentada constantemente, se n\u00e3o ela n\u00e3o sobrevive. Manter-se atualizado e conhecer diferentes \u00e1reas de diferentes conhecimentos \u00e9 uma boa maneira de saber quais rumos tomar para desenvolver o seu talento da melhor maneira poss\u00edvel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A forma\u00e7\u00e3o da criatividade Muito se \u00e9 falado sobre a natureza da criatividade. Diversos autores defendem se a crian\u00e7a nasce com um talento ou n\u00e3o,&hellip;<\/p>\n","protected":false},"author":39,"featured_media":1410,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_customify_content_layout":"","_customify_sidebar":"","_customify_page_header_display":"","_customify_disable_header":"","_customify_disable_header_top":"","_customify_disable_header_main":"","_customify_disable_header_bottom":"","_customify_disable_page_title":"","_customify_disable_content_vertical_padding":"","_customify_disable_footer_top":"","_customify_disable_footer_main":"","_customify_disable_footer_bottom":"","_customify_breadcrumb_display":"","_customify_header_transparent_display":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[15,8,33,16,12,11,9],"class_list":["post-1407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-sabra","tag-assistencia-social","tag-canto-coral","tag-criatividade","tag-musicalizacao-infantil","tag-oficina-musical-sabra","tag-orquestra-sinfonica-de-betim","tag-sociedade-artistica-brasileira"],"jetpack_featured_media_url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2018\/08\/projetos-artisticos-a-evolucao-da-criatividade-20180417140635.jpg-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p95j2Z-mH","jetpack-related-posts":[{"id":2900,"url":"https:\/\/www.sabra.org.br\/site\/estimular-a-criatividade\/","url_meta":{"origin":1407,"position":0},"title":"Estimular a criatividade","author":"M\u00e1rcio Miranda Pontes","date":"1 de maio de 2020","format":false,"excerpt":"Estimular a criatividade das crian\u00e7as \u00e9 dever de pais e educadores. Com a ajuda das institui\u00e7\u00f5es de ensino e de organiza\u00e7\u00f5es que incentivam a educa\u00e7\u00e3o, a cultura e a cidadania, essa tarefa pode ser ainda mais transformadora. Saiba mais.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"criatividade","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/05\/conheca-x-formas-de-estimular-a-criatividade-do-seu-filho-20200317174456.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/05\/conheca-x-formas-de-estimular-a-criatividade-do-seu-filho-20200317174456.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/05\/conheca-x-formas-de-estimular-a-criatividade-do-seu-filho-20200317174456.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/05\/conheca-x-formas-de-estimular-a-criatividade-do-seu-filho-20200317174456.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4231,"url":"https:\/\/www.sabra.org.br\/site\/criatividade\/","url_meta":{"origin":1407,"position":1},"title":"A m\u00fasica como fator importante para o desenvolvimento criativo das crian\u00e7as","author":"M\u00e1rcio Miranda Pontes","date":"28 de setembro de 2021","format":false,"excerpt":"A m\u00fasica como fator importante para o desenvolvimento criativo das crian\u00e7as Atrav\u00e9s da m\u00fasica \u00e9 poss\u00edvel estimular o c\u00e9rebro e, assim, aprimorar as mais diversas habilidades e aptid\u00f5es. Nesse contexto, impulsionar o desenvolvimento criativo \u00e9 um dos grandes pap\u00e9is da m\u00fasica, principalmente para as crian\u00e7as. Patroci\u0301nio m\u00e1ster: @institutounimedbh, viabilizado pelo\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"criatividade-estimular-musica","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/09\/a-musica-como-fator-importante-para-o-desenvolvimento-criativo-das-criancas-20210125102928.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/09\/a-musica-como-fator-importante-para-o-desenvolvimento-criativo-das-criancas-20210125102928.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/09\/a-musica-como-fator-importante-para-o-desenvolvimento-criativo-das-criancas-20210125102928.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/09\/a-musica-como-fator-importante-para-o-desenvolvimento-criativo-das-criancas-20210125102928.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13304,"url":"https:\/\/www.sabra.org.br\/site\/aprenda-a-estimular-o-talento-musical-do-seu-filho\/","url_meta":{"origin":1407,"position":2},"title":"Aprenda a estimular o talento musical do seu filho","author":"","date":"22 de agosto de 2025","format":false,"excerpt":"A m\u00fasica possui um poder transformador na vida das crian\u00e7as, estimulando a criatividade, a express\u00e3o emocional e o desenvolvimento cognitivo. Neste artigo, vamos compartilhar dicas valiosas para ajudar voc\u00ea a estimular o talento musical do seu filho. A Sabra, uma institui\u00e7\u00e3o comprometida com a promo\u00e7\u00e3o da arte e cultura, busca\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":13301,"url":"https:\/\/www.sabra.org.br\/site\/saiba-como-explorar-a-criatividade-atraves-da-musicalizacao\/","url_meta":{"origin":1407,"position":3},"title":"Saiba como explorar a criatividade atrav\u00e9s da musicaliza\u00e7\u00e3o","author":"","date":"22 de agosto de 2025","format":false,"excerpt":"A m\u00fasica \u00e9 uma fonte inesgot\u00e1vel de inspira\u00e7\u00e3o e criatividade. Neste artigo, vamos explorar como a musicaliza\u00e7\u00e3o pode ser uma ferramenta poderosa para despertar e explorar a criatividade em pessoas de todas as idades. A Sabra, uma institui\u00e7\u00e3o comprometida com a promo\u00e7\u00e3o da arte e cultura, busca engajar seu p\u00fablico-alvo\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1490,"url":"https:\/\/www.sabra.org.br\/site\/conheca-a-relacao-entre-educacao-musical-infantil-e-criatividade\/","url_meta":{"origin":1407,"position":4},"title":"Conhe\u00e7a a rela\u00e7\u00e3o entre Educa\u00e7\u00e3o musical infantil e Criatividade","author":"M\u00e1rcio Miranda Pontes","date":"11 de setembro de 2018","format":false,"excerpt":"Cada vez mais, escolas p\u00fablicas e privadas t\u00eam investido na educa\u00e7\u00e3o musical infantil de seus estudantes. Mas, quais os benef\u00edcios dessa musicaliza\u00e7\u00e3o ainda na inf\u00e2ncia, e como esse ensino se relaciona com a criatividade nos pequenos? Neste texto, falaremos um pouco mais sobre educa\u00e7\u00e3o musical infantil e criatividade. Quer saber\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"Educa\u00e7\u00e3o Musical","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2018\/09\/conheca-a-relacao-entre-educacao-musical-infantil-e-criatividade-20180702161300.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2018\/09\/conheca-a-relacao-entre-educacao-musical-infantil-e-criatividade-20180702161300.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2018\/09\/conheca-a-relacao-entre-educacao-musical-infantil-e-criatividade-20180702161300.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2018\/09\/conheca-a-relacao-entre-educacao-musical-infantil-e-criatividade-20180702161300.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1611,"url":"https:\/\/www.sabra.org.br\/site\/criatividade-relaxamento\/","url_meta":{"origin":1407,"position":5},"title":"M\u00daSICA, CRIATIVIDADE E RELAXAMENTO","author":"M\u00e1rcio Miranda Pontes","date":"30 de outubro de 2018","format":false,"excerpt":"\u00c9 impressionante como estamos em contato com a m\u00fasica o tempo todo. Isso come\u00e7a muito cedo, pois logo nos primeiros meses de vida ganhamos brinquedos que emitem pequenas melodias. Ouvimos m\u00fasicas enquanto praticamos exerc\u00edcios, dirigimos, cozinhamos, e at\u00e9 mesmo quando estamos trabalhando. Sem falar nas festas, as m\u00fasicas s\u00e3o requisitos\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"M\u00fasica, relaxamento e criatividade","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2018\/10\/musica-os-efeitos-que-ela-causa-no-cerebro-humano-20180705134730.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2018\/10\/musica-os-efeitos-que-ela-causa-no-cerebro-humano-20180705134730.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2018\/10\/musica-os-efeitos-que-ela-causa-no-cerebro-humano-20180705134730.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2018\/10\/musica-os-efeitos-que-ela-causa-no-cerebro-humano-20180705134730.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/1407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/comments?post=1407"}],"version-history":[{"count":0,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/1407\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media\/1410"}],"wp:attachment":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media?parent=1407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/categories?post=1407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/tags?post=1407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}