{"id":2124,"date":"2019-06-05T22:57:03","date_gmt":"2019-06-06T01:57:03","guid":{"rendered":"https:\/\/www.sabra.org.br\/site\/?p=2124"},"modified":"2025-04-20T19:17:26","modified_gmt":"2025-04-20T22:17:26","slug":"inspiracao-2","status":"publish","type":"post","link":"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/","title":{"rendered":"Inspira\u00e7\u00e3o"},"content":{"rendered":"<h2>Voc\u00ea sabe onde e como os grandes artistas buscam inspira\u00e7\u00e3o?<\/h2>\n<p>Voc\u00ea j\u00e1 parou para pensar o qu\u00e3o impressionante \u00e9 a m\u00fasica, ou qualquer outro tipo de express\u00e3o art\u00edstica? Um artista, que voc\u00ea jamais conheceu, criou uma pe\u00e7a que emocionou voc\u00ea, assim como diversas outras pessoas. Isso gera uma grande d\u00favida: de onde um artista cria a inspira\u00e7\u00e3o para criar obras t\u00e3o preciosas?<\/p>\n<h2>A m\u00fasica como fonte de inspira\u00e7\u00e3o<\/h2>\n<p>Grande parte dos artistas usa a m\u00fasica como uma forma de inspira\u00e7\u00e3o. Muitos m\u00fasicos citam outros artistas como refer\u00eancia e parte dessa inspira\u00e7\u00e3o \u00e9 t\u00e9cnica. Por isso, aproveitam a bagagem musical de outros m\u00fasicos para compor suas obras, a fim de colocar a pr\u00f3pria interpreta\u00e7\u00e3o em algo que eles admiram e gostam.<\/p>\n<p>Isso faz com que seja muito comum encontrar refer\u00eancias a outros m\u00fasicos em obras de artistas muito famosos. Um exemplo disso, \u00e9 a m\u00fasica cl\u00e1ssica, os Beatles e in\u00fameras outras refer\u00eancias, que s\u00e3o fonte de inspira\u00e7\u00e3o para diversos artistas.<\/p>\n<p>Parte da magia da m\u00fasica \u00e9 compartilh\u00e1-la com as pessoas, e existem poucas formas melhores de fazer isso que incorporando a obra de outro artista, feita em outro momento e com outro significado, a sua pr\u00f3pria obra.<\/p>\n<p>Outros artistas ainda, buscam formas diferentes de se inspirar dentro da m\u00fasica. Como por exemplo, transformar um canto em uma m\u00fasica instrumental, ou misturar ambos, \u00e9 uma grande forma de inspira\u00e7\u00e3o para m\u00fasicos.<\/p>\n<h2>A literatura<\/h2>\n<p>A literatura e a m\u00fasica t\u00eam muito em comum. Ambos tocam em nossos sentimentos, emo\u00e7\u00f5es e, principalmente, em nossa imagina\u00e7\u00e3o. Por isso, muitos m\u00fasicos, especialmente os mais cl\u00e1ssicos, encontram na literatura uma fonte de inspira\u00e7\u00e3o. Ao ler uma passagem muito tocante, o m\u00fasico sente a curiosidade natural de saber como transmitir a mesma emo\u00e7\u00e3o, ou como complementar a emo\u00e7\u00e3o do livro, atrav\u00e9s da m\u00fasica.<\/p>\n<p>A combina\u00e7\u00e3o da m\u00fasica como complemento para outras obras art\u00edsticas \u00e9 enorme. Nos filmes, por exemplo, a m\u00fasica tem um peso t\u00e3o importante nas cenas e nas obras, que merece uma categoria especial at\u00e9 mesmo no Oscar.<\/p>\n<h2>As experi\u00eancias pessoais<\/h2>\n<p>Essa tamb\u00e9m \u00e9 outra forma que os artistas usam para influenciar a sua m\u00fasica. Arte, no seu \u00e2mago, \u00e9 uma forma de express\u00e3o e uma das principais fontes de inspira\u00e7\u00e3o para os artistas s\u00e3o as pr\u00f3prias experi\u00eancias pessoais.<\/p>\n<p>G\u00eaneros musicais como o rap e o hip hop, s\u00e3o famosos por artistas que colocam muito da sua personalidade, de sua experi\u00eancia e da sua hist\u00f3ria em suas m\u00fasicas, fazendo com que a conex\u00e3o criada com f\u00e3s que passaram pela mesma experi\u00eancia, ou que simplesmente se conectam com a mensagem, seja o produto mais precioso de toda a cria\u00e7\u00e3o.<\/p>\n<p>De qualquer forma, a inspira\u00e7\u00e3o para qualquer artista, seja m\u00fasico ou n\u00e3o, pode ser diversas coisas. Algo que o move, que o toque, que o emocione ou mesmo que o impressione, ou desperte alguma curiosidade. Na parte mais emocional, que \u00e9 o mais forte em qualquer obra art\u00edstica, \u00e9 preciso estar preparado para receber a inspira\u00e7\u00e3o em qualquer momento, interpret\u00e1-la e atuar em cima dela.<\/p>\n<p>Na parte mais t\u00e9cnica, \u00e9 preciso estudar! Estudar os grandes m\u00fasicos e n\u00e3o copi\u00e1-los, mas sim, evoluir em cima do trabalho que eles fizeram para construir algo que fa\u00e7a uma ponte entre o antigo e novo. Esse \u00e9 um desafio para qualquer artista que, por si s\u00f3, j\u00e1 \u00e9 uma incr\u00edvel forma de inspira\u00e7\u00e3o.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"sztNInuHkO\"><p><a href=\"https:\/\/www.sabra.org.br\/site\/responsabilidade-social\/\">Responsabilidade Social<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;Responsabilidade Social&#8221; &#8212; SABRA - Sociedade Art\u00edstica Brasileira\" src=\"https:\/\/www.sabra.org.br\/site\/responsabilidade-social\/embed\/#?secret=7Mi3R6cTRV#?secret=sztNInuHkO\" data-secret=\"sztNInuHkO\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<h2>Se voc\u00ea gostou deste post:<\/h2>\n<p>&#8211; siga as nossas p\u00e1ginas nas redes sociais para acompanhar as nossas atualiza\u00e7\u00f5es: estamos no <a href=\"https:\/\/www.facebook.com\/sabrabrasil\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, no <a href=\"https:\/\/www.instagram.com\/sabrabrasil\/\" target=\"_blank\" rel=\"noopener noreferrer\">Instagram<\/a>, no <a href=\"https:\/\/www.linkedin.com\/company\/25002088\" target=\"_blank\" rel=\"noopener noreferrer\">LinkedIn<\/a>, no <a href=\"https:\/\/twitter.com\/ContatoSabra\" target=\"_blank\" rel=\"noopener noreferrer\">Twitter<\/a> e no <a href=\"https:\/\/www.youtube.com\/channel\/UCJw-kbuEvzUNdeQf20Pa-eQ\" target=\"_blank\" rel=\"noopener noreferrer\">YouTube<\/a>!<\/p>\n<p>&#8211; Conhe\u00e7a o trabalho da Sociedade Art\u00edstica Brasileira (SABRA) e todas as iniciativas culturais e sociais que ela mant\u00e9m. <a href=\"https:\/\/www.sabra.org.br\/site\/acoes\/\" target=\"_blank\" rel=\"noopener noreferrer\">Acesse nosso site!<\/a><\/p>\n<p>&#8211; entre em contato com a gente. E veja quais s\u00e3o as op\u00e7\u00f5es de ajuda na manuten\u00e7\u00e3o de nossas a\u00e7\u00f5es sociais e culturais. Basta acessar nossa p\u00e1gina <a href=\"https:\/\/www.sabra.org.br\/site\/doe-agora\/\" target=\"_blank\" rel=\"noopener noreferrer\">Doe Agora!<\/a><\/p>\n<p>&#8211; Compartilhe este texto nas suas redes sociais e ajude os seus amigos a tamb\u00e9m dominarem o assunto!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>fonte de inspira\u00e7\u00e3o<br \/>\ninspira\u00e7\u00e3o<br \/>\nm\u00fasica<br \/>\nartistas<br \/>\nexperi\u00eancias pessoais<\/p>\n","protected":false},"author":39,"featured_media":2125,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[15,8,1285,16,1286,11,9],"class_list":["post-2124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-sabra","tag-assistencia-social","tag-canto-coral","tag-escola-de-musica-sabra","tag-musicalizacao-infantil","tag-orquestra-infanto-juvenil-de-betim","tag-orquestra-sinfonica-de-betim","tag-sociedade-artistica-brasileira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inspira\u00e7\u00e3o - SABRA - Sociedade Art\u00edstica Brasileira<\/title>\n<meta name=\"description\" content=\"Voc\u00ea j\u00e1 parou para pensar em todas as formas que a m\u00fasica interage conosco? Com isso surge uma pergunta: de onde o m\u00fasico tira a inspira\u00e7\u00e3o para algo t\u00e3o impressionante?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inspira\u00e7\u00e3o - SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea j\u00e1 parou para pensar em todas as formas que a m\u00fasica interage conosco? Com isso surge uma pergunta: de onde o m\u00fasico tira a inspira\u00e7\u00e3o para algo t\u00e3o impressionante?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabrabrasil\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-06T01:57:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-20T22:17:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/voce-sabe-onde-e-como-os-grandes-artistas-buscam-inspiracao-20190531112303.jpg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"526\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:site\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/inspiracao-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/inspiracao-2\\\/\"},\"author\":{\"name\":\"M\u00e1rcio Miranda Pontes\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\"},\"headline\":\"Inspira\u00e7\u00e3o\",\"datePublished\":\"2019-06-06T01:57:03+00:00\",\"dateModified\":\"2025-04-20T22:17:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/inspiracao-2\\\/\"},\"wordCount\":739,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/inspiracao-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/voce-sabe-onde-e-como-os-grandes-artistas-buscam-inspiracao-20190531112303.jpg.jpg\",\"keywords\":[\"Assist\u00eancia social\",\"Canto Coral\",\"Escola de Musica SABRA\",\"Musicaliza\u00e7\u00e3o Infantil\",\"Orquestra Infanto Juvenil de Betim\",\"Orquestra Sinf\u00f4nica de Betim\",\"Sociedade Art\u00edstica Brasileira\"],\"articleSection\":[\"Blog SABRA\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/inspiracao-2\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/inspiracao-2\\\/\",\"name\":\"Inspira\u00e7\u00e3o - SABRA - Sociedade Art\u00edstica Brasileira\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/inspiracao-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/inspiracao-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/voce-sabe-onde-e-como-os-grandes-artistas-buscam-inspiracao-20190531112303.jpg.jpg\",\"datePublished\":\"2019-06-06T01:57:03+00:00\",\"dateModified\":\"2025-04-20T22:17:26+00:00\",\"description\":\"Voc\u00ea j\u00e1 parou para pensar em todas as formas que a m\u00fasica interage conosco? Com isso surge uma pergunta: de onde o m\u00fasico tira a inspira\u00e7\u00e3o para algo t\u00e3o impressionante?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/inspiracao-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/inspiracao-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/inspiracao-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/voce-sabe-onde-e-como-os-grandes-artistas-buscam-inspiracao-20190531112303.jpg.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/voce-sabe-onde-e-como-os-grandes-artistas-buscam-inspiracao-20190531112303.jpg.jpg\",\"width\":800,\"height\":526,\"caption\":\"Sociedade Art\u00edstica Brasileria SABRA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/inspiracao-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inspira\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"name\":\"SABRA - Sociedade Art\u00edstica Brasileira\",\"description\":\"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\",\"name\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\",\"alternateName\":\"SABRA\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"width\":400,\"height\":128,\"caption\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sabrabrasil\",\"https:\\\/\\\/x.com\\\/ContatoSabra\",\"https:\\\/\\\/www.instagram.com\\\/sabrabrasil\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/25002088\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/sociedadeartisticabrasileira\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/sabrabrasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\",\"name\":\"M\u00e1rcio Miranda Pontes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"caption\":\"M\u00e1rcio Miranda Pontes\"},\"sameAs\":[\"http:\\\/\\\/www.sabra.org.br\"],\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/author\\\/marcio-miranda-pontes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inspira\u00e7\u00e3o - SABRA - Sociedade Art\u00edstica Brasileira","description":"Voc\u00ea j\u00e1 parou para pensar em todas as formas que a m\u00fasica interage conosco? Com isso surge uma pergunta: de onde o m\u00fasico tira a inspira\u00e7\u00e3o para algo t\u00e3o impressionante?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Inspira\u00e7\u00e3o - SABRA - Sociedade Art\u00edstica Brasileira","og_description":"Voc\u00ea j\u00e1 parou para pensar em todas as formas que a m\u00fasica interage conosco? Com isso surge uma pergunta: de onde o m\u00fasico tira a inspira\u00e7\u00e3o para algo t\u00e3o impressionante?","og_url":"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/","og_site_name":"SABRA - Sociedade Art\u00edstica Brasileira","article_publisher":"https:\/\/www.facebook.com\/sabrabrasil","article_published_time":"2019-06-06T01:57:03+00:00","article_modified_time":"2025-04-20T22:17:26+00:00","og_image":[{"width":800,"height":526,"url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/voce-sabe-onde-e-como-os-grandes-artistas-buscam-inspiracao-20190531112303.jpg.jpg","type":"image\/jpeg"}],"author":"M\u00e1rcio Miranda Pontes","twitter_card":"summary_large_image","twitter_creator":"@ContatoSabra","twitter_site":"@ContatoSabra","twitter_misc":{"Escrito por":"M\u00e1rcio Miranda Pontes","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/#article","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/"},"author":{"name":"M\u00e1rcio Miranda Pontes","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2"},"headline":"Inspira\u00e7\u00e3o","datePublished":"2019-06-06T01:57:03+00:00","dateModified":"2025-04-20T22:17:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/"},"wordCount":739,"publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/voce-sabe-onde-e-como-os-grandes-artistas-buscam-inspiracao-20190531112303.jpg.jpg","keywords":["Assist\u00eancia social","Canto Coral","Escola de Musica SABRA","Musicaliza\u00e7\u00e3o Infantil","Orquestra Infanto Juvenil de Betim","Orquestra Sinf\u00f4nica de Betim","Sociedade Art\u00edstica Brasileira"],"articleSection":["Blog SABRA"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/","url":"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/","name":"Inspira\u00e7\u00e3o - SABRA - Sociedade Art\u00edstica Brasileira","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/#primaryimage"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/voce-sabe-onde-e-como-os-grandes-artistas-buscam-inspiracao-20190531112303.jpg.jpg","datePublished":"2019-06-06T01:57:03+00:00","dateModified":"2025-04-20T22:17:26+00:00","description":"Voc\u00ea j\u00e1 parou para pensar em todas as formas que a m\u00fasica interage conosco? Com isso surge uma pergunta: de onde o m\u00fasico tira a inspira\u00e7\u00e3o para algo t\u00e3o impressionante?","breadcrumb":{"@id":"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sabra.org.br\/site\/inspiracao-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/#primaryimage","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/voce-sabe-onde-e-como-os-grandes-artistas-buscam-inspiracao-20190531112303.jpg.jpg","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/voce-sabe-onde-e-como-os-grandes-artistas-buscam-inspiracao-20190531112303.jpg.jpg","width":800,"height":526,"caption":"Sociedade Art\u00edstica Brasileria SABRA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sabra.org.br\/site\/inspiracao-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.sabra.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Inspira\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.sabra.org.br\/site\/#website","url":"https:\/\/www.sabra.org.br\/site\/","name":"SABRA - Sociedade Art\u00edstica Brasileira","description":"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico","publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sabra.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.sabra.org.br\/site\/#organization","name":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA","alternateName":"SABRA","url":"https:\/\/www.sabra.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","width":400,"height":128,"caption":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabrabrasil","https:\/\/x.com\/ContatoSabra","https:\/\/www.instagram.com\/sabrabrasil\/","https:\/\/www.linkedin.com\/company\/25002088\/","https:\/\/br.pinterest.com\/sociedadeartisticabrasileira\/","https:\/\/www.youtube.com\/c\/sabrabrasil"]},{"@type":"Person","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2","name":"M\u00e1rcio Miranda Pontes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","caption":"M\u00e1rcio Miranda Pontes"},"sameAs":["http:\/\/www.sabra.org.br"],"url":"https:\/\/www.sabra.org.br\/site\/author\/marcio-miranda-pontes\/"}]}},"jetpack_featured_media_url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/voce-sabe-onde-e-como-os-grandes-artistas-buscam-inspiracao-20190531112303.jpg.jpg","jetpack_shortlink":"https:\/\/wp.me\/p95j2Z-yg","jetpack-related-posts":[{"id":7921,"url":"https:\/\/www.sabra.org.br\/site\/rituais-supersticoes\/","url_meta":{"origin":2124,"position":0},"title":"Conhe\u00e7a os curiosos rituais e supersti\u00e7\u00f5es dos m\u00fasicos cl\u00e1ssicos","author":"M\u00e1rcio Miranda Pontes","date":"6 de setembro de 2023","format":false,"excerpt":"Conhe\u00e7a os segredos por tr\u00e1s dos rituais de Bach, Beethoven, Mozart e outros grandes compositores. Desde ora\u00e7\u00f5es a contagem meticulosa de gotas, essas pr\u00e1ticas curiosas revelam o mundo misterioso da m\u00fasica cl\u00e1ssica. Saiba mais neste artigo cativante!","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"sabra-m\u00fasica-ajuda-acreditava-tinha-supersti\u00e7\u00f5es-curiosidades-rituais","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/09\/conheca-os-curiosos-rituais-e-supersticoes-dos-musicos-classicosjpg-20230628095402.jpg-jpg.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/09\/conheca-os-curiosos-rituais-e-supersticoes-dos-musicos-classicosjpg-20230628095402.jpg-jpg.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/09\/conheca-os-curiosos-rituais-e-supersticoes-dos-musicos-classicosjpg-20230628095402.jpg-jpg.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/09\/conheca-os-curiosos-rituais-e-supersticoes-dos-musicos-classicosjpg-20230628095402.jpg-jpg.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1854,"url":"https:\/\/www.sabra.org.br\/site\/inspiracao\/","url_meta":{"origin":2124,"position":1},"title":"Inspira\u00e7\u00e3o","author":"M\u00e1rcio Miranda Pontes","date":"28 de mar\u00e7o de 2019","format":false,"excerpt":"yo-yo ma hist\u00f3ria da m\u00fasica redes sociais m\u00fasica piano","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"Inspira\u00e7\u00e3o","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/03\/inspiracao-conheca-historias-de-musicos-que-comecaram-sua-carreira-na-infancia-20180918131645.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/03\/inspiracao-conheca-historias-de-musicos-que-comecaram-sua-carreira-na-infancia-20180918131645.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/03\/inspiracao-conheca-historias-de-musicos-que-comecaram-sua-carreira-na-infancia-20180918131645.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/03\/inspiracao-conheca-historias-de-musicos-que-comecaram-sua-carreira-na-infancia-20180918131645.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13218,"url":"https:\/\/www.sabra.org.br\/site\/entenda-como-a-musica-pode-ser-a-fonte-de-inspiracao-para-outras-artes\/","url_meta":{"origin":2124,"position":2},"title":"Entenda como a m\u00fasica pode ser a fonte de inspira\u00e7\u00e3o para outras Artes","author":"","date":"22 de agosto de 2025","format":false,"excerpt":"A m\u00fasica \u00e9 uma forma de arte que tem o poder de evocar emo\u00e7\u00f5es e sentimentos profundos em quem a ouve. Essa capacidade \u00fanica da m\u00fasica de tocar a alma humana e despertar a imagina\u00e7\u00e3o a torna uma fonte inesgot\u00e1vel de inspira\u00e7\u00e3o para outras formas de arte. Neste texto, exploraremos\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":9050,"url":"https:\/\/www.sabra.org.br\/site\/inspiracao-ambiental\/","url_meta":{"origin":2124,"position":3},"title":"A m\u00fasica como ferramenta de sensibiliza\u00e7\u00e3o para problemas ambientais do s\u00e9culo XXI","author":"M\u00e1rcio Miranda Pontes","date":"18 de mar\u00e7o de 2024","format":false,"excerpt":"Em um mundo onde desafios ambientais crescentes ecoam por todos os cantos, a m\u00fasica emerge como uma luz guia, uma melodia que ressoa n\u00e3o apenas nos ouvidos, mas tamb\u00e9m nos cora\u00e7\u00f5es e nas mentes.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"sabra-m\u00fasica-ambientais-ambiental-inspira\u00e7\u00e3o-ferramenta-pessoas","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2024\/03\/a-musica-como-ferramenta-de-sensibilizacao-para-problemas-ambientais-do-seculo-xxijpg-20240130121258.jpg-jpg.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2024\/03\/a-musica-como-ferramenta-de-sensibilizacao-para-problemas-ambientais-do-seculo-xxijpg-20240130121258.jpg-jpg.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2024\/03\/a-musica-como-ferramenta-de-sensibilizacao-para-problemas-ambientais-do-seculo-xxijpg-20240130121258.jpg-jpg.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2024\/03\/a-musica-como-ferramenta-de-sensibilizacao-para-problemas-ambientais-do-seculo-xxijpg-20240130121258.jpg-jpg.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13036,"url":"https:\/\/www.sabra.org.br\/site\/guia-de-como-produzir-musica-indie-x-dicas-para-um-som-autentico\/","url_meta":{"origin":2124,"position":4},"title":"Guia de como produzir m\u00fasica indie: X dicas para um som aut\u00eantico","author":"","date":"22 de agosto de 2025","format":false,"excerpt":"A m\u00fasica indie, ou independente, se destaca pela autenticidade e liberdade criativa que oferece aos artistas. Produzir m\u00fasica indie vai muito al\u00e9m de seguir uma f\u00f3rmula pr\u00e9-estabelecida. Trata-se de criar sons originais, explorar novas sonoridades e, principalmente, transmitir uma mensagem \u00fanica. Este guia tem como objetivo oferecer algumas dicas importantes\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2909,"url":"https:\/\/www.sabra.org.br\/site\/biografias-musicos\/","url_meta":{"origin":2124,"position":5},"title":"Biografias &#8211; m\u00fasicos","author":"M\u00e1rcio Miranda Pontes","date":"3 de maio de 2020","format":false,"excerpt":"5 biografias que todo apaixonado por m\u00fasica deve come\u00e7ar a ler Ler um livro \u00e9 um dos grandes prazeres da vida, especialmente quando ele trata de um assunto pelo qual somos apaixonados. No caso da m\u00fasica, a primeira das sete artes, podemos encontrar tanto obras que abordam a teoria musical,\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"biografias-musicos","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/05\/x-biografias-que-todo-apaixonado-por-musica-deve-comecar-a-ler-20200317174456.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/05\/x-biografias-que-todo-apaixonado-por-musica-deve-comecar-a-ler-20200317174456.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/05\/x-biografias-que-todo-apaixonado-por-musica-deve-comecar-a-ler-20200317174456.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/05\/x-biografias-que-todo-apaixonado-por-musica-deve-comecar-a-ler-20200317174456.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/2124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/comments?post=2124"}],"version-history":[{"count":0,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/2124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media\/2125"}],"wp:attachment":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media?parent=2124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/categories?post=2124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/tags?post=2124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}