{"id":2132,"date":"2019-06-11T09:56:01","date_gmt":"2019-06-11T12:56:01","guid":{"rendered":"https:\/\/www.sabra.org.br\/site\/?p=2132"},"modified":"2025-04-20T19:18:03","modified_gmt":"2025-04-20T22:18:03","slug":"servico-social-e-sociedade","status":"publish","type":"post","link":"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/","title":{"rendered":"Servi\u00e7o Social e Sociedade"},"content":{"rendered":"<h2>Qual o papel do servi\u00e7o social na nossa sociedade?<\/h2>\n<p>Aspectos como a evolu\u00e7\u00e3o do capitalismo e o desenvolvimento dos centros urbanos v\u00eam acompanhados de uma s\u00e9rie de mazelas sociais. Neste contexto, o papel do servi\u00e7o social \u00e9 atender \u00e0 sociedade, oferecendo aos indiv\u00edduos em condi\u00e7\u00f5es de vulnerabilidade recursos para terem acesso aos seus direitos e a melhores oportunidades na vida.<\/p>\n<p>Para entender mais a fundo os aspectos deste trabalho e como ele \u00e9 realizado, continue lendo este artigo.<\/p>\n<h2>Compreendendo o escopo do servi\u00e7o social<\/h2>\n<p>O desenvolvimento urbano e a evolu\u00e7\u00e3o do capitalismo geram como efeito colateral a exist\u00eancia de for\u00e7as econ\u00f4micas antag\u00f4nicas. Neste processo, uma s\u00e9rie de indiv\u00edduos passa a ser marginalizada no que diz respeito ao acesso aos seus direitos b\u00e1sicos, e, em um n\u00edvel mais avan\u00e7ado, a oportunidades de vida.<\/p>\n<p>Quando falamos em direitos b\u00e1sicos, nos referimos principalmente a aspectos como sa\u00fade, alimenta\u00e7\u00e3o, seguran\u00e7a, lazer, transporte e educa\u00e7\u00e3o, por exemplo. Simplificadamente, os indiv\u00edduos considerados como em estado de vulnerabilidade social s\u00e3o aqueles que em raz\u00e3o de fatores socioecon\u00f4micos est\u00e3o exclu\u00eddos socialmente, n\u00e3o tendo acesso a um ou mais destes direitos b\u00e1sicos.<\/p>\n<p>Neste contexto, o servi\u00e7o social presta um trabalho de assist\u00eancia a estes indiv\u00edduos. Esta assist\u00eancia deve ser fornecida pelo Estado, mas \u00e9 tamb\u00e9m realizada por entidades independentes como ONGs e outra institui\u00e7\u00f5es particulares.<\/p>\n<h2>O trabalho de assist\u00eancia social<\/h2>\n<p>O servi\u00e7o social oferece \u00e0 sociedade primeiramente o trabalho de identifica\u00e7\u00e3o e presta\u00e7\u00e3o de assist\u00eancia aos indiv\u00edduos em situa\u00e7\u00e3o de vulnerabilidade. Com isto, pode oferecer a estes op\u00e7\u00f5es e alternativas que facilitem o acesso aos seus direitos.<\/p>\n<p>Al\u00e9m disso, em uma outra esfera, o servi\u00e7o social oferece atendimento a pessoas que j\u00e1 tiveram seus direitos violados. Um exemplo disso \u00e9 quando ocorrem cat\u00e1strofes naturais ou provocadas pelo homem, como deslizamentos que geram danos \u00e0 moradia, alagamentos, contamina\u00e7\u00e3o de \u00e1gua e recursos naturais, etc.<\/p>\n<p>Nestes contextos, o servi\u00e7o social pode auxiliar na repara\u00e7\u00e3o destes danos e na reaquisi\u00e7\u00e3o destes direitos.<\/p>\n<h2>O servi\u00e7o social como ferramenta de fomento \u00e0 cultura e ao lazer<\/h2>\n<p>Al\u00e9m dos direitos b\u00e1sicos, o servi\u00e7o social pode ampliar tamb\u00e9m o acesso \u00e0 cultura e ao lazer. Indiv\u00edduos em situa\u00e7\u00e3o de vulnerabilidade t\u00eam menos acesso a programas que fomentem estes importantes aspectos da vida em sociedade.<\/p>\n<p>As institui\u00e7\u00f5es de assist\u00eancia social podem estimular a presen\u00e7a destes trabalhos nas comunidades vulner\u00e1veis. Assim, elas t\u00eam um impacto direto na redu\u00e7\u00e3o das taxas criminais e na gera\u00e7\u00e3o de novas oportunidades para indiv\u00edduos em vulnerabilidade social.<\/p>\n<p>Al\u00e9m disso, programas de ensino de artes e l\u00ednguas, por exemplo, al\u00e9m do teor educacional, contribuem para o aumento da autoestima dos indiv\u00edduos. S\u00e3o capazes de desenvolver neles um senso de pertencimento que estimula a busca por melhores condi\u00e7\u00f5es de vida por meio de ferramentas l\u00edcitas, al\u00e9m de melhorar suas oportunidades de obterem melhores vagas de emprego.<\/p>\n<h2>Garantia de acesso aos direitos do cidad\u00e3o<\/h2>\n<p>Como voc\u00ea p\u00f4de notar, o principal papel do servi\u00e7o social \u00e9 equilibrar os efeitos das desigualdades, principalmente de origem socioecon\u00f4mica. Desta forma, ele contribui para a cidadania de indiv\u00edduos em vulnerabilidade, garantindo o acesso aos seus direitos b\u00e1sicos e permitindo o acesso a melhores oportunidades e condi\u00e7\u00f5es de vida.<\/p>\n<h2>Se voc\u00ea gostou deste post:<\/h2>\n<p>&#8211; siga as nossas p\u00e1ginas nas redes sociais para acompanhar as nossas atualiza\u00e7\u00f5es: estamos no <a href=\"https:\/\/www.facebook.com\/sabrabrasil\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, no <a href=\"https:\/\/www.instagram.com\/sabrabrasil\/\" target=\"_blank\" rel=\"noopener noreferrer\">Instagram<\/a>, no <a href=\"https:\/\/www.linkedin.com\/company\/25002088\" target=\"_blank\" rel=\"noopener noreferrer\">LinkedIn<\/a>, no <a href=\"https:\/\/twitter.com\/ContatoSabra\" target=\"_blank\" rel=\"noopener noreferrer\">Twitter<\/a> e no <a href=\"https:\/\/www.youtube.com\/channel\/UCJw-kbuEvzUNdeQf20Pa-eQ\" target=\"_blank\" rel=\"noopener noreferrer\">YouTube<\/a>!<\/p>\n<p>&#8211; Conhe\u00e7a o trabalho da Sociedade Art\u00edstica Brasileira (SABRA) e todas as iniciativas culturais e sociais que ela mant\u00e9m. <a href=\"https:\/\/www.sabra.org.br\/site\/acoes\/\" target=\"_blank\" rel=\"noopener noreferrer\">Acesse nosso site!<\/a><\/p>\n<p>&#8211; entre em contato com a gente. E veja quais s\u00e3o as op\u00e7\u00f5es de ajuda na manuten\u00e7\u00e3o de nossas a\u00e7\u00f5es sociais e culturais. Basta acessar nossa p\u00e1gina <a href=\"https:\/\/www.sabra.org.br\/site\/doe-agora\/\" target=\"_blank\" rel=\"noopener noreferrer\">Doe Agora!<\/a><\/p>\n<p>&#8211; Compartilhe este texto nas suas redes sociais e ajude os seus amigos a tamb\u00e9m dominarem o assunto!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>servi\u00e7o social<br \/>\npapel do servi\u00e7o social<br \/>\nacesso aos seus direitos<br \/>\nacesso aos seus direitos b\u00e1sicos<br \/>\nindiv\u00edduos em situa\u00e7\u00e3o de vulnerabilidade<\/p>\n","protected":false},"author":39,"featured_media":2134,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[15,8,1285,16,1286,11,9],"class_list":["post-2132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-sabra","tag-assistencia-social","tag-canto-coral","tag-escola-de-musica-sabra","tag-musicalizacao-infantil","tag-orquestra-infanto-juvenil-de-betim","tag-orquestra-sinfonica-de-betim","tag-sociedade-artistica-brasileira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servi\u00e7o Social e Sociedade - SABRA - Sociedade Art\u00edstica Brasileira<\/title>\n<meta name=\"description\" content=\"Al\u00e9m de garantir que a sociedade se torne menos desigual, o servi\u00e7o social permite que fam\u00edlias carentes sejam ouvidas e tenham o m\u00ednimo de dignidade.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servi\u00e7o Social e Sociedade - SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"og:description\" content=\"Al\u00e9m de garantir que a sociedade se torne menos desigual, o servi\u00e7o social permite que fam\u00edlias carentes sejam ouvidas e, assim, tenham o m\u00ednimo de dignidade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/\" \/>\n<meta property=\"og:site_name\" content=\"SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabrabrasil\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-11T12:56:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-20T22:18:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/qual-o-papel-do-servico-social-na-nossa-sociedade-20181029144609.jpg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Al\u00e9m de garantir que a sociedade se torne menos desigual, o servi\u00e7o social permite que fam\u00edlias carentes sejam ouvidas e, assim, tenham o m\u00ednimo de dignidade.\" \/>\n<meta name=\"twitter:creator\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:site\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/servico-social-e-sociedade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/servico-social-e-sociedade\\\/\"},\"author\":{\"name\":\"M\u00e1rcio Miranda Pontes\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\"},\"headline\":\"Servi\u00e7o Social e Sociedade\",\"datePublished\":\"2019-06-11T12:56:01+00:00\",\"dateModified\":\"2025-04-20T22:18:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/servico-social-e-sociedade\\\/\"},\"wordCount\":705,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/servico-social-e-sociedade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/qual-o-papel-do-servico-social-na-nossa-sociedade-20181029144609.jpg.jpg\",\"keywords\":[\"Assist\u00eancia social\",\"Canto Coral\",\"Escola de Musica SABRA\",\"Musicaliza\u00e7\u00e3o Infantil\",\"Orquestra Infanto Juvenil de Betim\",\"Orquestra Sinf\u00f4nica de Betim\",\"Sociedade Art\u00edstica Brasileira\"],\"articleSection\":[\"Blog SABRA\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/servico-social-e-sociedade\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/servico-social-e-sociedade\\\/\",\"name\":\"Servi\u00e7o Social e Sociedade - SABRA - Sociedade Art\u00edstica Brasileira\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/servico-social-e-sociedade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/servico-social-e-sociedade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/qual-o-papel-do-servico-social-na-nossa-sociedade-20181029144609.jpg.jpg\",\"datePublished\":\"2019-06-11T12:56:01+00:00\",\"dateModified\":\"2025-04-20T22:18:03+00:00\",\"description\":\"Al\u00e9m de garantir que a sociedade se torne menos desigual, o servi\u00e7o social permite que fam\u00edlias carentes sejam ouvidas e tenham o m\u00ednimo de dignidade.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/servico-social-e-sociedade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/servico-social-e-sociedade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/servico-social-e-sociedade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/qual-o-papel-do-servico-social-na-nossa-sociedade-20181029144609.jpg.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/qual-o-papel-do-servico-social-na-nossa-sociedade-20181029144609.jpg.jpg\",\"width\":800,\"height\":576,\"caption\":\"Sociedade Art\u00edstica Brasileira SABRA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/servico-social-e-sociedade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servi\u00e7o Social e Sociedade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"name\":\"SABRA - Sociedade Art\u00edstica Brasileira\",\"description\":\"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\",\"name\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\",\"alternateName\":\"SABRA\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"width\":400,\"height\":128,\"caption\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sabrabrasil\",\"https:\\\/\\\/x.com\\\/ContatoSabra\",\"https:\\\/\\\/www.instagram.com\\\/sabrabrasil\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/25002088\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/sociedadeartisticabrasileira\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/sabrabrasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\",\"name\":\"M\u00e1rcio Miranda Pontes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"caption\":\"M\u00e1rcio Miranda Pontes\"},\"sameAs\":[\"http:\\\/\\\/www.sabra.org.br\"],\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/author\\\/marcio-miranda-pontes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servi\u00e7o Social e Sociedade - SABRA - Sociedade Art\u00edstica Brasileira","description":"Al\u00e9m de garantir que a sociedade se torne menos desigual, o servi\u00e7o social permite que fam\u00edlias carentes sejam ouvidas e tenham o m\u00ednimo de dignidade.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/","og_locale":"pt_BR","og_type":"article","og_title":"Servi\u00e7o Social e Sociedade - SABRA - Sociedade Art\u00edstica Brasileira","og_description":"Al\u00e9m de garantir que a sociedade se torne menos desigual, o servi\u00e7o social permite que fam\u00edlias carentes sejam ouvidas e, assim, tenham o m\u00ednimo de dignidade.","og_url":"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/","og_site_name":"SABRA - Sociedade Art\u00edstica Brasileira","article_publisher":"https:\/\/www.facebook.com\/sabrabrasil","article_published_time":"2019-06-11T12:56:01+00:00","article_modified_time":"2025-04-20T22:18:03+00:00","og_image":[{"width":800,"height":576,"url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/qual-o-papel-do-servico-social-na-nossa-sociedade-20181029144609.jpg.jpg","type":"image\/jpeg"}],"author":"M\u00e1rcio Miranda Pontes","twitter_card":"summary_large_image","twitter_description":"Al\u00e9m de garantir que a sociedade se torne menos desigual, o servi\u00e7o social permite que fam\u00edlias carentes sejam ouvidas e, assim, tenham o m\u00ednimo de dignidade.","twitter_creator":"@ContatoSabra","twitter_site":"@ContatoSabra","twitter_misc":{"Escrito por":"M\u00e1rcio Miranda Pontes","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/#article","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/"},"author":{"name":"M\u00e1rcio Miranda Pontes","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2"},"headline":"Servi\u00e7o Social e Sociedade","datePublished":"2019-06-11T12:56:01+00:00","dateModified":"2025-04-20T22:18:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/"},"wordCount":705,"publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/qual-o-papel-do-servico-social-na-nossa-sociedade-20181029144609.jpg.jpg","keywords":["Assist\u00eancia social","Canto Coral","Escola de Musica SABRA","Musicaliza\u00e7\u00e3o Infantil","Orquestra Infanto Juvenil de Betim","Orquestra Sinf\u00f4nica de Betim","Sociedade Art\u00edstica Brasileira"],"articleSection":["Blog SABRA"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/","url":"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/","name":"Servi\u00e7o Social e Sociedade - SABRA - Sociedade Art\u00edstica Brasileira","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/#primaryimage"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/qual-o-papel-do-servico-social-na-nossa-sociedade-20181029144609.jpg.jpg","datePublished":"2019-06-11T12:56:01+00:00","dateModified":"2025-04-20T22:18:03+00:00","description":"Al\u00e9m de garantir que a sociedade se torne menos desigual, o servi\u00e7o social permite que fam\u00edlias carentes sejam ouvidas e tenham o m\u00ednimo de dignidade.","breadcrumb":{"@id":"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/#primaryimage","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/qual-o-papel-do-servico-social-na-nossa-sociedade-20181029144609.jpg.jpg","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/qual-o-papel-do-servico-social-na-nossa-sociedade-20181029144609.jpg.jpg","width":800,"height":576,"caption":"Sociedade Art\u00edstica Brasileira SABRA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sabra.org.br\/site\/servico-social-e-sociedade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.sabra.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Servi\u00e7o Social e Sociedade"}]},{"@type":"WebSite","@id":"https:\/\/www.sabra.org.br\/site\/#website","url":"https:\/\/www.sabra.org.br\/site\/","name":"SABRA - Sociedade Art\u00edstica Brasileira","description":"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico","publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sabra.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.sabra.org.br\/site\/#organization","name":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA","alternateName":"SABRA","url":"https:\/\/www.sabra.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","width":400,"height":128,"caption":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabrabrasil","https:\/\/x.com\/ContatoSabra","https:\/\/www.instagram.com\/sabrabrasil\/","https:\/\/www.linkedin.com\/company\/25002088\/","https:\/\/br.pinterest.com\/sociedadeartisticabrasileira\/","https:\/\/www.youtube.com\/c\/sabrabrasil"]},{"@type":"Person","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2","name":"M\u00e1rcio Miranda Pontes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","caption":"M\u00e1rcio Miranda Pontes"},"sameAs":["http:\/\/www.sabra.org.br"],"url":"https:\/\/www.sabra.org.br\/site\/author\/marcio-miranda-pontes\/"}]}},"jetpack_featured_media_url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/qual-o-papel-do-servico-social-na-nossa-sociedade-20181029144609.jpg.jpg","jetpack_shortlink":"https:\/\/wp.me\/p95j2Z-yo","jetpack-related-posts":[{"id":1920,"url":"https:\/\/www.sabra.org.br\/site\/vulnerabilidade-social\/","url_meta":{"origin":2132,"position":0},"title":"Vulnerabilidade Social","author":"M\u00e1rcio Miranda Pontes","date":"9 de maio de 2019","format":false,"excerpt":"servi\u00e7o social social servi\u00e7o social atua vulnerabilidade social situa\u00e7\u00e3o de vulnerabilidade","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"Vulnerabilidade Social Servi\u00e7o Social","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/05\/vulnerabilidade-social-saiba-como-o-servico-social-pode-ajudar-nessa-situacao-20181029144609.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/05\/vulnerabilidade-social-saiba-como-o-servico-social-pode-ajudar-nessa-situacao-20181029144609.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/05\/vulnerabilidade-social-saiba-como-o-servico-social-pode-ajudar-nessa-situacao-20181029144609.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/05\/vulnerabilidade-social-saiba-como-o-servico-social-pode-ajudar-nessa-situacao-20181029144609.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7269,"url":"https:\/\/www.sabra.org.br\/site\/educacao-assistente-social\/","url_meta":{"origin":2132,"position":1},"title":"Qual o papel e como o assistente contribui com a educa\u00e7\u00e3o do nosso pa\u00eds?","author":"M\u00e1rcio Miranda Pontes","date":"5 de junho de 2023","format":false,"excerpt":"Voc\u00ea sabe qual o papel e como o assistente social contribui com a educa\u00e7\u00e3o de nosso pa\u00eds? Entende muito pouco sobre esse assunto? Ent\u00e3o, n\u00e3o perca mais tempo e acesse agora mesmo este artigo!","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"educa\u00e7\u00e3o-assistente-social-sociais-escola-sabra","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/06\/qual-o-papel-e-como-o-assistente-contribui-com-a-educacao-do-nosso-pais-20181029144609.jpg-jpg.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/06\/qual-o-papel-e-como-o-assistente-contribui-com-a-educacao-do-nosso-pais-20181029144609.jpg-jpg.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/06\/qual-o-papel-e-como-o-assistente-contribui-com-a-educacao-do-nosso-pais-20181029144609.jpg-jpg.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/06\/qual-o-papel-e-como-o-assistente-contribui-com-a-educacao-do-nosso-pais-20181029144609.jpg-jpg.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1448,"url":"https:\/\/www.sabra.org.br\/site\/musica-para-todos-concerto-gratuito-em-betim\/","url_meta":{"origin":2132,"position":2},"title":"M\u00fasica para Todos promove concerto gratuito em Betim","author":"M\u00e1rcio Miranda Pontes","date":"28 de agosto de 2018","format":false,"excerpt":"Orquestra Sinf\u00f4nica de Betim se apresenta no domingo em projeto de valoriza\u00e7\u00e3o da m\u00fasica erudita \u00a0 A Orquestra Sinf\u00f4nica de Betim se apresenta neste domingo, 02\/09, \u00e0s 10h30, no bairro Bueno Franco, em Betim, dentro da programa\u00e7\u00e3o do M\u00fasica para Todos. O projeto promove concertos itinerantes nos bairros da cidade\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/www.sabra.org.br\/site\/category\/noticias\/"},"img":{"alt_text":"M\u00fasica para todos","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2018\/08\/M%C3%BAsica-para-todos.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2018\/08\/M%C3%BAsica-para-todos.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2018\/08\/M%C3%BAsica-para-todos.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2018\/08\/M%C3%BAsica-para-todos.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1923,"url":"https:\/\/www.sabra.org.br\/site\/aprendizagem-e-musica\/","url_meta":{"origin":2132,"position":3},"title":"Aprendizagem e M\u00fasica","author":"M\u00e1rcio Miranda Pontes","date":"10 de maio de 2019","format":false,"excerpt":"influenciar o processo de aprendizagem processo de aprendizagem faculdades f\u00edsicas e mentais desenvolvimento de habilidades lingu\u00edsticas habilidades lingu\u00edsticas e sensoriais","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"Aprendizagem e M\u00fasica","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/05\/como-a-musica-pode-influenciar-o-processo-de-aprendizagem-20181024171547.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/05\/como-a-musica-pode-influenciar-o-processo-de-aprendizagem-20181024171547.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/05\/como-a-musica-pode-influenciar-o-processo-de-aprendizagem-20181024171547.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/05\/como-a-musica-pode-influenciar-o-processo-de-aprendizagem-20181024171547.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7235,"url":"https:\/\/www.sabra.org.br\/site\/assistente-social-mudancas\/","url_meta":{"origin":2132,"position":4},"title":"Por que o assistente social precisa estar preparado para as mudan\u00e7as da sociedade?","author":"M\u00e1rcio Miranda Pontes","date":"31 de maio de 2023","format":false,"excerpt":"Um assistente social deve estar sempre atualizado e de olhos bem abertos para as mudan\u00e7as da sociedade, pois \u00e9 tendo elas como base que a sua atua\u00e7\u00e3o ganha import\u00e2ncia. Que tal acessar este texto e continuar a leitura? Fique atento (a)!","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"social-sociais-profissional-sociedade-trabalho-mudan\u00e7a-sabra","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/05\/por-que-o-assistente-social-precisa-estar-preparado-para-as-mudancas-da-sociedade-20181029144609.jpg-jpg.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/05\/por-que-o-assistente-social-precisa-estar-preparado-para-as-mudancas-da-sociedade-20181029144609.jpg-jpg.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/05\/por-que-o-assistente-social-precisa-estar-preparado-para-as-mudancas-da-sociedade-20181029144609.jpg-jpg.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/05\/por-que-o-assistente-social-precisa-estar-preparado-para-as-mudancas-da-sociedade-20181029144609.jpg-jpg.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7679,"url":"https:\/\/www.sabra.org.br\/site\/reinsercao-social\/","url_meta":{"origin":2132,"position":5},"title":"Reinser\u00e7\u00e3o Social: O servi\u00e7o social facilita esse processo","author":"M\u00e1rcio Miranda Pontes","date":"24 de julho de 2023","format":false,"excerpt":"Sabia que um assistente social pode facilitar a reinser\u00e7\u00e3o social? Pois \u00e9! Esse profissional aplica as melhores t\u00e9cnicas visando n\u00e3o s\u00f3 desenvolver a pessoa, mas tamb\u00e9m acompanh\u00e1-la para que, de fato, a reinser\u00e7\u00e3o aconte\u00e7a. Veja neste texto mais informa\u00e7\u00f5es sobre isso!","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"sabra-m\u00fasica-social-reinser\u00e7\u00e3o-a\u00e7\u00f5es-detentos-sociais","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/07\/reinsercao-social-entenda-como-o-servico-social-facilita-esse-processo-20181029144609.jpg-jpg.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/07\/reinsercao-social-entenda-como-o-servico-social-facilita-esse-processo-20181029144609.jpg-jpg.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/07\/reinsercao-social-entenda-como-o-servico-social-facilita-esse-processo-20181029144609.jpg-jpg.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/07\/reinsercao-social-entenda-como-o-servico-social-facilita-esse-processo-20181029144609.jpg-jpg.webp?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/2132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/comments?post=2132"}],"version-history":[{"count":0,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/2132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media\/2134"}],"wp:attachment":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media?parent=2132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/categories?post=2132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/tags?post=2132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}