{"id":3032,"date":"2023-06-30T11:25:19","date_gmt":"2023-06-30T14:25:19","guid":{"rendered":"https:\/\/www.sabra.org.br\/site\/?p=3032"},"modified":"2023-06-30T11:25:19","modified_gmt":"2023-06-30T14:25:19","slug":"dia-mundial-rock","status":"publish","type":"post","link":"https:\/\/www.sabra.org.br\/site\/dia-mundial-rock\/","title":{"rendered":"Dia Mundial do Rock"},"content":{"rendered":"<p>Dia 13 de julho \u00e9 dia de rock, beb\u00ea! E nada melhor do que comemorar essa data em grande estilo: com quatro fatos curiosos sobre o Dia Mundial do Rock!<\/p>\n<p>Vamos l\u00e1!<\/p>\n<h2>Dia Mundial do Rock: dia de celebrar a liberdade de express\u00e3o<\/h2>\n<h3>Live Aid: o in\u00edcio do Dia Mundial do Rock<\/h3>\n<p>Talvez voc\u00ea n\u00e3o saiba, mas o Dia Mundial do Rock ganhou espa\u00e7o de destaque no calend\u00e1rio por causa do Live Aid, evento organizado pelo cantor e compositor irland\u00eas Bob Geldof e transmitido, ao vivo, pela BBC no dia 13 de julho de 1985.<\/p>\n<p>Com o objetivo de arrecadar doa\u00e7\u00f5es para o combate \u00e0 fome na Eti\u00f3pia, o festival contou com a presen\u00e7a de grandes nomes da \u00e9poca: The Who, Led Zeppelin, Queen, Madonna, David Bowie, BB King, U2, Sting, Rolling Stones, Paul McCartney, Scorpions, Black Sabbath, entre outros.<\/p>\n<p>O Live Aid ocorreu simultaneamente em Londres, na Inglaterra, e na Filad\u00e9lfia, nos Estados Unidos. O evento causou tanto impacto que o pr\u00f3prio Phil Collins sugeriu que a data fosse gravada como o dia global do rock.<\/p>\n<h3>Dia n\u00e3o t\u00e3o mundial assim<\/h3>\n<p>Apesar de ser uma data \u201cmundial\u201d, ela \u00e9 comemorada especialmente no Brasil, no dia 13 de julho. Tudo isso gra\u00e7as \u00e0s r\u00e1dios 89 FM e 97 FM, que se dedicam ao g\u00eanero musical e fizeram, na \u00e9poca, uma campanha para consagrar o Dia Mundial no pa\u00eds.<\/p>\n<p>Nos Estados Unidos, o Rock n\u2019 Roll \u00e9 celebrado no dia 9 de julho, data em que estreou o programa de televis\u00e3o \u201cAmerican Bandstand\u201d (1952-1989), que ajudou a tornar o estilo musical mais popular.<\/p>\n<p>No dia 13, as principais cidades brasileiras costumam organizar show com renomados artistas e representantes do rock. Al\u00e9m de aproveitar os festivais, os roqueiros podem homenagear o g\u00eanero vestindo a camisa de sua banda preferida e ouvindo \u00e1lbuns favoritos. Por que n\u00e3o montar uma banda como os amigos tamb\u00e9m?<\/p>\n<h3>Mais do que barulho<\/h3>\n<p>O Rock n\u2019 Roll \u00e9 muito mais do que um g\u00eanero musical que re\u00fane guitarra, contrabaixo e bateria. \u00c9 um estilo de vida, uma forma de manifestar o pensamento e, sobretudo, de buscar a liberdade e a igualdade social.<\/p>\n<h3>Blues, R&amp;B\u2026 e bossa nova<\/h3>\n<p>O rock surgiu entre as d\u00e9cadas de 1940 e 1950, nos Estados Unidos, como resultado da fus\u00e3o de estilos musicais: Country, Blues, R&amp;B e gospel. Tanto \u00e9 que o g\u00eanero contava com os sons do piano e do saxofone. Entre os nomes mais c\u00e9lebres da \u00e9poca, est\u00e3o Bill Haley, Carl Perkins, Jerry Lee Lewis, Fats Domino, Chuck Berry e Little Richard.<\/p>\n<p>No Brasil, o g\u00eanero ganhou for\u00e7a com o cantor Cauby Peixoto em 1957. Nessa d\u00e9cada, o Rock n\u2019 Roll j\u00e1 era reconhecido no pa\u00eds, em fun\u00e7\u00e3o do sucesso de Elvis Presley, mas popularizou-se com a grava\u00e7\u00e3o, em portugu\u00eas, de \u201cRock and Roll em Copacabana\u201d. Foi a primeira can\u00e7\u00e3o de rock cantada por um brasileiro!<\/p>\n<p>At\u00e9 ent\u00e3o o rock e a bossa nova andavam juntos. Ambos os estilos tratavam de praia, paquera e juventude. Apenas em 1964 ficaram distantes. Curioso, n\u00e3o?<\/p>\n<hr \/>\n<h2>Se voc\u00ea gostou deste post:<\/h2>\n<ul>\n<li>SIGA as nossas p\u00e1ginas nas redes sociais para acompanhar as nossas atualiza\u00e7\u00f5es: estamos no <a href=\"https:\/\/www.facebook.com\/sabrabrasil\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>, no <a href=\"https:\/\/www.instagram.com\/sabrabrasil\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a>, no <a href=\"https:\/\/www.linkedin.com\/company\/25002088\" target=\"_blank\" rel=\"noopener\">LinkedIn<\/a>, no <a href=\"https:\/\/twitter.com\/ContatoSabra\" target=\"_blank\" rel=\"noopener\">Twitter<\/a> e no <a href=\"https:\/\/www.youtube.com\/channel\/UCJw-kbuEvzUNdeQf20Pa-eQ\" target=\"_blank\" rel=\"noopener\">YouTube<\/a>!<\/p>\n<\/li>\n<li>\n<p>CONHE\u00c7A o trabalho da Sociedade Art\u00edstica Brasileira (SABRA) e todas as iniciativas culturais e sociais que ela mant\u00e9m. <a href=\"https:\/\/www.sabra.org.br\/site\/acoes\/\" target=\"_blank\" rel=\"noopener\">Acesse nosso site!<\/a><\/p>\n<\/li>\n<li>\n<p>ENTRE EM CONTATO com a gente. E veja quais s\u00e3o as op\u00e7\u00f5es de ajuda na manuten\u00e7\u00e3o de nossas a\u00e7\u00f5es sociais e culturais. Basta acessar nossa p\u00e1gina <a href=\"https:\/\/www.sabra.org.br\/site\/doe-agora\/\" target=\"_blank\" rel=\"noopener\">Doe Agora!<\/a><\/p>\n<\/li>\n<li>\n<p>COMPARTILHE este texto nas suas redes sociais e ajude os seus amigos a tamb\u00e9m dominarem o assunto!<\/p>\n<\/li>\n<\/ul>\n<p>\u2013 Os projetos da @sabrabrasil s\u00e3o realizados com o patroci\u0301nio m\u00e1ster: @institutounimedbh, viabilizado pelo incentivo de mais de 5,2 mil m\u00e9dicos cooperados e colaboradores via Lei de Incentivo \u00e0 Cultura &#8211; @culturagovbr<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"63r8cv6vFz\"><p><a href=\"https:\/\/www.sabra.org.br\/site\/dia-dos-surdos\/\">Dia dos surdos<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;Dia dos surdos&#8221; &#8212; SABRA - Sociedade Art\u00edstica Brasileira\" src=\"https:\/\/www.sabra.org.br\/site\/dia-dos-surdos\/embed\/#?secret=5QCUrBFyej#?secret=63r8cv6vFz\" data-secret=\"63r8cv6vFz\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Engana-se quem pensa que Rock n\u2019 Roll \u00e9 s\u00f3 barulho. \u00c9 um estilo de vida, uma forma de express\u00e3o e, at\u00e9 mesmo, uma data comemorativa. Para celebrar o Dia Mundial do Rock, selecionamos quatro fatos curiosos sobre a origem e o g\u00eanero musical. Confira!<\/p>\n","protected":false},"author":39,"featured_media":7441,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_customify_content_layout":"","_customify_sidebar":"","_customify_page_header_display":"default","_customify_disable_header":"","_customify_disable_header_top":"","_customify_disable_header_main":"","_customify_disable_header_bottom":"","_customify_disable_page_title":"","_customify_disable_content_vertical_padding":"","_customify_disable_footer_top":"","_customify_disable_footer_main":"","_customify_disable_footer_bottom":"","_customify_breadcrumb_display":"","_customify_header_transparent_display":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[15,2757,3626,3623,8,3629,1285,3628,16,3519,1286,11,3622,9],"class_list":["post-3032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-sabra","tag-assistencia-social","tag-belo-horizonte","tag-cabo-frio","tag-campos-dos-goytacazes","tag-canto-coral","tag-contagem","tag-escola-de-musica-sabra","tag-ibirite","tag-musicalizacao-infantil","tag-nova-lima-2","tag-orquestra-infanto-juvenil-de-betim","tag-orquestra-sinfonica-de-betim","tag-raposos","tag-sociedade-artistica-brasileira"],"jetpack_featured_media_url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/06\/dia-mundial-do-rock-x-coisas-que-voce-precisa-saber-sobre-essa-data-20200602154116.jpg-jpg.webp","jetpack_shortlink":"https:\/\/wp.me\/p95j2Z-MU","jetpack-related-posts":[{"id":386,"url":"https:\/\/www.sabra.org.br\/site\/orquestra-sinfonica-de-betim-concertos-em-bh-e-betim\/","url_meta":{"origin":3032,"position":0},"title":"Orquestra Sinf\u00f4nica de Betim &#8211; Concertos em BH e Betim","author":"M\u00e1rcio Miranda Pontes","date":"14 de outubro de 2016","format":false,"excerpt":"[vc_row][vc_column][vc_column_text css=\"\"] A Orquestra Sinf\u00f4nica de Betim realiza mais dois concertos de suas s\u00e9ries anuais. Em outubro ser\u00e3o apresentadas obras musicais que demonstram o funcionamento de seus naipes \u2013 percuss\u00e3o, metais, madeiras e cordas, al\u00e9m de sua integra\u00e7\u00e3o para a realiza\u00e7\u00e3o em conjunto de obras sinf\u00f4nicas. O primeiro ser\u00e1 \u00e0s\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/www.sabra.org.br\/site\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":14059,"url":"https:\/\/www.sabra.org.br\/site\/audicao-contagem-julho25\/","url_meta":{"origin":3032,"position":1},"title":"Audi\u00e7\u00e3o de alunos da Sabra celebra transforma\u00e7\u00e3o pela m\u00fasica\u00a0","author":"M\u00e1rcio Miranda Pontes","date":"9 de julho de 2025","format":false,"excerpt":"Evento gratuito na Pra\u00e7a da Jaboticaba marca a trajet\u00f3ria de jovens m\u00fasicos formados pela Escola de M\u00fasica SABRA \u00a0 Contagem, julho de 2025 \u2013 A Escola de M\u00fasica SABRA, em parceria com o Minist\u00e9rio da Cultura, a Prefeitura Municipal de Contagem e com patroc\u00ednio m\u00e1ster do Instituto Unimed-BH, realizar\u00e1 um\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/www.sabra.org.br\/site\/category\/noticias\/"},"img":{"alt_text":"audi\u00e7\u00e3o-contagem-julho-2025-sabra-escola-de-m\u00fasica","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2025\/07\/Folder-audicao-julho-contagem.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2025\/07\/Folder-audicao-julho-contagem.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2025\/07\/Folder-audicao-julho-contagem.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2025\/07\/Folder-audicao-julho-contagem.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4251,"url":"https:\/\/www.sabra.org.br\/site\/orquestra-4\/","url_meta":{"origin":3032,"position":2},"title":"Aprovados para vagas suplementares no Curso \u201cOrquestra Sinf\u00f4nica de Betim\u201d 2021","author":"M\u00e1rcio Miranda Pontes","date":"14 de outubro de 2021","format":false,"excerpt":"A SOCIEDADE ART\u00cdSTICA BRASILEIRA \u2013 SABRA, parabeniza todos os candidatos e candidatas participantes no processo seletivo para as vagas no curso da Orquestra Sinf\u00f4nica de Betim e publica, como previsto no Edital de Sele\u00e7\u00e3o 010\/2021, a lista dos aprovados para o ano de 2021. Os candidatos e candidatas aprovados dever\u00e3o\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/www.sabra.org.br\/site\/category\/noticias\/"},"img":{"alt_text":"orquestra-m\u00fasica-tipo","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/05\/saiba-quais-sao-os-tipos-de-orquestra-existem-20210203092956.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/05\/saiba-quais-sao-os-tipos-de-orquestra-existem-20210203092956.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/05\/saiba-quais-sao-os-tipos-de-orquestra-existem-20210203092956.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/05\/saiba-quais-sao-os-tipos-de-orquestra-existem-20210203092956.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4787,"url":"https:\/\/www.sabra.org.br\/site\/resultado-edital-010-2022-orquestra-sinfonica\/","url_meta":{"origin":3032,"position":3},"title":"Resultado Edital 010\/2022 &#8211; Orquestra Sinf\u00f4nica","author":"M\u00e1rcio Miranda Pontes","date":"2 de mar\u00e7o de 2022","format":false,"excerpt":"Confira o resultado do Edital 010\/2022 e veja a lista dos aprovados para o curso da Orquestra Sinf\u00f4nica de Betim.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"sabra-m\u00fasica-sinestesia-experi\u00eancias-sensoriais-sentidos-sinest\u00e9sica-associados-cor-exploraremos-musical-percep\u00e7\u00f5es-resultado-edital","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2024\/04\/a-conexao-entre-a-musica-e-as-experiencias-sensoriais-na-sinestesia-20240229111914.jpg-jpg.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2024\/04\/a-conexao-entre-a-musica-e-as-experiencias-sensoriais-na-sinestesia-20240229111914.jpg-jpg.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2024\/04\/a-conexao-entre-a-musica-e-as-experiencias-sensoriais-na-sinestesia-20240229111914.jpg-jpg.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2024\/04\/a-conexao-entre-a-musica-e-as-experiencias-sensoriais-na-sinestesia-20240229111914.jpg-jpg.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5285,"url":"https:\/\/www.sabra.org.br\/site\/direitos-mulher\/","url_meta":{"origin":3032,"position":4},"title":"M\u00fasicas para homenagear as Mulheres","author":"M\u00e1rcio Miranda Pontes","date":"27 de junho de 2022","format":false,"excerpt":"Elza Soares, Beyonc\u00e9, Madonna, Maria Gad\u00fa... S\u00e3o muitas as artistas que falam sobre o empoderamento feminino em suas m\u00fasicas. Para celebrar as Mulheres, separamos 25 can\u00e7\u00f5es incr\u00edveis que valem a pena dar o play. Aumente o som e cante com a gente!","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"mulher-direito-internacional","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/06\/musicas-para-homenagear-o-dia-das-mulheres-20220303163637.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/06\/musicas-para-homenagear-o-dia-das-mulheres-20220303163637.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/06\/musicas-para-homenagear-o-dia-das-mulheres-20220303163637.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/06\/musicas-para-homenagear-o-dia-das-mulheres-20220303163637.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":628,"url":"https:\/\/www.sabra.org.br\/site\/orquestra-infantil-de-betim-concerto\/","url_meta":{"origin":3032,"position":5},"title":"Orquestra Infantil de Betim ensaia suas primeiras melodias","author":"M\u00e1rcio Miranda Pontes","date":"6 de setembro de 2017","format":false,"excerpt":"Confira o concerto da Orquestra Infantil de Betim no dia 1 de dezembro, onde alunos de violino mostrar\u00e3o seu talento.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"concerto-orquestra-infantil-sinf\u00f4nica-cultura","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2017\/09\/Violino-e1765390873703.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/3032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/comments?post=3032"}],"version-history":[{"count":0,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/3032\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media\/7441"}],"wp:attachment":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media?parent=3032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/categories?post=3032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/tags?post=3032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}