{"id":3938,"date":"2021-06-15T08:19:52","date_gmt":"2021-06-15T11:19:52","guid":{"rendered":"https:\/\/www.sabra.org.br\/site\/?p=3938"},"modified":"2025-04-18T11:19:13","modified_gmt":"2025-04-18T14:19:13","slug":"trabalho-2","status":"publish","type":"post","link":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/","title":{"rendered":"Trabalho decente: saiba o que \u00e9 e qual a realidade do pa\u00eds"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]A Organiza\u00e7\u00e3o Internacional do Trabalho (OIT) definiu em 1999 o que \u00e9 conhecido como \u2018trabalho decente\u2019. Conforme o nome indica, \u00e9 uma premissa de trazer a dignidade aos diversos mecanismos produtivos, nas mais variadas \u00e1reas de exerc\u00edcio profissional.<\/p>\n<p>No Brasil, essa premissa foi intensificada por meio da Agenda Nacional de Trabalho Decente (ANTD), em maio de 2006, mas que foi assinado pelo at\u00e9 ent\u00e3o presidente da Rep\u00fablica, Luiz In\u00e1cio Lula da Silva, ainda em 2003.<\/p>\n<h2>Caracter\u00edsticas do Trabalho Decente<\/h2>\n<p>A OIT, ag\u00eancia triparte, especializada e aut\u00f4noma da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU) \u00e9 quem define as diretrizes destes conceitos de forma a agregar mais pa\u00edses que adotem suas a\u00e7\u00f5es. Atualmente, s\u00e3o 187 na\u00e7\u00f5es que entram na OIT como estados-membros (incluindo o Brasil).<\/p>\n<p>Conforme a pr\u00f3pria organiza\u00e7\u00e3o aponta em seu site, o objetivo \u00e9 a promo\u00e7\u00e3o de oportunidades para mulheres e homens terem um \u201ctrabalho produtivo e de qualidade, em condi\u00e7\u00f5es de liberdade, equidade, seguran\u00e7a e dignidade humanas\u201d.<\/p>\n<p>Ainda, exalta que isso \u00e9 algo fundamental para diminuir uma endemia em v\u00e1rios pa\u00edses: os altos \u00edndices de pobreza. Consequentemente, aponta a OIT, diminuem-se as desigualdades sociais, al\u00e9m de garantir a democracia e a sustentabilidade.<\/p>\n<h2>Objetivo de Desenvolvimento Sustent\u00e1vel<\/h2>\n<p>A ONU tipifica 17 Objetivos de Desenvolvimento Sustent\u00e1vel (ODS), buscando combater a pobreza, cuidar do planeta Terra e aumentar a prosperidade entre todos, como Agenda para 2030. E a ODS n\u00famero 8 trata exatamente disso: &#8220;Trabalho decente e crescimento econ\u00f4mico: promover o crescimento econ\u00f4mico sustentado, inclusivo e sustent\u00e1vel, emprego pleno e produtivo, e trabalho decente para todos\u201d.<\/p>\n<p>Ou seja, trata-se de algo que, al\u00e9m de ser buscado nos \u00faltimos anos, ganhou uma \u00eanfase na Agenda das Na\u00e7\u00f5es Unidades at\u00e9 2030. Isso traz como consequ\u00eancia uma s\u00e9rie de recomenda\u00e7\u00f5es e ado\u00e7\u00e3o de pol\u00edticas governamentais que garantam esse processo.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"LmQVst3C5S\"><p><a href=\"https:\/\/www.sabra.org.br\/site\/sustentabilidade\/\">Guia b\u00e1sico sobre os Objetivos de Desenvolvimento Sustent\u00e1vel da ONU<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;Guia b\u00e1sico sobre os Objetivos de Desenvolvimento Sustent\u00e1vel da ONU&#8221; &#8212; SABRA - Sociedade Art\u00edstica Brasileira\" src=\"https:\/\/www.sabra.org.br\/site\/sustentabilidade\/embed\/#?secret=0E9mwcLULS#?secret=LmQVst3C5S\" data-secret=\"LmQVst3C5S\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<h2>Agentes do trabalho decente<\/h2>\n<p>Em consequ\u00eancia, o trabalho decente s\u00f3 \u00e9 realizado quando h\u00e1 o trip\u00e9 para isso: governos, empregadores e empregados. Assim, \u00e9 necess\u00e1rio que todos atuem na mesma dire\u00e7\u00e3o, por meio de um processo que se retroalimenta e precisa de uma parceria prof\u00edcua para a garantia dos direitos dos trabalhadores.<\/p>\n<h2>Realidade no Brasil<\/h2>\n<p>Dentro do nosso pa\u00eds, esse conceito ganhou novos contornos com o Plano Nacional de Emprego e Trabalho Decente (PNETD), que foi discutido e aprovado em junho de 2009 pelo Governo Federal.<\/p>\n<p>Na sequ\u00eancia, j\u00e1 em 2012, Bras\u00edlia sediou a I Confer\u00eancia Nacional de Emprego e Trabalho Decente (I CNETD), para construir uma pol\u00edtica a n\u00edvel federal sobre os pressupostos dessa ideia. Desde ent\u00e3o, entes federativos t\u00eam algumas diretrizes para aplicar, nas mais variadas esferas.<\/p>\n<p>Especialistas em ODS apontam que, na atual configura\u00e7\u00e3o de 2021, o Brasil tem poucos Objetivos a serem cumpridos at\u00e9 2030; \u2018felizmente\u2019, o trabalho decente est\u00e1 entre as principais, muito em virtude dos novos mecanismos de prote\u00e7\u00e3o ao trabalhador, mas que ainda devem percorrer um longo caminho.<\/p>\n<p>Isso porque o n\u00famero de desempregados, atualmente em cerca de 14,4 milh\u00f5es, puxa o pa\u00eds para um estado de alerta. Com novos circuitos a serem explorados, por\u00e9m vislumbra-se trazer de volta as premissas que colocaram o Brasil entre um dos maiores promotores do trabalho decente, como fora vista no in\u00edcio da d\u00e9cada passada.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"rCUsGwzgAQ\"><p><a href=\"https:\/\/www.sabra.org.br\/site\/rock-orquestra-2\/\">Voc\u00ea sabe como o rock pode ser utilizado em orquestras?<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;Voc\u00ea sabe como o rock pode ser utilizado em orquestras?&#8221; &#8212; SABRA - Sociedade Art\u00edstica Brasileira\" src=\"https:\/\/www.sabra.org.br\/site\/rock-orquestra-2\/embed\/#?secret=ukXECt1vqN#?secret=rCUsGwzgAQ\" data-secret=\"rCUsGwzgAQ\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<hr \/>\n<h2>Se voc\u00ea gostou deste post:<\/h2>\n<p>&#8211; SIGA as nossas p\u00e1ginas nas redes sociais para acompanhar as nossas atualiza\u00e7\u00f5es: estamos no <a href=\"https:\/\/www.facebook.com\/sabrabrasil\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>, no <a href=\"https:\/\/www.instagram.com\/sabrabrasil\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a>, no <a href=\"https:\/\/www.linkedin.com\/company\/25002088\" target=\"_blank\" rel=\"noopener\">LinkedIn<\/a>, no <a href=\"https:\/\/twitter.com\/ContatoSabra\" target=\"_blank\" rel=\"noopener\">Twitter<\/a> e no <a href=\"https:\/\/www.youtube.com\/channel\/UCJw-kbuEvzUNdeQf20Pa-eQ\" target=\"_blank\" rel=\"noopener\">YouTube<\/a>!<\/p>\n<p>&#8211; CONHE\u00c7A o trabalho da Sociedade Art\u00edstica Brasileira (SABRA) e todas as iniciativas culturais e sociais que ela mant\u00e9m. <a href=\"https:\/\/www.sabra.org.br\/site\/acoes\/\" target=\"_blank\" rel=\"noopener\">Acesse nosso site!<\/a><\/p>\n<p>&#8211; ENTRE EM CONTATO com a gente. E veja quais s\u00e3o as op\u00e7\u00f5es de ajuda na manuten\u00e7\u00e3o de nossas a\u00e7\u00f5es sociais e culturais. Basta acessar nossa p\u00e1gina <a href=\"https:\/\/www.sabra.org.br\/site\/doe-agora\/\" target=\"_blank\" rel=\"noopener\">Doe Agora!<\/a><\/p>\n<p>&#8211; COMPARTILHE este texto nas suas redes sociais e ajude os seus amigos a tamb\u00e9m dominarem o assunto![\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trabalho decente: saiba o que \u00e9 e qual a realidade do pa\u00eds<\/p>\n<p>A Organiza\u00e7\u00e3o Internacional do Trabalho (OIT), ag\u00eancia da ONU, definiu em 1999 o que conceituamos como &#8216;trabalho decente&#8217;. Quatro anos mais tarde, o Brasil aderiu a essa pr\u00e1tica. Mas, afinal, do que se trata e como o pa\u00eds vem adotando essas medidas? Confira no artigo.<\/p>\n","protected":false},"author":39,"featured_media":3939,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[1738,15,8,1285,16,1286,11,9],"class_list":["post-3938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-sabra","tag-nova-lima","tag-assistencia-social","tag-canto-coral","tag-escola-de-musica-sabra","tag-musicalizacao-infantil","tag-orquestra-infanto-juvenil-de-betim","tag-orquestra-sinfonica-de-betim","tag-sociedade-artistica-brasileira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trabalho decente: saiba o que \u00e9 e qual a realidade do pa\u00eds - SABRA - Sociedade Art\u00edstica Brasileira<\/title>\n<meta name=\"description\" content=\"A Organiza\u00e7\u00e3o Internacional do Trabalho (OIT), ag\u00eancia da ONU, definiu em 1999 o que conceituamos como &#039;trabalho decente&#039;. O Brasil aderiu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sabra.org.br\/site\/trabalho-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trabalho decente: saiba o que \u00e9 e qual a realidade do pa\u00eds - SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"og:description\" content=\"A Organiza\u00e7\u00e3o Internacional do Trabalho (OIT), ag\u00eancia da ONU, definiu em 1999 o que conceituamos como &#039;trabalho decente&#039;. O Brasil aderiu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sabra.org.br\/site\/trabalho-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabrabrasil\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-15T11:19:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-18T14:19:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:site\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/trabalho-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/trabalho-2\\\/\"},\"author\":{\"name\":\"M\u00e1rcio Miranda Pontes\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\"},\"headline\":\"Trabalho decente: saiba o que \u00e9 e qual a realidade do pa\u00eds\",\"datePublished\":\"2021-06-15T11:19:52+00:00\",\"dateModified\":\"2025-04-18T14:19:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/trabalho-2\\\/\"},\"wordCount\":707,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/trabalho-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg\",\"keywords\":[\"#nova lima\",\"Assist\u00eancia social\",\"Canto Coral\",\"Escola de Musica SABRA\",\"Musicaliza\u00e7\u00e3o Infantil\",\"Orquestra Infanto Juvenil de Betim\",\"Orquestra Sinf\u00f4nica de Betim\",\"Sociedade Art\u00edstica Brasileira\"],\"articleSection\":[\"Blog SABRA\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/trabalho-2\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/trabalho-2\\\/\",\"name\":\"Trabalho decente: saiba o que \u00e9 e qual a realidade do pa\u00eds - SABRA - Sociedade Art\u00edstica Brasileira\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/trabalho-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/trabalho-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg\",\"datePublished\":\"2021-06-15T11:19:52+00:00\",\"dateModified\":\"2025-04-18T14:19:13+00:00\",\"description\":\"A Organiza\u00e7\u00e3o Internacional do Trabalho (OIT), ag\u00eancia da ONU, definiu em 1999 o que conceituamos como 'trabalho decente'. O Brasil aderiu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/trabalho-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/trabalho-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/trabalho-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg\",\"width\":800,\"height\":534,\"caption\":\"Sociedade Art\u00edstica Brasileira SABRA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/trabalho-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trabalho decente: saiba o que \u00e9 e qual a realidade do pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"name\":\"SABRA - Sociedade Art\u00edstica Brasileira\",\"description\":\"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\",\"name\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\",\"alternateName\":\"SABRA\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"width\":400,\"height\":128,\"caption\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sabrabrasil\",\"https:\\\/\\\/x.com\\\/ContatoSabra\",\"https:\\\/\\\/www.instagram.com\\\/sabrabrasil\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/25002088\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/sociedadeartisticabrasileira\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/sabrabrasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\",\"name\":\"M\u00e1rcio Miranda Pontes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"caption\":\"M\u00e1rcio Miranda Pontes\"},\"sameAs\":[\"http:\\\/\\\/www.sabra.org.br\"],\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/author\\\/marcio-miranda-pontes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trabalho decente: saiba o que \u00e9 e qual a realidade do pa\u00eds - SABRA - Sociedade Art\u00edstica Brasileira","description":"A Organiza\u00e7\u00e3o Internacional do Trabalho (OIT), ag\u00eancia da ONU, definiu em 1999 o que conceituamos como 'trabalho decente'. O Brasil aderiu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Trabalho decente: saiba o que \u00e9 e qual a realidade do pa\u00eds - SABRA - Sociedade Art\u00edstica Brasileira","og_description":"A Organiza\u00e7\u00e3o Internacional do Trabalho (OIT), ag\u00eancia da ONU, definiu em 1999 o que conceituamos como 'trabalho decente'. O Brasil aderiu.","og_url":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/","og_site_name":"SABRA - Sociedade Art\u00edstica Brasileira","article_publisher":"https:\/\/www.facebook.com\/sabrabrasil","article_published_time":"2021-06-15T11:19:52+00:00","article_modified_time":"2025-04-18T14:19:13+00:00","og_image":[{"width":800,"height":534,"url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg","type":"image\/jpeg"}],"author":"M\u00e1rcio Miranda Pontes","twitter_card":"summary_large_image","twitter_creator":"@ContatoSabra","twitter_site":"@ContatoSabra","twitter_misc":{"Escrito por":"M\u00e1rcio Miranda Pontes","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/#article","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/"},"author":{"name":"M\u00e1rcio Miranda Pontes","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2"},"headline":"Trabalho decente: saiba o que \u00e9 e qual a realidade do pa\u00eds","datePublished":"2021-06-15T11:19:52+00:00","dateModified":"2025-04-18T14:19:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/"},"wordCount":707,"publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg","keywords":["#nova lima","Assist\u00eancia social","Canto Coral","Escola de Musica SABRA","Musicaliza\u00e7\u00e3o Infantil","Orquestra Infanto Juvenil de Betim","Orquestra Sinf\u00f4nica de Betim","Sociedade Art\u00edstica Brasileira"],"articleSection":["Blog SABRA"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/","url":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/","name":"Trabalho decente: saiba o que \u00e9 e qual a realidade do pa\u00eds - SABRA - Sociedade Art\u00edstica Brasileira","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/#primaryimage"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg","datePublished":"2021-06-15T11:19:52+00:00","dateModified":"2025-04-18T14:19:13+00:00","description":"A Organiza\u00e7\u00e3o Internacional do Trabalho (OIT), ag\u00eancia da ONU, definiu em 1999 o que conceituamos como 'trabalho decente'. O Brasil aderiu.","breadcrumb":{"@id":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sabra.org.br\/site\/trabalho-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/#primaryimage","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg","width":800,"height":534,"caption":"Sociedade Art\u00edstica Brasileira SABRA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.sabra.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Trabalho decente: saiba o que \u00e9 e qual a realidade do pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/www.sabra.org.br\/site\/#website","url":"https:\/\/www.sabra.org.br\/site\/","name":"SABRA - Sociedade Art\u00edstica Brasileira","description":"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico","publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sabra.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.sabra.org.br\/site\/#organization","name":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA","alternateName":"SABRA","url":"https:\/\/www.sabra.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","width":400,"height":128,"caption":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabrabrasil","https:\/\/x.com\/ContatoSabra","https:\/\/www.instagram.com\/sabrabrasil\/","https:\/\/www.linkedin.com\/company\/25002088\/","https:\/\/br.pinterest.com\/sociedadeartisticabrasileira\/","https:\/\/www.youtube.com\/c\/sabrabrasil"]},{"@type":"Person","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2","name":"M\u00e1rcio Miranda Pontes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","caption":"M\u00e1rcio Miranda Pontes"},"sameAs":["http:\/\/www.sabra.org.br"],"url":"https:\/\/www.sabra.org.br\/site\/author\/marcio-miranda-pontes\/"}]}},"jetpack_featured_media_url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg","jetpack_shortlink":"https:\/\/wp.me\/p95j2Z-11w","jetpack-related-posts":[{"id":2998,"url":"https:\/\/www.sabra.org.br\/site\/sabra-objetivos-da-organizacao\/","url_meta":{"origin":3938,"position":0},"title":"SABRA: Objetivos da Organiza\u00e7\u00e3o","author":"M\u00e1rcio Miranda Pontes","date":"11 de junho de 2020","format":false,"excerpt":"Voc\u00ea conhece o trabalho social promovido pela Sociedade Art\u00edstica Brasileira? Conhece seus objetivos? Neste post, voc\u00ea conhecer\u00e1 tudo isso, al\u00e9m dos projetos que levam Arte e Cultura para jovens e familiares.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"SABRA-objetivos-organizacao","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/06\/sociedade-artistica-brasileira-conheca-os-principais-objetivos-da-organizacao-20200602154116.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/06\/sociedade-artistica-brasileira-conheca-os-principais-objetivos-da-organizacao-20200602154116.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/06\/sociedade-artistica-brasileira-conheca-os-principais-objetivos-da-organizacao-20200602154116.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/06\/sociedade-artistica-brasileira-conheca-os-principais-objetivos-da-organizacao-20200602154116.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2269,"url":"https:\/\/www.sabra.org.br\/site\/origem-orquestra\/","url_meta":{"origin":3938,"position":1},"title":"Origem da Orquestra","author":"M\u00e1rcio Miranda Pontes","date":"26 de julho de 2019","format":false,"excerpt":"A palavra \u201corquestra\u201d vem do grego \u201corkh\u00e9stra\u201d, que designava, na Gr\u00e9cia Antiga, o espa\u00e7o localizado entre a plateia e o palco, ocupado pelo coro e composto por m\u00fasicos e dan\u00e7arinos.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"orquestras-instrumentos-s\u00e9culos","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2017\/09\/Orquestra.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2017\/09\/Orquestra.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2017\/09\/Orquestra.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2017\/09\/Orquestra.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2017\/09\/Orquestra.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2017\/09\/Orquestra.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":7250,"url":"https:\/\/www.sabra.org.br\/site\/concerto-orquestra\/","url_meta":{"origin":3938,"position":2},"title":"Nova s\u00e9rie de concertos com a Orquestra Sinf\u00f4nica de Betim","author":"M\u00e1rcio Miranda Pontes","date":"2 de junho de 2023","format":false,"excerpt":"Voc\u00ea sabia que a m\u00fasica pode ser uma excelente aliada do ensino de ci\u00eancias para as crian\u00e7as na escola? \u00c9 isso mesmo! Quer saber como isso acontece? Confira o texto a seguir!","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/www.sabra.org.br\/site\/category\/noticias\/"},"img":{"alt_text":"orquestra-sinf\u00f4nica-betim-juvenil-infantil-infanto-sabra-concerto","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/12\/IMG_9406-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/12\/IMG_9406-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/12\/IMG_9406-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/12\/IMG_9406-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/12\/IMG_9406-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/12\/IMG_9406-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":8056,"url":"https:\/\/www.sabra.org.br\/site\/sabra-concerto\/","url_meta":{"origin":3938,"position":3},"title":"SABRA promove Concerto Noturno.","author":"M\u00e1rcio Miranda Pontes","date":"25 de setembro de 2023","format":false,"excerpt":"SABRA promove Concerto Noturno com diversos grupos musicais para comemorar seus 10 anos de funda\u00e7\u00e3o. O evento acontece no pr\u00f3ximo dia 28 de setembro, , \u00e0s 19h30no Sal\u00e3o de Eventos do CAR em Betim.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"sabra-m\u00fasica-coral-meio-concerto-cultura-trabalho-betim-cooperado-escola-evento-incentivo-sinf\u00f4nica-projeto-social","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/09\/unnamed-jpg.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/09\/unnamed-jpg.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/09\/unnamed-jpg.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/09\/unnamed-jpg.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/09\/unnamed-jpg.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":5814,"url":"https:\/\/www.sabra.org.br\/site\/curiosidades-sabra\/","url_meta":{"origin":3938,"position":4},"title":"Curiosidades sobre a SABRA","author":"M\u00e1rcio Miranda Pontes","date":"7 de setembro de 2022","format":false,"excerpt":"Existem diversas curiosidades que podem impactar no trabalho de uma empresa e com a SABRA n\u00e3o \u00e9 diferente. Acesse o conte\u00fado completo e veja mais detalhes sobre o assunto no blog!","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"cultura-sociais-sociedade-trabalho-sabra","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/09\/curiosidades-sobre-a-sabra-20220707153044.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/09\/curiosidades-sobre-a-sabra-20220707153044.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/09\/curiosidades-sobre-a-sabra-20220707153044.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/09\/curiosidades-sobre-a-sabra-20220707153044.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6773,"url":"https:\/\/www.sabra.org.br\/site\/orquestra2023\/","url_meta":{"origin":3938,"position":5},"title":"Orquestra Sinf\u00f4nica de Betim 2023","author":"M\u00e1rcio Miranda Pontes","date":"21 de mar\u00e7o de 2023","format":false,"excerpt":"A Sociedade Art\u00edstica Brasileira (SABRA) est\u00e1 com vagas abertas para o curso de Orquestra Sinf\u00f4nica. S\u00e3o 55 vagas abertas, sendo 53 para instrumentistas e duas para assistente de produ\u00e7\u00e3o. Podem participar candidatos com 16 anos ou mais, que morem na Regi\u00e3o Metropolitana de Belo Horizonte. \u00c9 preciso comprovar conhecimento dos\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/www.sabra.org.br\/site\/category\/noticias\/"},"img":{"alt_text":"orquestra-sinf\u00f4nica-sabra-betim-escola-m\u00fasica","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/Orquestra-Sinfonica-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/Orquestra-Sinfonica-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/Orquestra-Sinfonica-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/Orquestra-Sinfonica-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/Orquestra-Sinfonica-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/Orquestra-Sinfonica-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/3938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/comments?post=3938"}],"version-history":[{"count":0,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/3938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media\/3939"}],"wp:attachment":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media?parent=3938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/categories?post=3938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/tags?post=3938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}