{"id":4021,"date":"2021-07-10T11:43:32","date_gmt":"2021-07-10T14:43:32","guid":{"rendered":"https:\/\/www.sabra.org.br\/site\/?p=4021"},"modified":"2021-07-10T11:43:32","modified_gmt":"2021-07-10T14:43:32","slug":"aldir-blanc","status":"publish","type":"post","link":"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/","title":{"rendered":"Quem foi Aldir Blanc e qual sua import\u00e2ncia para o Brasil?"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Compositor, escritor e m\u00e9dico brasileiro, Aldir Blanc nos deixou aos 73 anos devido \u00e0s complica\u00e7\u00f5es do Covid-19, em maio de 2020. Entretanto, ficou sua vasta contribui\u00e7\u00e3o para a M\u00fasica Popular Brasileira (MPB) e na literatura.<\/p>\n<h2>Quem foi Aldir Blanc?<\/h2>\n<p>Carioca, nascido em 2 de setembro de 1946, no Rio de Janeiro, Aldir Blanc Mendes era filho \u00fanico de Dona Helena e Seu Alceu.<\/p>\n<p>Desde novo, acompanhava o primo mais velho que frequentava a quadra da escola de samba Acad\u00eamicos do Salgueiro, a qual se tornou sua escola do cora\u00e7\u00e3o.<\/p>\n<h2>A rela\u00e7\u00e3o com a m\u00fasica<\/h2>\n<p>Sua rela\u00e7\u00e3o com a m\u00fasica come\u00e7ou a ser mais forte na d\u00e9cada de 1960. Aos 16 anos aprendeu a tocar bateria, um pouco depois, fundou o grupo Rio Bossa Trio que, tempo depois, passou a ter mais um integrante: S\u00edlvio da Silva. O grupo ent\u00e3o passou a se chamar GB-4 e sua primeira parceria musical foi com \u201cA noite, a mar\u00e9 e o amor\u201d.<\/p>\n<p>Nesta d\u00e9cada, em 1965, ele tamb\u00e9m iniciava os estudos na Escola de Medicina e Cirurgia do Rio de Janeiro. Com a faculdade, seguiu conciliando suas parcerias musicais e participando de festivais, como o Festival Internacional da Can\u00e7\u00e3o e o Festival Universit\u00e1rio da M\u00fasica Popular Brasileira.<\/p>\n<p>J\u00e1 formado em medicina e com especializa\u00e7\u00e3o em psiquiatria, em 1972, Aldir e o m\u00fasico Jo\u00e3o Bosco conseguiram mostrar algumas das suas composi\u00e7\u00f5es para Elis Regina. Ela, por sua vez, gostou de \u201cBala com Bala&#8221; e a can\u00e7\u00e3o foi parar no LP &#8220;Elis&#8221;.<\/p>\n<p>Ap\u00f3s a cantora firmar parceria com Aldir, ela gravou cerca de 20 m\u00fasicas da dupla. No disco, \u201cEssa Mulher\u201d, entrou a composi\u00e7\u00e3o deles que passou a se tornar uma das mais conhecidas: &#8220;O B\u00eabado e a Equilibrista&#8221; \u2013 ficou marcada por ficar virar um \u201chino informal\u201d no per\u00edodo da anistia e decl\u00ednio da Ditadura Militar no Brasil.<\/p>\n<p>V\u00e1rios outros artistas puderam receber as contribui\u00e7\u00f5es das composi\u00e7\u00f5es e melodias da dupla: a cantora Simone, violinista Guinga, o sambista Moacyr Luz, Faf\u00e1 de Bel\u00e9m com \u2018\u2019Cora\u00e7\u00e3o do Agreste\u2019\u2019 e tema da novela Tieta da Rede Globo, a voz de Nana Caymmi em \u201cResposta ao Tempo\u201d, \u201cA Viagem\u201d para a novela com o mesmo nome, gravada pelo Roupa Nova, entre tantas outras.<\/p>\n<h2>Na literatura<\/h2>\n<p>Al\u00e9m de compor m\u00fasicas, cantar, ser m\u00e9dico-psiquiatra, Aldir Blanc tamb\u00e9m escrevia contos, poemas, e obras voltadas \u00e0 literatura infantil. Entretanto, se dedicava muito ao criar cr\u00f4nicas. Com elas, ganhou ainda mais destaque.<\/p>\n<p>A inspira\u00e7\u00e3o para elas era sua vida no sub\u00farbio carioca e escrevia para jornais e revistas como, por exemplo, \u00daltima Hora, O Pasquim e o \u201cHomem\u201d.<\/p>\n<p>As cr\u00f4nicas ganharam espa\u00e7o nos livros, entre eles: Um cara bacana na 19\u00aa, O gabinete do doutor Blanc, Vila Isabel: invent\u00e1rio da inf\u00e2ncia, Rua dos Artistas e arredores e Porta de tinturaria.<\/p>\n<h2>Sua import\u00e2ncia para o Brasil<\/h2>\n<p>Aldir Blanc contribuiu e muito para a m\u00fasica no Brasil, principalmente para o Choro Jazz. Deixou mais de 500 composi\u00e7\u00f5es e fez parcerias com v\u00e1rios artistas do pa\u00eds. Dedicou-se \u00e0 literatura e medicina e mostrou seu talento ao escrever temas profundos que passam desde ao cotidiano at\u00e9 os mais densos e pol\u00edticos.<\/p>\n<p>Certamente ser\u00e1 sempre lembrado como um dos maiores nomes n\u00e3o s\u00f3 da m\u00fasica brasileira, mas tamb\u00e9m da cultura brasileira.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"AyiG8EHpgK\"><p><a href=\"https:\/\/www.sabra.org.br\/site\/cultural-x-artistico\/\">CULTURAL X ART\u00cdSTICO<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;CULTURAL X ART\u00cdSTICO&#8221; &#8212; SABRA - Sociedade Art\u00edstica Brasileira\" src=\"https:\/\/www.sabra.org.br\/site\/cultural-x-artistico\/embed\/#?secret=AyiG8EHpgK\" data-secret=\"AyiG8EHpgK\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>Quer saber mais curiosidades sobre o mundo da arte e cultura? Ent\u00e3o continue navegando em nosso site.<\/p>\n<hr \/>\n<h2>Se voc\u00ea gostou deste post:<\/h2>\n<p>&#8211; SIGA as nossas p\u00e1ginas nas redes sociais para acompanhar as nossas atualiza\u00e7\u00f5es: estamos no <a href=\"https:\/\/www.facebook.com\/sabrabrasil\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>, no <a href=\"https:\/\/www.instagram.com\/sabrabrasil\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a>, no <a href=\"https:\/\/www.linkedin.com\/company\/25002088\" target=\"_blank\" rel=\"noopener\">LinkedIn<\/a>, no <a href=\"https:\/\/twitter.com\/ContatoSabra\" target=\"_blank\" rel=\"noopener\">Twitter<\/a> e no <a href=\"https:\/\/www.youtube.com\/channel\/UCJw-kbuEvzUNdeQf20Pa-eQ\" target=\"_blank\" rel=\"noopener\">YouTube<\/a>!<\/p>\n<p>&#8211; CONHE\u00c7A o trabalho da Sociedade Art\u00edstica Brasileira (SABRA) e todas as iniciativas culturais e sociais que ela mant\u00e9m. <a href=\"https:\/\/www.sabra.org.br\/site\/acoes\/\" target=\"_blank\" rel=\"noopener\">Acesse nosso site!<\/a><\/p>\n<p>&#8211; ENTRE EM CONTATO com a gente. E veja quais s\u00e3o as op\u00e7\u00f5es de ajuda na manuten\u00e7\u00e3o de nossas a\u00e7\u00f5es sociais e culturais. Basta acessar nossa p\u00e1gina <a href=\"https:\/\/www.sabra.org.br\/site\/doe-agora\/\" target=\"_blank\" rel=\"noopener\">Doe Agora!<\/a><\/p>\n<p>&#8211; COMPARTILHE este texto nas suas redes sociais e ajude os seus amigos a tamb\u00e9m dominarem o assunto![\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quem foi Aldir Blanc e qual sua import\u00e2ncia para o Brasil?<\/p>\n<p>Voc\u00ea j\u00e1 ouviu falar no compositor e escritor brasileiro Aldir Blanc? Sabia que ele muito \u00e9 importante para o cen\u00e1rio cultural do nosso pa\u00eds? Conhe\u00e7a mais sobre sua biografia e contribui\u00e7\u00f5es!<\/p>\n","protected":false},"author":39,"featured_media":4023,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[15,8,1285,16,3519,1286,11,9],"class_list":["post-4021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-sabra","tag-assistencia-social","tag-canto-coral","tag-escola-de-musica-sabra","tag-musicalizacao-infantil","tag-nova-lima-2","tag-orquestra-infanto-juvenil-de-betim","tag-orquestra-sinfonica-de-betim","tag-sociedade-artistica-brasileira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quem foi Aldir Blanc e qual sua import\u00e2ncia para o Brasil? - SABRA - Sociedade Art\u00edstica Brasileira<\/title>\n<meta name=\"description\" content=\"Voc\u00ea j\u00e1 ouviu falar no compositor e escritor brasileiro Aldir Blanc? Sabia que ele muito \u00e9 importante para o cen\u00e1rio cultural do nosso pa\u00eds?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quem foi Aldir Blanc e qual sua import\u00e2ncia para o Brasil? - SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea j\u00e1 ouviu falar no compositor e escritor brasileiro Aldir Blanc? Sabia que ele muito \u00e9 importante para o cen\u00e1rio cultural do nosso pa\u00eds?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/\" \/>\n<meta property=\"og:site_name\" content=\"SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabrabrasil\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-10T14:43:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/07\/quem-foi-aldir-blanc-e-qual-sua-importancia-para-o-brasil-20210311095559.jpg.jpg?fit=800%2C480&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:site\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aldir-blanc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aldir-blanc\\\/\"},\"author\":{\"name\":\"M\u00e1rcio Miranda Pontes\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\"},\"headline\":\"Quem foi Aldir Blanc e qual sua import\u00e2ncia para o Brasil?\",\"datePublished\":\"2021-07-10T14:43:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aldir-blanc\\\/\"},\"wordCount\":735,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aldir-blanc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/quem-foi-aldir-blanc-e-qual-sua-importancia-para-o-brasil-20210311095559.jpg.jpg\",\"keywords\":[\"Assist\u00eancia social\",\"Canto Coral\",\"Escola de Musica SABRA\",\"Musicaliza\u00e7\u00e3o Infantil\",\"nova lima\",\"Orquestra Infanto Juvenil de Betim\",\"Orquestra Sinf\u00f4nica de Betim\",\"Sociedade Art\u00edstica Brasileira\"],\"articleSection\":[\"Blog SABRA\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aldir-blanc\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aldir-blanc\\\/\",\"name\":\"Quem foi Aldir Blanc e qual sua import\u00e2ncia para o Brasil? - SABRA - Sociedade Art\u00edstica Brasileira\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aldir-blanc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aldir-blanc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/quem-foi-aldir-blanc-e-qual-sua-importancia-para-o-brasil-20210311095559.jpg.jpg\",\"datePublished\":\"2021-07-10T14:43:32+00:00\",\"description\":\"Voc\u00ea j\u00e1 ouviu falar no compositor e escritor brasileiro Aldir Blanc? Sabia que ele muito \u00e9 importante para o cen\u00e1rio cultural do nosso pa\u00eds?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aldir-blanc\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aldir-blanc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aldir-blanc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/quem-foi-aldir-blanc-e-qual-sua-importancia-para-o-brasil-20210311095559.jpg.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/quem-foi-aldir-blanc-e-qual-sua-importancia-para-o-brasil-20210311095559.jpg.jpg\",\"width\":800,\"height\":480,\"caption\":\"Sociedade Art\u00edstica Brasileira SABRA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aldir-blanc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quem foi Aldir Blanc e qual sua import\u00e2ncia para o Brasil?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"name\":\"SABRA - Sociedade Art\u00edstica Brasileira\",\"description\":\"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\",\"name\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\",\"alternateName\":\"SABRA\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"width\":400,\"height\":128,\"caption\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sabrabrasil\",\"https:\\\/\\\/x.com\\\/ContatoSabra\",\"https:\\\/\\\/www.instagram.com\\\/sabrabrasil\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/25002088\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/sociedadeartisticabrasileira\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/sabrabrasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\",\"name\":\"M\u00e1rcio Miranda Pontes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"caption\":\"M\u00e1rcio Miranda Pontes\"},\"sameAs\":[\"http:\\\/\\\/www.sabra.org.br\"],\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/author\\\/marcio-miranda-pontes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quem foi Aldir Blanc e qual sua import\u00e2ncia para o Brasil? - SABRA - Sociedade Art\u00edstica Brasileira","description":"Voc\u00ea j\u00e1 ouviu falar no compositor e escritor brasileiro Aldir Blanc? Sabia que ele muito \u00e9 importante para o cen\u00e1rio cultural do nosso pa\u00eds?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/","og_locale":"pt_BR","og_type":"article","og_title":"Quem foi Aldir Blanc e qual sua import\u00e2ncia para o Brasil? - SABRA - Sociedade Art\u00edstica Brasileira","og_description":"Voc\u00ea j\u00e1 ouviu falar no compositor e escritor brasileiro Aldir Blanc? Sabia que ele muito \u00e9 importante para o cen\u00e1rio cultural do nosso pa\u00eds?","og_url":"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/","og_site_name":"SABRA - Sociedade Art\u00edstica Brasileira","article_publisher":"https:\/\/www.facebook.com\/sabrabrasil","article_published_time":"2021-07-10T14:43:32+00:00","og_image":[{"width":800,"height":480,"url":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/07\/quem-foi-aldir-blanc-e-qual-sua-importancia-para-o-brasil-20210311095559.jpg.jpg?fit=800%2C480&ssl=1","type":"image\/jpeg"}],"author":"M\u00e1rcio Miranda Pontes","twitter_card":"summary_large_image","twitter_creator":"@ContatoSabra","twitter_site":"@ContatoSabra","twitter_misc":{"Escrito por":"M\u00e1rcio Miranda Pontes","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/#article","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/"},"author":{"name":"M\u00e1rcio Miranda Pontes","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2"},"headline":"Quem foi Aldir Blanc e qual sua import\u00e2ncia para o Brasil?","datePublished":"2021-07-10T14:43:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/"},"wordCount":735,"publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/07\/quem-foi-aldir-blanc-e-qual-sua-importancia-para-o-brasil-20210311095559.jpg.jpg","keywords":["Assist\u00eancia social","Canto Coral","Escola de Musica SABRA","Musicaliza\u00e7\u00e3o Infantil","nova lima","Orquestra Infanto Juvenil de Betim","Orquestra Sinf\u00f4nica de Betim","Sociedade Art\u00edstica Brasileira"],"articleSection":["Blog SABRA"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/","url":"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/","name":"Quem foi Aldir Blanc e qual sua import\u00e2ncia para o Brasil? - SABRA - Sociedade Art\u00edstica Brasileira","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/#primaryimage"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/07\/quem-foi-aldir-blanc-e-qual-sua-importancia-para-o-brasil-20210311095559.jpg.jpg","datePublished":"2021-07-10T14:43:32+00:00","description":"Voc\u00ea j\u00e1 ouviu falar no compositor e escritor brasileiro Aldir Blanc? Sabia que ele muito \u00e9 importante para o cen\u00e1rio cultural do nosso pa\u00eds?","breadcrumb":{"@id":"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sabra.org.br\/site\/aldir-blanc\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/#primaryimage","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/07\/quem-foi-aldir-blanc-e-qual-sua-importancia-para-o-brasil-20210311095559.jpg.jpg","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/07\/quem-foi-aldir-blanc-e-qual-sua-importancia-para-o-brasil-20210311095559.jpg.jpg","width":800,"height":480,"caption":"Sociedade Art\u00edstica Brasileira SABRA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sabra.org.br\/site\/aldir-blanc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.sabra.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Quem foi Aldir Blanc e qual sua import\u00e2ncia para o Brasil?"}]},{"@type":"WebSite","@id":"https:\/\/www.sabra.org.br\/site\/#website","url":"https:\/\/www.sabra.org.br\/site\/","name":"SABRA - Sociedade Art\u00edstica Brasileira","description":"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico","publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sabra.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.sabra.org.br\/site\/#organization","name":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA","alternateName":"SABRA","url":"https:\/\/www.sabra.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","width":400,"height":128,"caption":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabrabrasil","https:\/\/x.com\/ContatoSabra","https:\/\/www.instagram.com\/sabrabrasil\/","https:\/\/www.linkedin.com\/company\/25002088\/","https:\/\/br.pinterest.com\/sociedadeartisticabrasileira\/","https:\/\/www.youtube.com\/c\/sabrabrasil"]},{"@type":"Person","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2","name":"M\u00e1rcio Miranda Pontes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","caption":"M\u00e1rcio Miranda Pontes"},"sameAs":["http:\/\/www.sabra.org.br"],"url":"https:\/\/www.sabra.org.br\/site\/author\/marcio-miranda-pontes\/"}]}},"jetpack_featured_media_url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/07\/quem-foi-aldir-blanc-e-qual-sua-importancia-para-o-brasil-20210311095559.jpg.jpg","jetpack_shortlink":"https:\/\/wp.me\/p95j2Z-12R","jetpack-related-posts":[{"id":4243,"url":"https:\/\/www.sabra.org.br\/site\/musica-brasileira-grandes-nomes\/","url_meta":{"origin":4021,"position":0},"title":"Grandes nomes da m\u00fasica brasileira que infelizmente nos deixaram em 2020","author":"M\u00e1rcio Miranda Pontes","date":"8 de outubro de 2021","format":false,"excerpt":"Grandes nomes da m\u00fasica brasileira que infelizmente nos deixaram em 2020 O mundo da m\u00fasica sofreu com grandes perdas no ano de 2020. Entre m\u00fasicos, compositores e instrumentistas, dezenas de nomes importantes se foram, deixando um espa\u00e7o aberto e contribui\u00e7\u00f5es grandiosas. Vamos conhecer alguns deles? Patroci\u0301nio m\u00e1ster: @institutounimedbh, viabilizado pelo\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"m\u00fasica-brasileira-grandes-nomes","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/10\/grandes-nomes-da-musica-brasileira-que-infelizmente-nos-deixaram-em-20210125102928.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/10\/grandes-nomes-da-musica-brasileira-que-infelizmente-nos-deixaram-em-20210125102928.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/10\/grandes-nomes-da-musica-brasileira-que-infelizmente-nos-deixaram-em-20210125102928.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/10\/grandes-nomes-da-musica-brasileira-que-infelizmente-nos-deixaram-em-20210125102928.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2980,"url":"https:\/\/www.sabra.org.br\/site\/discos-para-playlist\/","url_meta":{"origin":4021,"position":1},"title":"Discos para sua playlist","author":"M\u00e1rcio Miranda Pontes","date":"4 de junho de 2020","format":false,"excerpt":"Anda meio perdido, sem saber o que colocar na sua playlist? Acesse o nosso link a seguir e descubra os 5 discos de m\u00fasica que voc\u00ea precisa ouvir ainda este ano!","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"playlist-discos","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/06\/x-discos-de-musica-que-voce-precisa-ouvir-ainda-esse-ano-20200430180602.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/06\/x-discos-de-musica-que-voce-precisa-ouvir-ainda-esse-ano-20200430180602.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/06\/x-discos-de-musica-que-voce-precisa-ouvir-ainda-esse-ano-20200430180602.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2020\/06\/x-discos-de-musica-que-voce-precisa-ouvir-ainda-esse-ano-20200430180602.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6835,"url":"https:\/\/www.sabra.org.br\/site\/biografia-musicos\/","url_meta":{"origin":4021,"position":2},"title":"Biografias de m\u00fasicos brasileiros","author":"M\u00e1rcio Miranda Pontes","date":"30 de mar\u00e7o de 2023","format":false,"excerpt":"Quer saber mais sobre a m\u00fasica brasileira e seus mais incr\u00edveis expoentes? Acesse o link a seguir e conhe\u00e7a pelo menos 4 biografias de m\u00fasicos brasileiros que voc\u00ea n\u00e3o pode deixar de ler!","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"m\u00fasica-brasileira-biografia","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/x-biografias-de-cantores-brasileiros-20221024103355.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/x-biografias-de-cantores-brasileiros-20221024103355.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/x-biografias-de-cantores-brasileiros-20221024103355.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/03\/x-biografias-de-cantores-brasileiros-20221024103355.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6144,"url":"https:\/\/www.sabra.org.br\/site\/musicas-mais-conhecidas\/","url_meta":{"origin":4021,"position":3},"title":"M\u00fasicas mais populares de todos os tempos","author":"M\u00e1rcio Miranda Pontes","date":"27 de outubro de 2022","format":false,"excerpt":"Seja por fatores culturais, acontecimentos hist\u00f3ricos ou outras quest\u00f5es, algumas m\u00fasicas se tornam conhecidas e acabam por perdurarem por anos na vida das pessoas. Separamos para voc\u00ea, leitor, algumas m\u00fasicas brasileiras mais populares:","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"m\u00fasica-popular-brasileira","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/10\/x-musicas-mais-populares-de-todos-os-temposjpg-20220908094423.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/10\/x-musicas-mais-populares-de-todos-os-temposjpg-20220908094423.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/10\/x-musicas-mais-populares-de-todos-os-temposjpg-20220908094423.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/10\/x-musicas-mais-populares-de-todos-os-temposjpg-20220908094423.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7961,"url":"https:\/\/www.sabra.org.br\/site\/compositores-classica\/","url_meta":{"origin":4021,"position":4},"title":"6 grandes nomes que marcaram a m\u00fasica cl\u00e1ssica","author":"M\u00e1rcio Miranda Pontes","date":"13 de setembro de 2023","format":false,"excerpt":"Descubra os 6 grandes nomes que deixaram um legado indel\u00e9vel na m\u00fasica cl\u00e1ssica. Explore suas obras ic\u00f4nicas e mergulhe na magia da m\u00fasica cl\u00e1ssica. Prepare-se para uma viagem pelo tempo e pela genialidade desses mestres da m\u00fasica!","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"sabra-m\u00fasica-compositores-cl\u00e1ssica-nascido-bach-chopin-obras","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/09\/x-grandes-nomes-que-marcaram-a-musica-classicajpg-20230628095402.jpg-jpg.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/09\/x-grandes-nomes-que-marcaram-a-musica-classicajpg-20230628095402.jpg-jpg.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/09\/x-grandes-nomes-que-marcaram-a-musica-classicajpg-20230628095402.jpg-jpg.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/09\/x-grandes-nomes-que-marcaram-a-musica-classicajpg-20230628095402.jpg-jpg.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":8284,"url":"https:\/\/www.sabra.org.br\/site\/autor-conhecido\/","url_meta":{"origin":4021,"position":5},"title":"Conhe\u00e7a escritores brasileiros independentes","author":"M\u00e1rcio Miranda Pontes","date":"20 de outubro de 2023","format":false,"excerpt":"Existem diversos profissionais que chamam a aten\u00e7\u00e3o quando o assunto \u00e9 a produ\u00e7\u00e3o independente, com diversos temas e obras. Quer saber mais? Aproveite para acessar o conte\u00fado completo e confira todos os detalhes.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"sabra-m\u00fasica-autor-conhecido","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/10\/conheca-x-escritores-brasileiros-independentesjpg-20221124141249.jpg-jpg.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/10\/conheca-x-escritores-brasileiros-independentesjpg-20221124141249.jpg-jpg.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/10\/conheca-x-escritores-brasileiros-independentesjpg-20221124141249.jpg-jpg.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/10\/conheca-x-escritores-brasileiros-independentesjpg-20221124141249.jpg-jpg.webp?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/4021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/comments?post=4021"}],"version-history":[{"count":0,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/4021\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media\/4023"}],"wp:attachment":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media?parent=4021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/categories?post=4021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/tags?post=4021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}