{"id":4144,"date":"2021-08-30T17:23:14","date_gmt":"2021-08-30T20:23:14","guid":{"rendered":"https:\/\/www.sabra.org.br\/site\/?p=4144"},"modified":"2025-04-18T18:23:36","modified_gmt":"2025-04-18T21:23:36","slug":"desenvolvimento-sustentavel","status":"publish","type":"post","link":"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/","title":{"rendered":"Principais desafios para o Brasil atingir os Objetivos de Desenvolvimento Sustent\u00e1vel"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Esgotamento de recursos, aquecimento global, polui\u00e7\u00e3o, s\u00e3o alguns elementos do cen\u00e1rio atual que v\u00e3o na contram\u00e3o do conceito de desenvolvimento sustent\u00e1vel.<\/p>\n<p>Apesar de ser um conceito bastante amplo, mas \u00e9 poss\u00edvel definir o desenvolvimento sustent\u00e1vel, em linhas gerais, como o desenvolvimento que permite o suprimento das necessidades da gera\u00e7\u00e3o atual sem que a capacidade de atendimento da necessidade das gera\u00e7\u00f5es futuras seja comprometida.<\/p>\n<p>No Brasil a pauta do desenvolvimento sustent\u00e1vel \u00e9 largamente discutida, o pa\u00eds j\u00e1 foi sede das confer\u00eancias mais importantes da hist\u00f3ria sobre o tema: a Rio 92 (Confer\u00eancia das Na\u00e7\u00f5es Unidas sobre Meio Ambiente e Desenvolvimento) e a Rio 20 (Confer\u00eancia das Na\u00e7\u00f5es Unidas sobre Desenvolvimento Sustent\u00e1vel).<\/p>\n<p>O objetivo dos eventos foi reafirmar o compromisso pol\u00edtico com o desenvolvimento sustent\u00e1vel, e durante a Rio 20, o conceito de desenvolvimento sustent\u00e1vel foi consolidado em suas 3 dimens\u00f5es: social, econ\u00f4mica e ambiental.<\/p>\n<p>Atualmente, o desenvolvimento sustent\u00e1vel \u00e9 orientado principalmente pela Agenda 2030, um plano global desenvolvido pela ONU em 2015 que definiu 17 objetivos de desenvolvimento sustent\u00e1vel e 169 metas que visam erradicar a pobreza e oferecer condi\u00e7\u00f5es de uma vida digna a todos, sem comprometer as gera\u00e7\u00f5es futuras. Para cumprir os objetivos definidos pela Agenda 2030, o Brasil precisar\u00e1 lidar com diversos obst\u00e1culos. Destacamos aqui os que representam os maiores desafios.<\/p>\n<h2>As consequ\u00eancias da revolu\u00e7\u00e3o verde<\/h2>\n<p>Movimento iniciado no M\u00e9xico que chegou ao Brasil durante o per\u00edodo da ditadura militar (entre as d\u00e9cadas de 1960 e 1970), a chamada Revolu\u00e7\u00e3o Verde foi um per\u00edodo de intenso investimento na cria\u00e7\u00e3o e aprimoramento de novas t\u00e9cnicas agr\u00edcolas.<\/p>\n<p>O resultado foi o aumento expressivo da produ\u00e7\u00e3o, por\u00e9m, as consequ\u00eancias do per\u00edodo perduram at\u00e9 hoje. Desmatamento massivo, utiliza\u00e7\u00e3o de agrot\u00f3xicos que contaminam solos e rios transformando negativamente os ecossistemas, e a expuls\u00e3o dos pequenos produtores (o que aumentou o \u00eaxodo rural e, consequentemente, as popula\u00e7\u00f5es perif\u00e9ricas) s\u00e3o as principais consequ\u00eancias.<\/p>\n<p>Atualmente, a agricultura n\u00e3o possui seu foco totalmente voltado para a produ\u00e7\u00e3o, mas h\u00e1 uma cultura de sustentabilidade imergindo. Entretanto, ainda h\u00e1 um caminho longo para reverter o cen\u00e1rio criado pela Revolu\u00e7\u00e3o Verde.<\/p>\n<h2>A crise sanit\u00e1ria do novo coronav\u00edrus<\/h2>\n<p>N\u00e3o h\u00e1 d\u00favidas de que o advento da pandemia do novo coronav\u00edrus mudou drasticamente todas as \u00e1reas e tarefas. Tal mudan\u00e7a radical tem impactos sens\u00edveis no alcance das metas de desenvolvimento sustent\u00e1vel definidas pela ONU em 2015.<\/p>\n<p>No \u00e2mbito da sa\u00fade p\u00fablica, destacamos a superlota\u00e7\u00e3o hospitalar, escassez de insumos e interrup\u00e7\u00e3o de atendimentos n\u00e3o relacionados \u00e0 covid-19. Nota-se tamb\u00e9m um grande aumento dos problemas de sa\u00fade mental.<\/p>\n<p>O acesso \u00e0 educa\u00e7\u00e3o, por sua vez, tornou-se ainda mais dif\u00edcil. O ensino a dist\u00e2ncia trouxe grande preju\u00edzo ao aprendizado de crian\u00e7as e adolescentes em idade escolar, uma vez que houve a necessidade de uma adapta\u00e7\u00e3o brusca do ensino presencial para o remoto. Ademais, o acesso \u00e0 internet, computadores, tablets e celulares n\u00e3o \u00e9 uma unanimidade entre os alunos, muitos dos quais n\u00e3o tem condi\u00e7\u00f5es de assistir \u00e0s aulas.<\/p>\n<p>Al\u00e9m desses desafios, o Brasil ainda precisa lidar com outros in\u00fameros obst\u00e1culos como saneamento b\u00e1sico escasso (o que facilita o cont\u00e1gio pelo novo coronav\u00edrus), aumento da incid\u00eancia de viol\u00eancia dom\u00e9stica, crise econ\u00f4mica e desemprego.<\/p>\n<p>Os impactos da pandemia ainda n\u00e3o s\u00e3o todos conhecidos. Mas n\u00e3o restam d\u00favidas de que h\u00e1 muito trabalho pela frente.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"8IV46wQ1BK\"><p><a href=\"https:\/\/www.sabra.org.br\/site\/turismo-sustentavel\/\">Turismo sustent\u00e1vel: o que \u00e9 e qual sua import\u00e2ncia<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;Turismo sustent\u00e1vel: o que \u00e9 e qual sua import\u00e2ncia&#8221; &#8212; SABRA - Sociedade Art\u00edstica Brasileira\" src=\"https:\/\/www.sabra.org.br\/site\/turismo-sustentavel\/embed\/#?secret=ZYMlDT0ZPP#?secret=8IV46wQ1BK\" data-secret=\"8IV46wQ1BK\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<hr \/>\n<h2>Se voc\u00ea gostou deste post:<\/h2>\n<p>&#8211; SIGA as nossas p\u00e1ginas nas redes sociais para acompanhar as nossas atualiza\u00e7\u00f5es: estamos no <a href=\"https:\/\/www.facebook.com\/sabrabrasil\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>, no <a href=\"https:\/\/www.instagram.com\/sabrabrasil\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a>, no <a href=\"https:\/\/www.linkedin.com\/company\/25002088\" target=\"_blank\" rel=\"noopener\">LinkedIn<\/a>, no <a href=\"https:\/\/twitter.com\/ContatoSabra\" target=\"_blank\" rel=\"noopener\">Twitter<\/a> e no <a href=\"https:\/\/www.youtube.com\/channel\/UCJw-kbuEvzUNdeQf20Pa-eQ\" target=\"_blank\" rel=\"noopener\">YouTube<\/a>!<\/p>\n<p>&#8211; CONHE\u00c7A o trabalho da Sociedade Art\u00edstica Brasileira (SABRA) e todas as iniciativas culturais e sociais que ela mant\u00e9m. <a href=\"https:\/\/www.sabra.org.br\/site\/acoes\/\" target=\"_blank\" rel=\"noopener\">Acesse nosso site!<\/a><\/p>\n<p>&#8211; ENTRE EM CONTATO com a gente. E veja quais s\u00e3o as op\u00e7\u00f5es de ajuda na manuten\u00e7\u00e3o de nossas a\u00e7\u00f5es sociais e culturais. Basta acessar nossa p\u00e1gina <a href=\"https:\/\/www.sabra.org.br\/site\/doe-agora\/\" target=\"_blank\" rel=\"noopener\">Doe Agora!<\/a><\/p>\n<p>&#8211; COMPARTILHE este texto nas suas redes sociais e ajude os seus amigos a tamb\u00e9m dominarem o assunto!<\/p>\n<p>\u2013 Os projetos da @sabrabrasil s\u00e3o realizados com o patroci\u0301nio m\u00e1ster: @institutounimedbh, viabilizado pelo incentivo de mais de 5,2 mil m\u00e9dicos cooperados e colaboradores via Lei de Incentivo \u00e0 Cultura. Patroc\u00ednio prata: @vallourec e apoio: @prefeiturabetim[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Principais desafios para o Brasil atingir os Objetivos de Desenvolvimento Sustent\u00e1vel<\/p>\n<p>O Brasil ainda precisa enfrentar diversos desafios para alcan\u00e7ar as metas de desenvolvimento sustent\u00e1vel definidas em 2015, sobre tudo ap\u00f3s a pandemia do novo coronav\u00edrus. Para saber mais sobre o assunto, acesse nosso blog.<\/p>\n<p>Patroci\u0301nio m\u00e1ster: @institutounimedbh, viabilizado pelo incentivo de mais de 5,2 mil m\u00e9dicos cooperados e colaboradores via Lei de Incentivo \u00e0 Cultura. Patroc\u00ednio prata: @vallourec e apoio: @prefeiturabetim<\/p>\n<p>#sabrabrasil #institutounimedbh #vallourec #semedbetim #betim #novalima #raposos #camposdosgoytacazes #maestromarciomirandapontes<\/p>\n","protected":false},"author":39,"featured_media":4145,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[15,3623,8,1285,16,3519,1286,11,3622,9],"class_list":["post-4144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-sabra","tag-assistencia-social","tag-campos-dos-goytacazes","tag-canto-coral","tag-escola-de-musica-sabra","tag-musicalizacao-infantil","tag-nova-lima-2","tag-orquestra-infanto-juvenil-de-betim","tag-orquestra-sinfonica-de-betim","tag-raposos","tag-sociedade-artistica-brasileira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desenvolvimento Sustent\u00e1vel e Suas Desafios - SABRA - Sociedade Art\u00edstica Brasileira<\/title>\n<meta name=\"description\" content=\"O Brasil ainda precisa enfrentar diversos desafios para alcan\u00e7ar as metas de desenvolvimento sustent\u00e1vel definidas em 2015.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desenvolvimento Sustent\u00e1vel e Suas Desafios - SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"og:description\" content=\"O Brasil ainda precisa enfrentar diversos desafios para alcan\u00e7ar as metas de desenvolvimento sustent\u00e1vel definidas em 2015.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/\" \/>\n<meta property=\"og:site_name\" content=\"SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabrabrasil\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-30T20:23:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-18T21:23:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/08\/principais-desafios-para-o-brasil-atingir-os-objetivos-de-desenvolvimento-sustentavel-20210609152644.jpg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:site\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/desenvolvimento-sustentavel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/desenvolvimento-sustentavel\\\/\"},\"author\":{\"name\":\"M\u00e1rcio Miranda Pontes\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\"},\"headline\":\"Principais desafios para o Brasil atingir os Objetivos de Desenvolvimento Sustent\u00e1vel\",\"datePublished\":\"2021-08-30T20:23:14+00:00\",\"dateModified\":\"2025-04-18T21:23:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/desenvolvimento-sustentavel\\\/\"},\"wordCount\":791,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/desenvolvimento-sustentavel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/principais-desafios-para-o-brasil-atingir-os-objetivos-de-desenvolvimento-sustentavel-20210609152644.jpg.jpg\",\"keywords\":[\"Assist\u00eancia social\",\"Campos dos Goytacazes\",\"Canto Coral\",\"Escola de Musica SABRA\",\"Musicaliza\u00e7\u00e3o Infantil\",\"nova lima\",\"Orquestra Infanto Juvenil de Betim\",\"Orquestra Sinf\u00f4nica de Betim\",\"Raposos\",\"Sociedade Art\u00edstica Brasileira\"],\"articleSection\":[\"Blog SABRA\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/desenvolvimento-sustentavel\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/desenvolvimento-sustentavel\\\/\",\"name\":\"Desenvolvimento Sustent\u00e1vel e Suas Desafios - SABRA - Sociedade Art\u00edstica Brasileira\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/desenvolvimento-sustentavel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/desenvolvimento-sustentavel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/principais-desafios-para-o-brasil-atingir-os-objetivos-de-desenvolvimento-sustentavel-20210609152644.jpg.jpg\",\"datePublished\":\"2021-08-30T20:23:14+00:00\",\"dateModified\":\"2025-04-18T21:23:36+00:00\",\"description\":\"O Brasil ainda precisa enfrentar diversos desafios para alcan\u00e7ar as metas de desenvolvimento sustent\u00e1vel definidas em 2015.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/desenvolvimento-sustentavel\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/desenvolvimento-sustentavel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/desenvolvimento-sustentavel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/principais-desafios-para-o-brasil-atingir-os-objetivos-de-desenvolvimento-sustentavel-20210609152644.jpg.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/principais-desafios-para-o-brasil-atingir-os-objetivos-de-desenvolvimento-sustentavel-20210609152644.jpg.jpg\",\"width\":800,\"height\":533,\"caption\":\"Sociedade Art\u00edstica Brasileira SABRA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/desenvolvimento-sustentavel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Principais desafios para o Brasil atingir os Objetivos de Desenvolvimento Sustent\u00e1vel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"name\":\"SABRA - Sociedade Art\u00edstica Brasileira\",\"description\":\"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\",\"name\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\",\"alternateName\":\"SABRA\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"width\":400,\"height\":128,\"caption\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sabrabrasil\",\"https:\\\/\\\/x.com\\\/ContatoSabra\",\"https:\\\/\\\/www.instagram.com\\\/sabrabrasil\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/25002088\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/sociedadeartisticabrasileira\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/sabrabrasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\",\"name\":\"M\u00e1rcio Miranda Pontes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"caption\":\"M\u00e1rcio Miranda Pontes\"},\"sameAs\":[\"http:\\\/\\\/www.sabra.org.br\"],\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/author\\\/marcio-miranda-pontes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desenvolvimento Sustent\u00e1vel e Suas Desafios - SABRA - Sociedade Art\u00edstica Brasileira","description":"O Brasil ainda precisa enfrentar diversos desafios para alcan\u00e7ar as metas de desenvolvimento sustent\u00e1vel definidas em 2015.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/","og_locale":"pt_BR","og_type":"article","og_title":"Desenvolvimento Sustent\u00e1vel e Suas Desafios - SABRA - Sociedade Art\u00edstica Brasileira","og_description":"O Brasil ainda precisa enfrentar diversos desafios para alcan\u00e7ar as metas de desenvolvimento sustent\u00e1vel definidas em 2015.","og_url":"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/","og_site_name":"SABRA - Sociedade Art\u00edstica Brasileira","article_publisher":"https:\/\/www.facebook.com\/sabrabrasil","article_published_time":"2021-08-30T20:23:14+00:00","article_modified_time":"2025-04-18T21:23:36+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/08\/principais-desafios-para-o-brasil-atingir-os-objetivos-de-desenvolvimento-sustentavel-20210609152644.jpg.jpg","type":"image\/jpeg"}],"author":"M\u00e1rcio Miranda Pontes","twitter_card":"summary_large_image","twitter_creator":"@ContatoSabra","twitter_site":"@ContatoSabra","twitter_misc":{"Escrito por":"M\u00e1rcio Miranda Pontes","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/#article","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/"},"author":{"name":"M\u00e1rcio Miranda Pontes","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2"},"headline":"Principais desafios para o Brasil atingir os Objetivos de Desenvolvimento Sustent\u00e1vel","datePublished":"2021-08-30T20:23:14+00:00","dateModified":"2025-04-18T21:23:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/"},"wordCount":791,"publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/08\/principais-desafios-para-o-brasil-atingir-os-objetivos-de-desenvolvimento-sustentavel-20210609152644.jpg.jpg","keywords":["Assist\u00eancia social","Campos dos Goytacazes","Canto Coral","Escola de Musica SABRA","Musicaliza\u00e7\u00e3o Infantil","nova lima","Orquestra Infanto Juvenil de Betim","Orquestra Sinf\u00f4nica de Betim","Raposos","Sociedade Art\u00edstica Brasileira"],"articleSection":["Blog SABRA"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/","url":"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/","name":"Desenvolvimento Sustent\u00e1vel e Suas Desafios - SABRA - Sociedade Art\u00edstica Brasileira","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/#primaryimage"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/08\/principais-desafios-para-o-brasil-atingir-os-objetivos-de-desenvolvimento-sustentavel-20210609152644.jpg.jpg","datePublished":"2021-08-30T20:23:14+00:00","dateModified":"2025-04-18T21:23:36+00:00","description":"O Brasil ainda precisa enfrentar diversos desafios para alcan\u00e7ar as metas de desenvolvimento sustent\u00e1vel definidas em 2015.","breadcrumb":{"@id":"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/#primaryimage","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/08\/principais-desafios-para-o-brasil-atingir-os-objetivos-de-desenvolvimento-sustentavel-20210609152644.jpg.jpg","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/08\/principais-desafios-para-o-brasil-atingir-os-objetivos-de-desenvolvimento-sustentavel-20210609152644.jpg.jpg","width":800,"height":533,"caption":"Sociedade Art\u00edstica Brasileira SABRA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sabra.org.br\/site\/desenvolvimento-sustentavel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.sabra.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Principais desafios para o Brasil atingir os Objetivos de Desenvolvimento Sustent\u00e1vel"}]},{"@type":"WebSite","@id":"https:\/\/www.sabra.org.br\/site\/#website","url":"https:\/\/www.sabra.org.br\/site\/","name":"SABRA - Sociedade Art\u00edstica Brasileira","description":"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico","publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sabra.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.sabra.org.br\/site\/#organization","name":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA","alternateName":"SABRA","url":"https:\/\/www.sabra.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","width":400,"height":128,"caption":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabrabrasil","https:\/\/x.com\/ContatoSabra","https:\/\/www.instagram.com\/sabrabrasil\/","https:\/\/www.linkedin.com\/company\/25002088\/","https:\/\/br.pinterest.com\/sociedadeartisticabrasileira\/","https:\/\/www.youtube.com\/c\/sabrabrasil"]},{"@type":"Person","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2","name":"M\u00e1rcio Miranda Pontes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","caption":"M\u00e1rcio Miranda Pontes"},"sameAs":["http:\/\/www.sabra.org.br"],"url":"https:\/\/www.sabra.org.br\/site\/author\/marcio-miranda-pontes\/"}]}},"jetpack_featured_media_url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/08\/principais-desafios-para-o-brasil-atingir-os-objetivos-de-desenvolvimento-sustentavel-20210609152644.jpg.jpg","jetpack_shortlink":"https:\/\/wp.me\/p95j2Z-14Q","jetpack-related-posts":[{"id":3976,"url":"https:\/\/www.sabra.org.br\/site\/parceria-global\/","url_meta":{"origin":4144,"position":0},"title":"Desenvolvimento sustent\u00e1vel no Brasil e parceria global","author":"M\u00e1rcio Miranda Pontes","date":"29 de junho de 2021","format":false,"excerpt":"Parceria global e o desenvolvimento sustent\u00e1vel no Brasil O desenvolvimento sustent\u00e1vel \u00e9 um conceito importante que visa melhorar a prote\u00e7\u00e3o do meio ambiente para garantir um futuro melhor para as gera\u00e7\u00f5es futuras. No texto a seguir, entenda melhor a import\u00e2ncia da parceria global para o desenvolvimento sustent\u00e1vel no Brasil.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"desenvolvimento-sustent\u00e1vel-objetivo-brasil-blog-sabra","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/a-importancia-da-parceria-global-para-o-desenvolvimento-sustentavel-no-brasil-20210609152644.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/a-importancia-da-parceria-global-para-o-desenvolvimento-sustentavel-no-brasil-20210609152644.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/a-importancia-da-parceria-global-para-o-desenvolvimento-sustentavel-no-brasil-20210609152644.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/a-importancia-da-parceria-global-para-o-desenvolvimento-sustentavel-no-brasil-20210609152644.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3898,"url":"https:\/\/www.sabra.org.br\/site\/sustentabilidade\/","url_meta":{"origin":4144,"position":1},"title":"Guia b\u00e1sico sobre os Objetivos de Desenvolvimento Sustent\u00e1vel da ONU","author":"M\u00e1rcio Miranda Pontes","date":"21 de maio de 2021","format":false,"excerpt":"Guia b\u00e1sico sobre os Objetivos de Desenvolvimento Sustent\u00e1vel da ONU A ONU firmou acordo com os 193 pa\u00edses membros para um plano de a\u00e7\u00e3o global que visa o alcance de 17 diretrizes, a fim de garantir um futuro melhor e mais sustent\u00e1vel. Essas diretrizes s\u00e3o os Objetivos de Desenvolvimento Sustent\u00e1vel\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"desenvolvimento-sustentavel-sustentabilidade","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/05\/guia-basico-sobre-os-objetivos-de-desenvolvimento-sustentavel-da-onu-20210423165408.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/05\/guia-basico-sobre-os-objetivos-de-desenvolvimento-sustentavel-da-onu-20210423165408.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/05\/guia-basico-sobre-os-objetivos-de-desenvolvimento-sustentavel-da-onu-20210423165408.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/05\/guia-basico-sobre-os-objetivos-de-desenvolvimento-sustentavel-da-onu-20210423165408.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3963,"url":"https:\/\/www.sabra.org.br\/site\/comunidades-sustentaveis\/","url_meta":{"origin":4144,"position":2},"title":"Comunidades sustent\u00e1veis &#8211; os pilares para o desenvolvimento","author":"M\u00e1rcio Miranda Pontes","date":"24 de junho de 2021","format":false,"excerpt":"Comunidades sustent\u00e1veis - os pilares para o desenvolvimento As comunidades sustent\u00e1veis s\u00e3o aquelas que prezam pela sustentabilidade, atrav\u00e9s da preserva\u00e7\u00e3o de recursos naturais somada a uma conscientiza\u00e7\u00e3o social coletiva favor\u00e1vel ao bem-estar da popula\u00e7\u00e3o. Conhe\u00e7a os tr\u00eas pilares que comp\u00f5em uma comunidade sustent\u00e1vel: o social, o econ\u00f4mico e o ambiental.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"pilar-social-comunidade-sustest-sustentabilidade","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/os-pilares-para-o-desenvolvimento-de-comunidades-sustentaveis-20210423165408.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/os-pilares-para-o-desenvolvimento-de-comunidades-sustentaveis-20210423165408.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/os-pilares-para-o-desenvolvimento-de-comunidades-sustentaveis-20210423165408.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/os-pilares-para-o-desenvolvimento-de-comunidades-sustentaveis-20210423165408.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3938,"url":"https:\/\/www.sabra.org.br\/site\/trabalho-2\/","url_meta":{"origin":4144,"position":3},"title":"Trabalho decente: saiba o que \u00e9 e qual a realidade do pa\u00eds","author":"M\u00e1rcio Miranda Pontes","date":"15 de junho de 2021","format":false,"excerpt":"Trabalho decente: saiba o que \u00e9 e qual a realidade do pa\u00eds A Organiza\u00e7\u00e3o Internacional do Trabalho (OIT), ag\u00eancia da ONU, definiu em 1999 o que conceituamos como 'trabalho decente'. Quatro anos mais tarde, o Brasil aderiu a essa pr\u00e1tica. Mas, afinal, do que se trata e como o pa\u00eds\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"trabalho-decente-emprego-sustentabilidade","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/06\/trabalho-decente-saiba-o-que-e-e-qual-a-realidade-do-pais-20210423165408.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3987,"url":"https:\/\/www.sabra.org.br\/site\/agricultura-sustentavel\/","url_meta":{"origin":4144,"position":4},"title":"Agricultura sustent\u00e1vel &#8211; benef\u00edcios","author":"M\u00e1rcio Miranda Pontes","date":"1 de julho de 2021","format":false,"excerpt":"Agricultura sustent\u00e1vel - benef\u00edcios A agricultura sustent\u00e1vel traz diversos benef\u00edcios para a sociedade, como economia, uso adequado e consciente das mat\u00e9rias-primas e bem-estar social. Para conhecer melhor estes e outros benef\u00edcios da agricultura sustent\u00e1vel, leia o conte\u00fado a seguir!","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"agricultura-sustentavel-saudave-alimento-sociedade-familiar-subsist\u00eancia","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/07\/descubra-x-beneficios-da-agricultura-sustentavel-para-a-sociedade-20210609152644.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/07\/descubra-x-beneficios-da-agricultura-sustentavel-para-a-sociedade-20210609152644.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/07\/descubra-x-beneficios-da-agricultura-sustentavel-para-a-sociedade-20210609152644.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/07\/descubra-x-beneficios-da-agricultura-sustentavel-para-a-sociedade-20210609152644.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13198,"url":"https:\/\/www.sabra.org.br\/site\/saiba-como-a-arte-contribui-para-o-crescimento-economico-sustentavel\/","url_meta":{"origin":4144,"position":5},"title":"Saiba como a Arte contribui para o crescimento econ\u00f4mico sustent\u00e1vel","author":"","date":"22 de agosto de 2025","format":false,"excerpt":"A rela\u00e7\u00e3o entre arte e economia pode parecer distante \u00e0 primeira vista, mas a interconex\u00e3o entre esses dois campos \u00e9 mais profunda do que se imagina. A arte desempenha um papel vital no crescimento econ\u00f4mico sustent\u00e1vel, influenciando diversos setores e contribuindo para a forma\u00e7\u00e3o de uma sociedade mais equilibrada e\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/4144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/comments?post=4144"}],"version-history":[{"count":0,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/4144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media\/4145"}],"wp:attachment":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media?parent=4144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/categories?post=4144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/tags?post=4144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}