{"id":4879,"date":"2022-04-01T10:45:48","date_gmt":"2022-04-01T13:45:48","guid":{"rendered":"https:\/\/www.sabra.org.br\/site\/?p=4879"},"modified":"2022-04-01T10:45:48","modified_gmt":"2022-04-01T13:45:48","slug":"samba-enredo","status":"publish","type":"post","link":"https:\/\/www.sabra.org.br\/site\/samba-enredo\/","title":{"rendered":"Sambas-enredo que entraram para a hist\u00f3ria"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<h1>4 sambas-enredo que entraram para a hist\u00f3ria<\/h1>\n<p>O Carnaval \u00e9 uma das manifesta\u00e7\u00f5es culturais mais importantes do Brasil. <strong>E \u00e9 atrav\u00e9s dos desfiles que parte da nossa Hist\u00f3ria \u00e9 contada, nas letras dos sambas-enredo<\/strong>. Essas composi\u00e7\u00f5es podem homenagear figuras importantes, denunciar mazelas e celebrar as belezas do pa\u00eds.<\/p>\n<p>Muitas dessas can\u00e7\u00f5es marcaram \u00e9poca e at\u00e9 sa\u00edram da avenida, recebendo vers\u00f5es de cantores de diferentes g\u00eaneros musicais. No artigo de hoje, citaremos algumas delas. Confira abaixo <strong>4 sambas-enredo que entraram para hist\u00f3ria<\/strong>.<\/p>\n<h2>\u201cXica da Silva\u201d (Acad\u00eamicos do Salgueiro, 1963)<\/h2>\n<p>Escrito por <strong>Noel Rosa de Oliveira<\/strong> e <strong>Anescarzinho<\/strong> e levado \u00e0 avenida pelo carnavalesco <strong>Arlindo Rodrigues<\/strong>. Esse samba-enredo deu ao <strong>Salgueiro<\/strong> seu segundo t\u00edtulo no carnaval carioca e marcou \u00e9poca no primeiro desfile na Avenida Presidente Vargas.<\/p>\n<p>Na d\u00e9cada de 1960, a Escola resolveu homenagear personalidades negras importantes e que n\u00e3o eram t\u00e3o conhecidas do grande p\u00fablico. Foi com esse intuito que o enredo sobre <strong>Chica da Silva<\/strong>, ex-escrava que chegou \u00e0 alta sociedade, foi escolhido. Essa foi a primeira vez que uma personagem feminina foi tema central no carnaval do Rio.<\/p>\n<p>Al\u00e9m disso, o <strong>Salgueiro<\/strong> inovou, tamb\u00e9m, trazendo a primeira ala coreografada da hist\u00f3ria do Carnaval nesse desfile. \u201cO Minueto\u201d teve coreografia criada pela primeira bailarina negra do Teatro Municipal do Rio de Janeiro, <strong>Mercedes Baptista<\/strong>.<\/p>\n<p>O samba-enredo e o desfile homenageando Chica da Silva foi inspira\u00e7\u00e3o para o filme sobre a personagem, dirigido por Cac\u00e1 Diegues, em 1976.<\/p>\n<p><i>Com a influ\u00eancia e o poder do seu amor \/ Que superou a barreira da cor \/ Francisca da Silva, do cativeiro zombou \/ No Arraial do Tijuco \/ L\u00e1 no Estado de Minas.<\/i><\/p>\n<h2>\u201cAquarela Brasileira\u201d (Imp\u00e9rio Serrano, 1964)<\/h2>\n<p>Escrito por <strong>Silas de Oliveira<\/strong>, com interpreta\u00e7\u00e3o de <strong>Carmem Silvana<\/strong>, esse samba-enredo foi baseado em <strong>\u201cAquarela do Brasil\u201d de Ary Barroso<\/strong>. A m\u00fasica sem refr\u00e3o, com letra descritiva e versos longos \u00e9 um dos principais exemplares do estilo \u201csamba de len\u00e7ol\u201d.<\/p>\n<p>A can\u00e7\u00e3o exalta a natureza e a cultura de diferentes regi\u00f5es do Brasil e foi aclamada pelo p\u00fablico e imprensa. Ainda hoje, esse \u00e9 considerado um dos melhores sambas-enredo de todos os tempos, recebendo regrava\u00e7\u00f5es de diversos artistas populares. Elza Soares, Elis Regina, Martinho da Vila, Beth Carvalho, Em\u00edlio Santiago, Zeca Pagodinho, Leci Brand\u00e3o e Arlindo Cruz s\u00e3o alguns exemplos.<\/p>\n<p>Apesar de <strong>\u201cAquarela Brasileira\u201d<\/strong> ser um samba-enredo hist\u00f3rico, a <strong>Imp\u00e9rio Serrano<\/strong> n\u00e3o venceu o carnaval de 1964. A Escola ficou em 4\u00ba lugar naquele ano. A verde e branco resolveu fazer uma reedi\u00e7\u00e3o desse cl\u00e1ssico em 2004, dessa vez no Grupo Especial, chegando \u00e0 nona coloca\u00e7\u00e3o.<\/p>\n<p><i>Vejam esta maravilha de cen\u00e1rio \/ \u00c9 um epis\u00f3dio relic\u00e1rio \/ Que o artista num sonho genial \/ Escolheu para este carnaval \/ E o asfalto como passarela \/ Ser\u00e1 a tela do Brasil em forma de aquarela.<\/i><\/p>\n<h2>\u201cOs Sert\u00f5es\u201d (Em Cima da Hora, 1976)<\/h2>\n<p>Esse samba-enredo \u00e9 uma composi\u00e7\u00e3o de <strong>Edeor de Paula<\/strong> e foi levado \u00e0 avenida pelo carnavalesco <strong>Sebasti\u00e3o Souza de Oliveira<\/strong>. A can\u00e7\u00e3o foi inspirada pelo livro <strong>\u201cOs Sert\u00f5es\u201d, de Euclides da Cunha<\/strong>. Narrando a hist\u00f3ria dos sertanejos na Guerra de Canudos, a letra cita a seca, mis\u00e9ria e exalta a for\u00e7a desses homens.<\/p>\n<p>O samba da <strong>Em Cima da Hora<\/strong> \u00e9 bastante prestigiado, inclusive, vencendo o Estandarte de Ouro, em 1976, como melhor samba-enredo. Apesar disso, o desfile da Escola ficou em 13\u00ba lugar e levou a azul e branco ao rebaixamento naquele ano.<\/p>\n<p>A m\u00fasica ainda \u00e9 muito lembrada e marcou a hist\u00f3ria do Carnaval do Rio e do pa\u00eds, como um todo. Foi regravada em outra vers\u00e3o pelo cantor Fagner, em 1997.<\/p>\n<p><i>Foi no s\u00e9culo passado \/ No interior da Bahia \/ O Homem revoltado com a sorte \/ Do mundo em que vivia \/ Ocultou-se no sert\u00e3o \/ Espalhando a rebeldia \/ Se revoltando contra a lei \/ Que a sociedade oferecia.<\/i><\/p>\n<h2>\u201cKizomba, a Festa de uma Ra\u00e7a\u201d (Unidos de Vila Isabel, 1988)<\/h2>\n<p>O samba-enredo que tornou <strong>Vila Isabel<\/strong> campe\u00e3 pela primeira vez foi escrito por <strong>Rodolpho<\/strong>, <strong>Jonas<\/strong> e <strong>Luiz Carlos da Vila<\/strong>. A can\u00e7\u00e3o foi interpretada por <strong>Gera<\/strong> e <strong>Jorge Tropical<\/strong>.<\/p>\n<p>Idealizado pelos carnavalescos <strong>Milton Siqueira<\/strong>, <strong>Paulo C\u00e9sar Cardoso<\/strong> e <strong>Ilvamar Magalh\u00e3es<\/strong>, esse desfile entrou para a hist\u00f3ria por v\u00e1rios motivos. O uso de materiais alternativos (como palha e sisal) e incomuns na avenida foi algo que chamou aten\u00e7\u00e3o. Tamb\u00e9m, a letra homenageando a influ\u00eancia dos negros na cultura e religi\u00f5es do Brasil \u00e9 considerada uma das mais bonitas do carnaval.<\/p>\n<p>Posteriormente, a m\u00fasica ganhou vers\u00f5es dos cantores <strong>Martinho da Vila<\/strong> (que criou o enredo para a <strong>Vila<\/strong>) e Em\u00edlio Santiago.<\/p>\n<p><i>Que magia\/ Reza, ajeum e orix\u00e1s \/ Tem a for\u00e7a da cultura \/ Tem a arte e a bravura \/ E um bom jogo de cintura \/ Faz valer seus ideais \/ E a beleza pura dos seus rituais.<\/i><\/p>\n<p>Gostou desse texto? Ent\u00e3o continue lendo nosso blog para mais artigos com curiosidades e informa\u00e7\u00f5es sobre a m\u00fasica brasileira.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"f7vLKomKBr\"><p><a href=\"https:\/\/www.sabra.org.br\/site\/choro-samba\/\">Choro e Samba<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Choro e Samba&#8221; &#8212; SABRA - Sociedade Art\u00edstica Brasileira\" src=\"https:\/\/www.sabra.org.br\/site\/choro-samba\/embed\/#?secret=CsTo5pCHk3#?secret=f7vLKomKBr\" data-secret=\"f7vLKomKBr\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<hr \/>\n<h2>Se voc\u00ea gostou deste post:<\/h2>\n<p>&#8211; SIGA as nossas p\u00e1ginas nas redes sociais para acompanhar as nossas atualiza\u00e7\u00f5es: estamos no <a href=\"https:\/\/www.facebook.com\/sabrabrasil\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>, no <a href=\"https:\/\/www.instagram.com\/sabrabrasil\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a>, no <a href=\"https:\/\/www.linkedin.com\/company\/25002088\" target=\"_blank\" rel=\"noopener\">LinkedIn<\/a>, no <a href=\"https:\/\/twitter.com\/ContatoSabra\" target=\"_blank\" rel=\"noopener\">Twitter<\/a> e no <a href=\"https:\/\/www.youtube.com\/channel\/UCJw-kbuEvzUNdeQf20Pa-eQ\" target=\"_blank\" rel=\"noopener\">YouTube<\/a>!<\/p>\n<p>&#8211; CONHE\u00c7A o trabalho da Sociedade Art\u00edstica Brasileira (SABRA) e todas as iniciativas culturais e sociais que ela mant\u00e9m. <a href=\"https:\/\/www.sabra.org.br\/site\/acoes\/\" target=\"_blank\" rel=\"noopener\">Acesse nosso site!<\/a><\/p>\n<p>&#8211; ENTRE EM CONTATO com a gente. E veja quais s\u00e3o as op\u00e7\u00f5es de ajuda na manuten\u00e7\u00e3o de nossas a\u00e7\u00f5es sociais e culturais. Basta acessar nossa p\u00e1gina <a href=\"https:\/\/www.sabra.org.br\/site\/doe-agora\/\" target=\"_blank\" rel=\"noopener\">Doe Agora!<\/a><\/p>\n<p>&#8211; COMPARTILHE este texto nas suas redes sociais e ajude os seus amigos a tamb\u00e9m dominarem o assunto!<\/p>\n<p>\u2013 Os projetos da @sabrabrasil s\u00e3o realizados com o patroci\u0301nio m\u00e1ster: @vallourec e @institutounimedbh, viabilizado pelo incentivo de mais de 5,2 mil m\u00e9dicos cooperados e colaboradores via Lei de Incentivo \u00e0 Cultura &#8211; @mturismo, @culturagovbr. Apoio: @prefeiturabetim[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Carnaval \u00e9 a principal festa popular do pa\u00eds e \u00e9 uma celebra\u00e7\u00e3o que ajuda a entender a nossa Hist\u00f3ria. Os sambas-enredo sempre trazem assuntos e personagens que s\u00e3o importantes para a cultura brasileira e, muitas vezes, marcam \u00e9poca. No artigo de hoje, relembramos 4 sambas-enredo que entraram para a hist\u00f3ria e ganharam o Brasil inteiro. Confira!<\/p>\n","protected":false},"author":39,"featured_media":4880,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[15,3626,3623,8,1285,16,3519,1286,11,3622,9],"class_list":["post-4879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-sabra","tag-assistencia-social","tag-cabo-frio","tag-campos-dos-goytacazes","tag-canto-coral","tag-escola-de-musica-sabra","tag-musicalizacao-infantil","tag-nova-lima-2","tag-orquestra-infanto-juvenil-de-betim","tag-orquestra-sinfonica-de-betim","tag-raposos","tag-sociedade-artistica-brasileira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sambas-enredo que entraram para a hist\u00f3ria - SABRA - Sociedade Art\u00edstica Brasileira<\/title>\n<meta name=\"description\" content=\"O Carnaval \u00e9 a principal festa popular do pa\u00eds e \u00e9 uma celebra\u00e7\u00e3o que ajuda a entender a nossa Hist\u00f3ria. Samba-enredo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sabra.org.br\/site\/samba-enredo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sambas-enredo que entraram para a hist\u00f3ria - SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"og:description\" content=\"O Carnaval \u00e9 a principal festa popular do pa\u00eds e \u00e9 uma celebra\u00e7\u00e3o que ajuda a entender a nossa Hist\u00f3ria. Samba-enredo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sabra.org.br\/site\/samba-enredo\/\" \/>\n<meta property=\"og:site_name\" content=\"SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabrabrasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-01T13:45:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/04\/x-sambas-enredo-que-entraram-para-a-historia-20211111161807.jpg.jpg?fit=800%2C531&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:site\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/samba-enredo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/samba-enredo\\\/\"},\"author\":{\"name\":\"M\u00e1rcio Miranda Pontes\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\"},\"headline\":\"Sambas-enredo que entraram para a hist\u00f3ria\",\"datePublished\":\"2022-04-01T13:45:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/samba-enredo\\\/\"},\"wordCount\":1014,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/samba-enredo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/x-sambas-enredo-que-entraram-para-a-historia-20211111161807.jpg.jpg\",\"keywords\":[\"Assist\u00eancia social\",\"Cabo Frio\",\"Campos dos Goytacazes\",\"Canto Coral\",\"Escola de Musica SABRA\",\"Musicaliza\u00e7\u00e3o Infantil\",\"nova lima\",\"Orquestra Infanto Juvenil de Betim\",\"Orquestra Sinf\u00f4nica de Betim\",\"Raposos\",\"Sociedade Art\u00edstica Brasileira\"],\"articleSection\":[\"Blog SABRA\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/samba-enredo\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/samba-enredo\\\/\",\"name\":\"Sambas-enredo que entraram para a hist\u00f3ria - SABRA - Sociedade Art\u00edstica Brasileira\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/samba-enredo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/samba-enredo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/x-sambas-enredo-que-entraram-para-a-historia-20211111161807.jpg.jpg\",\"datePublished\":\"2022-04-01T13:45:48+00:00\",\"description\":\"O Carnaval \u00e9 a principal festa popular do pa\u00eds e \u00e9 uma celebra\u00e7\u00e3o que ajuda a entender a nossa Hist\u00f3ria. Samba-enredo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/samba-enredo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/samba-enredo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/samba-enredo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/x-sambas-enredo-que-entraram-para-a-historia-20211111161807.jpg.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/x-sambas-enredo-que-entraram-para-a-historia-20211111161807.jpg.jpg\",\"width\":800,\"height\":531,\"caption\":\"Sociedade Art\u00edstica Brasileira SABRA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/samba-enredo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sambas-enredo que entraram para a hist\u00f3ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"name\":\"SABRA - Sociedade Art\u00edstica Brasileira\",\"description\":\"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\",\"name\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\",\"alternateName\":\"SABRA\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"width\":400,\"height\":128,\"caption\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sabrabrasil\",\"https:\\\/\\\/x.com\\\/ContatoSabra\",\"https:\\\/\\\/www.instagram.com\\\/sabrabrasil\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/25002088\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/sociedadeartisticabrasileira\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/sabrabrasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\",\"name\":\"M\u00e1rcio Miranda Pontes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"caption\":\"M\u00e1rcio Miranda Pontes\"},\"sameAs\":[\"http:\\\/\\\/www.sabra.org.br\"],\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/author\\\/marcio-miranda-pontes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sambas-enredo que entraram para a hist\u00f3ria - SABRA - Sociedade Art\u00edstica Brasileira","description":"O Carnaval \u00e9 a principal festa popular do pa\u00eds e \u00e9 uma celebra\u00e7\u00e3o que ajuda a entender a nossa Hist\u00f3ria. Samba-enredo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sabra.org.br\/site\/samba-enredo\/","og_locale":"pt_BR","og_type":"article","og_title":"Sambas-enredo que entraram para a hist\u00f3ria - SABRA - Sociedade Art\u00edstica Brasileira","og_description":"O Carnaval \u00e9 a principal festa popular do pa\u00eds e \u00e9 uma celebra\u00e7\u00e3o que ajuda a entender a nossa Hist\u00f3ria. Samba-enredo","og_url":"https:\/\/www.sabra.org.br\/site\/samba-enredo\/","og_site_name":"SABRA - Sociedade Art\u00edstica Brasileira","article_publisher":"https:\/\/www.facebook.com\/sabrabrasil","article_published_time":"2022-04-01T13:45:48+00:00","og_image":[{"width":800,"height":531,"url":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/04\/x-sambas-enredo-que-entraram-para-a-historia-20211111161807.jpg.jpg?fit=800%2C531&ssl=1","type":"image\/jpeg"}],"author":"M\u00e1rcio Miranda Pontes","twitter_card":"summary_large_image","twitter_creator":"@ContatoSabra","twitter_site":"@ContatoSabra","twitter_misc":{"Escrito por":"M\u00e1rcio Miranda Pontes","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sabra.org.br\/site\/samba-enredo\/#article","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/samba-enredo\/"},"author":{"name":"M\u00e1rcio Miranda Pontes","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2"},"headline":"Sambas-enredo que entraram para a hist\u00f3ria","datePublished":"2022-04-01T13:45:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/samba-enredo\/"},"wordCount":1014,"publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/samba-enredo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/04\/x-sambas-enredo-que-entraram-para-a-historia-20211111161807.jpg.jpg","keywords":["Assist\u00eancia social","Cabo Frio","Campos dos Goytacazes","Canto Coral","Escola de Musica SABRA","Musicaliza\u00e7\u00e3o Infantil","nova lima","Orquestra Infanto Juvenil de Betim","Orquestra Sinf\u00f4nica de Betim","Raposos","Sociedade Art\u00edstica Brasileira"],"articleSection":["Blog SABRA"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.sabra.org.br\/site\/samba-enredo\/","url":"https:\/\/www.sabra.org.br\/site\/samba-enredo\/","name":"Sambas-enredo que entraram para a hist\u00f3ria - SABRA - Sociedade Art\u00edstica Brasileira","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/samba-enredo\/#primaryimage"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/samba-enredo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/04\/x-sambas-enredo-que-entraram-para-a-historia-20211111161807.jpg.jpg","datePublished":"2022-04-01T13:45:48+00:00","description":"O Carnaval \u00e9 a principal festa popular do pa\u00eds e \u00e9 uma celebra\u00e7\u00e3o que ajuda a entender a nossa Hist\u00f3ria. Samba-enredo","breadcrumb":{"@id":"https:\/\/www.sabra.org.br\/site\/samba-enredo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sabra.org.br\/site\/samba-enredo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/samba-enredo\/#primaryimage","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/04\/x-sambas-enredo-que-entraram-para-a-historia-20211111161807.jpg.jpg","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/04\/x-sambas-enredo-que-entraram-para-a-historia-20211111161807.jpg.jpg","width":800,"height":531,"caption":"Sociedade Art\u00edstica Brasileira SABRA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sabra.org.br\/site\/samba-enredo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.sabra.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Sambas-enredo que entraram para a hist\u00f3ria"}]},{"@type":"WebSite","@id":"https:\/\/www.sabra.org.br\/site\/#website","url":"https:\/\/www.sabra.org.br\/site\/","name":"SABRA - Sociedade Art\u00edstica Brasileira","description":"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico","publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sabra.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.sabra.org.br\/site\/#organization","name":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA","alternateName":"SABRA","url":"https:\/\/www.sabra.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","width":400,"height":128,"caption":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabrabrasil","https:\/\/x.com\/ContatoSabra","https:\/\/www.instagram.com\/sabrabrasil\/","https:\/\/www.linkedin.com\/company\/25002088\/","https:\/\/br.pinterest.com\/sociedadeartisticabrasileira\/","https:\/\/www.youtube.com\/c\/sabrabrasil"]},{"@type":"Person","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2","name":"M\u00e1rcio Miranda Pontes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","caption":"M\u00e1rcio Miranda Pontes"},"sameAs":["http:\/\/www.sabra.org.br"],"url":"https:\/\/www.sabra.org.br\/site\/author\/marcio-miranda-pontes\/"}]}},"jetpack_featured_media_url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/04\/x-sambas-enredo-que-entraram-para-a-historia-20211111161807.jpg.jpg","jetpack_shortlink":"https:\/\/wp.me\/p95j2Z-1gH","jetpack-related-posts":[{"id":4186,"url":"https:\/\/www.sabra.org.br\/site\/os-pilares-da-musica-brasileira-generos\/","url_meta":{"origin":4879,"position":0},"title":"Os pilares da m\u00fasica brasileira","author":"M\u00e1rcio Miranda Pontes","date":"17 de setembro de 2021","format":false,"excerpt":"Os pilares da m\u00fasica brasileira No Brasil, a m\u00fasica \u00e9 considerada uma das manifesta\u00e7\u00f5es mais importantes de arte e cultura. Para que voc\u00ea entenda quais s\u00e3o os principais pilares da m\u00fasica brasileira, elaboramos um conte\u00fado. Veja! Patroci\u0301nio m\u00e1ster: @institutounimedbh, viabilizado pelo incentivo de mais de 5,2 mil m\u00e9dicos cooperados e\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"samba-g\u00eaneros-musical-brasileira","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/09\/os-pilares-da-musica-brasileira-20210803101037.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/09\/os-pilares-da-musica-brasileira-20210803101037.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/09\/os-pilares-da-musica-brasileira-20210803101037.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/09\/os-pilares-da-musica-brasileira-20210803101037.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6384,"url":"https:\/\/www.sabra.org.br\/site\/musica-poesia\/","url_meta":{"origin":4879,"position":1},"title":"O v\u00ednculo entre a poesia e a m\u00fasica","author":"M\u00e1rcio Miranda Pontes","date":"8 de dezembro de 2022","format":false,"excerpt":"A poesia e a m\u00fasica, apesar de serem express\u00f5es art\u00edsticas que podem existir muito bem separadamente, t\u00eam uma hist\u00f3ria em comum, que prova este v\u00ednculo.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"m\u00fasica-poesia-tempo","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/12\/o-vinculo-entre-a-poesia-e-a-musica-20221024103355.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/12\/o-vinculo-entre-a-poesia-e-a-musica-20221024103355.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/12\/o-vinculo-entre-a-poesia-e-a-musica-20221024103355.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/12\/o-vinculo-entre-a-poesia-e-a-musica-20221024103355.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13107,"url":"https:\/\/www.sabra.org.br\/site\/conheca-os-principais-tipos-de-samba\/","url_meta":{"origin":4879,"position":2},"title":"Conhe\u00e7a os principais tipos de samba","author":"","date":"22 de agosto de 2025","format":false,"excerpt":"O samba \u00e9 uma das manifesta\u00e7\u00f5es culturais mais emblem\u00e1ticas do Brasil, conhecido por sua energia vibrante, ritmos cativantes e profunda liga\u00e7\u00e3o com a hist\u00f3ria e a identidade nacional. Origin\u00e1rio das tradi\u00e7\u00f5es afro-brasileiras, o samba evoluiu ao longo dos anos, resultando em diversas varia\u00e7\u00f5es que refletem a riqueza e a diversidade\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4669,"url":"https:\/\/www.sabra.org.br\/site\/imaterial\/","url_meta":{"origin":4879,"position":3},"title":"Manifesta\u00e7\u00f5es culturais consideradas patrim\u00f4nio imaterial do Brasil","author":"M\u00e1rcio Miranda Pontes","date":"11 de fevereiro de 2022","format":false,"excerpt":"Entenda o que \u00e9 patrim\u00f4nio imaterial e veja exemplos de manifesta\u00e7\u00f5es culturais de todo o Brasil, que representam a sua hist\u00f3ria, cultura, diversidade, modos de fazer e of\u00edcios passados de gera\u00e7\u00e3o para gera\u00e7\u00e3o.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"manifestacoes-culturais-consideradas-patrimonio-imaterial-do-brasil","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/02\/manifestacoes-culturais-consideradas-patrimonio-imaterial-do-brasil-20220208141739.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/02\/manifestacoes-culturais-consideradas-patrimonio-imaterial-do-brasil-20220208141739.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/02\/manifestacoes-culturais-consideradas-patrimonio-imaterial-do-brasil-20220208141739.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/02\/manifestacoes-culturais-consideradas-patrimonio-imaterial-do-brasil-20220208141739.jpg.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2022\/02\/manifestacoes-culturais-consideradas-patrimonio-imaterial-do-brasil-20220208141739.jpg.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":13457,"url":"https:\/\/www.sabra.org.br\/site\/compositor-brasileiro\/","url_meta":{"origin":4879,"position":4},"title":"6 compositores brasileiros que voc\u00ea precisa conhecer","author":"M\u00e1rcio Miranda Pontes","date":"4 de junho de 2025","format":false,"excerpt":"Explore as contribui\u00e7\u00f5es dos compositores brasileiros para a m\u00fasica. Tente ouvir esses 6 grandes mestres da composi\u00e7\u00e3o.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2213,"url":"https:\/\/www.sabra.org.br\/site\/bossa-nova\/","url_meta":{"origin":4879,"position":5},"title":"Bossa Nova","author":"M\u00e1rcio Miranda Pontes","date":"9 de julho de 2019","format":false,"excerpt":"bossa nova m\u00fasica popular brasileira mpb tom jobim e vinicius de moraes chega de saudade Jo\u00e3o Gilberto","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"Bossa nova","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/07\/bossa-nova-696x464.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/07\/bossa-nova-696x464.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/07\/bossa-nova-696x464.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/4879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/comments?post=4879"}],"version-history":[{"count":0,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/4879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media\/4880"}],"wp:attachment":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media?parent=4879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/categories?post=4879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/tags?post=4879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}