{"id":7002,"date":"2023-04-28T22:09:01","date_gmt":"2023-04-29T01:09:01","guid":{"rendered":"https:\/\/www.sabra.org.br\/site\/?p=7002"},"modified":"2023-04-28T22:09:01","modified_gmt":"2023-04-29T01:09:01","slug":"aprender-instrumento-2","status":"publish","type":"post","link":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/","title":{"rendered":"Instrumentos mais f\u00e1ceis para se aprender a tocar"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Muita gente tem vontade de entrar no mundo da m\u00fasica e aprender a tocar um instrumento musical, mas n\u00e3o sabe qual seria a melhor op\u00e7\u00e3o para iniciantes. Outros j\u00e1 tocam algum instrumento, mas queriam expandir seus conhecimentos e testar algo novo. Nesses casos, \u00e9 comum as pessoas buscarem instrumentos conhecidos por serem mais f\u00e1ceis de aprender.<\/p>\n<p>No momento da escolha \u00e9 preciso levar em conta que o grau de dificuldade tamb\u00e9m depende de outros fatores, como a aptid\u00e3o de cada um \u2013 algumas pessoas t\u00eam mais facilidade para tocar instrumentos de corda, por exemplo, e sofrem ao tentar aprender percuss\u00e3o. Portanto, \u00e9 importante observar n\u00e3o apenas o gosto, mas a habilidade de cada um. Se poss\u00edvel, ter um contato inicial com v\u00e1rios instrumentos antes de fazer sua decis\u00e3o final.<\/p>\n<p>Outra quest\u00e3o v\u00e1lida de se lembrar \u00e9 que alguns instrumentos s\u00e3o muito simples de aprender no n\u00edvel b\u00e1sico, mas conforme o aluno vai se aprofundando, a complexidade aumenta.<\/p>\n<p>Com tantos aspectos para se levar em conta antes de come\u00e7ar a aprender um instrumento musical, confira uma lista dos que s\u00e3o considerados mais f\u00e1ceis de aprender a tocar para te auxiliar a decidir qual deles voc\u00ea quer dominar!<\/p>\n<h3>1. Chocalho<\/h3>\n<p>De modo geral, podemos dizer que os instrumentos de percuss\u00e3o s\u00e3o mais simples de aprender. Para tocar o chocalho n\u00e3o tem muito segredo, e por isso mesmo \u00e9 bastante usado para trabalhar com crian\u00e7as, basta mexer o instrumento no ritmo da m\u00fasica e pronto.<\/p>\n<h3>2. Baixo<\/h3>\n<p>Quando pensamos em aprender um instrumento de cordas, logo nos vem \u00e0 cabe\u00e7a o viol\u00e3o. Nesse grupo de instrumentos muitos m\u00fasicos consideram o baixo como mais f\u00e1cil para iniciantes e com resultados b\u00e1sicos que aparecem rapidamente, tendo sua complexidade aumentada conforme o estudante avan\u00e7a na sua educa\u00e7\u00e3o musical.<\/p>\n<h3>3. Tri\u00e2ngulo<\/h3>\n<p>Outro instrumento de percuss\u00e3o, muito usado em m\u00fasicas de forr\u00f3. \u00c9 preciso aprender como e quando abafar o som e pegar as batidas da m\u00fasica, mas n\u00e3o tem um grande grau de complexidade.<\/p>\n<h3>3. Bateria<\/h3>\n<p>Uma das escolhas preferidas dos f\u00e3s de rock, a bateria \u00e9 bastante intuitiva e \u00e9 um daqueles instrumentos que s\u00e3o famosos pela facilidade para aprender a tocar, mas que pode ter seu n\u00edvel de dificuldade muito aumentado para quem quer dominar verdadeiramente o instrumento.<\/p>\n<h3>4. Gaita<\/h3>\n<p>Instrumentos de sopro em geral s\u00e3o considerados dif\u00edceis de aprender a tocar, mas a gaita \u00e9 bastante simples para iniciantes e aparece em in\u00fameras m\u00fasicas populares. Como em pouco tempo voc\u00ea come\u00e7a a ver resultados, isso motiva o aluno a continuar na sua educa\u00e7\u00e3o musical.<\/p>\n<h3>5. Bong\u00f4<\/h3>\n<p>O som do bong\u00f4 varia conforme os tipos de batida que voc\u00ea d\u00e1 no instrumento (nas bordas ou no centro e com as diferentes partes das m\u00e3os), mas o mecanismo de tocar \u00e9 simples e voc\u00ea consegue pegar a ideia inicial r\u00e1pido.<\/p>\n<h3>6. Flauta doce<\/h3>\n<p>Esse \u00e9 o instrumento de sopro mais utilizado por iniciantes exatamente pela facilidade de se dominar o b\u00e1sico. Al\u00e9m disso, ao contr\u00e1rio de outros instrumentos do mesmo grupo, n\u00e3o h\u00e1 muitos segredos na embocadura.<\/p>\n<hr \/>\n<h2>Se voc\u00ea gostou deste post:<\/h2>\n<p>&#8211; SIGA as nossas p\u00e1ginas nas redes sociais para acompanhar as nossas atualiza\u00e7\u00f5es: estamos no <a href=\"https:\/\/www.facebook.com\/sabrabrasil\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>, no <a href=\"https:\/\/www.instagram.com\/sabrabrasil\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a>, no <a href=\"https:\/\/www.linkedin.com\/company\/25002088\" target=\"_blank\" rel=\"noopener\">LinkedIn<\/a>, no <a href=\"https:\/\/twitter.com\/ContatoSabra\" target=\"_blank\" rel=\"noopener\">Twitter<\/a> e no <a href=\"https:\/\/www.youtube.com\/channel\/UCJw-kbuEvzUNdeQf20Pa-eQ\" target=\"_blank\" rel=\"noopener\">YouTube<\/a>!<\/p>\n<p>&#8211; CONHE\u00c7A o trabalho da Sociedade Art\u00edstica Brasileira (SABRA) e todas as iniciativas culturais e sociais que ela mant\u00e9m. <a href=\"https:\/\/www.sabra.org.br\/site\/acoes\/\" target=\"_blank\" rel=\"noopener\">Acesse nosso site!<\/a><\/p>\n<p>&#8211; ENTRE EM CONTATO com a gente. E veja quais s\u00e3o as op\u00e7\u00f5es de ajuda na manuten\u00e7\u00e3o de nossas a\u00e7\u00f5es sociais e culturais. Basta acessar nossa p\u00e1gina <a href=\"https:\/\/www.sabra.org.br\/site\/doe-agora\/\" target=\"_blank\" rel=\"noopener\">Doe Agora!<\/a><\/p>\n<p>&#8211; COMPARTILHE este texto nas suas redes sociais e ajude os seus amigos a tamb\u00e9m dominarem o assunto!<\/p>\n<p>\u2013 Os projetos da @sabrabrasil s\u00e3o realizados com o patroci\u0301nio m\u00e1ster: @institutounimedbh, viabilizado pelo incentivo de mais de 5,2 mil m\u00e9dicos cooperados e colaboradores via Lei de Incentivo \u00e0 Cultura &#8211; @culturagovbr<\/p>\n<p>https:\/\/www.sabra.org.br\/site\/sanfona\/[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um dos instrumentos mais populares, o viol\u00e3o n\u00e3o \u00e9 um dos mais f\u00e1ceis para quem quer aprender a tocar algo. Descubra no texto abaixo os instrumentos mais f\u00e1ceis para iniciantes!<\/p>\n","protected":false},"author":39,"featured_media":7004,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[15,2757,3626,3623,8,3629,1285,3628,16,3519,1286,11,3622,9],"class_list":["post-7002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-sabra","tag-assistencia-social","tag-belo-horizonte","tag-cabo-frio","tag-campos-dos-goytacazes","tag-canto-coral","tag-contagem","tag-escola-de-musica-sabra","tag-ibirite","tag-musicalizacao-infantil","tag-nova-lima-2","tag-orquestra-infanto-juvenil-de-betim","tag-orquestra-sinfonica-de-betim","tag-raposos","tag-sociedade-artistica-brasileira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Instrumentos mais f\u00e1ceis para se aprender a tocar<\/title>\n<meta name=\"description\" content=\"Um dos instrumentos mais populares, o viol\u00e3o n\u00e3o \u00e9 um dos mais f\u00e1ceis para quem quer aprender a tocar algo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Instrumentos mais f\u00e1ceis para se aprender a tocar\" \/>\n<meta property=\"og:description\" content=\"Um dos instrumentos mais populares, o viol\u00e3o n\u00e3o \u00e9 um dos mais f\u00e1ceis para quem quer aprender a tocar algo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SABRA - Sociedade Art\u00edstica Brasileira\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabrabrasil\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-29T01:09:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/04\/instrumentos-mais-faceis-para-se-aprender-a-tocar-20171219145022.jpg.jpg?fit=1619%2C1080&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1619\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:site\" content=\"@ContatoSabra\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00e1rcio Miranda Pontes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aprender-instrumento-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aprender-instrumento-2\\\/\"},\"author\":{\"name\":\"M\u00e1rcio Miranda Pontes\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\"},\"headline\":\"Instrumentos mais f\u00e1ceis para se aprender a tocar\",\"datePublished\":\"2023-04-29T01:09:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aprender-instrumento-2\\\/\"},\"wordCount\":706,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aprender-instrumento-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/instrumentos-mais-faceis-para-se-aprender-a-tocar-20171219145022.jpg.jpg\",\"keywords\":[\"Assist\u00eancia social\",\"Belo Horizonte\",\"Cabo Frio\",\"Campos dos Goytacazes\",\"Canto Coral\",\"Contagem\",\"Escola de Musica SABRA\",\"Ibirit\u00e9\",\"Musicaliza\u00e7\u00e3o Infantil\",\"nova lima\",\"Orquestra Infanto Juvenil de Betim\",\"Orquestra Sinf\u00f4nica de Betim\",\"Raposos\",\"Sociedade Art\u00edstica Brasileira\"],\"articleSection\":[\"Blog SABRA\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aprender-instrumento-2\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aprender-instrumento-2\\\/\",\"name\":\"Instrumentos mais f\u00e1ceis para se aprender a tocar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aprender-instrumento-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aprender-instrumento-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/instrumentos-mais-faceis-para-se-aprender-a-tocar-20171219145022.jpg.jpg\",\"datePublished\":\"2023-04-29T01:09:01+00:00\",\"description\":\"Um dos instrumentos mais populares, o viol\u00e3o n\u00e3o \u00e9 um dos mais f\u00e1ceis para quem quer aprender a tocar algo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aprender-instrumento-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aprender-instrumento-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aprender-instrumento-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/instrumentos-mais-faceis-para-se-aprender-a-tocar-20171219145022.jpg.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/instrumentos-mais-faceis-para-se-aprender-a-tocar-20171219145022.jpg.jpg\",\"width\":1619,\"height\":1080,\"caption\":\"Sociedade Art\u00edstica Brasileira SABRA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/aprender-instrumento-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Instrumentos mais f\u00e1ceis para se aprender a tocar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"name\":\"SABRA - Sociedade Art\u00edstica Brasileira\",\"description\":\"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#organization\",\"name\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\",\"alternateName\":\"SABRA\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/cropped-Logo_SABRA-Copia-1.webp\",\"width\":400,\"height\":128,\"caption\":\"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sabrabrasil\",\"https:\\\/\\\/x.com\\\/ContatoSabra\",\"https:\\\/\\\/www.instagram.com\\\/sabrabrasil\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/25002088\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/sociedadeartisticabrasileira\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/sabrabrasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/#\\\/schema\\\/person\\\/7d1d222c3c8891d4c37c7b41bf6315c2\",\"name\":\"M\u00e1rcio Miranda Pontes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g\",\"caption\":\"M\u00e1rcio Miranda Pontes\"},\"sameAs\":[\"http:\\\/\\\/www.sabra.org.br\"],\"url\":\"https:\\\/\\\/www.sabra.org.br\\\/site\\\/author\\\/marcio-miranda-pontes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Instrumentos mais f\u00e1ceis para se aprender a tocar","description":"Um dos instrumentos mais populares, o viol\u00e3o n\u00e3o \u00e9 um dos mais f\u00e1ceis para quem quer aprender a tocar algo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Instrumentos mais f\u00e1ceis para se aprender a tocar","og_description":"Um dos instrumentos mais populares, o viol\u00e3o n\u00e3o \u00e9 um dos mais f\u00e1ceis para quem quer aprender a tocar algo.","og_url":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/","og_site_name":"SABRA - Sociedade Art\u00edstica Brasileira","article_publisher":"https:\/\/www.facebook.com\/sabrabrasil","article_published_time":"2023-04-29T01:09:01+00:00","og_image":[{"width":1619,"height":1080,"url":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/04\/instrumentos-mais-faceis-para-se-aprender-a-tocar-20171219145022.jpg.jpg?fit=1619%2C1080&ssl=1","type":"image\/jpeg"}],"author":"M\u00e1rcio Miranda Pontes","twitter_card":"summary_large_image","twitter_creator":"@ContatoSabra","twitter_site":"@ContatoSabra","twitter_misc":{"Escrito por":"M\u00e1rcio Miranda Pontes","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/#article","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/"},"author":{"name":"M\u00e1rcio Miranda Pontes","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2"},"headline":"Instrumentos mais f\u00e1ceis para se aprender a tocar","datePublished":"2023-04-29T01:09:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/"},"wordCount":706,"publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/04\/instrumentos-mais-faceis-para-se-aprender-a-tocar-20171219145022.jpg.jpg","keywords":["Assist\u00eancia social","Belo Horizonte","Cabo Frio","Campos dos Goytacazes","Canto Coral","Contagem","Escola de Musica SABRA","Ibirit\u00e9","Musicaliza\u00e7\u00e3o Infantil","nova lima","Orquestra Infanto Juvenil de Betim","Orquestra Sinf\u00f4nica de Betim","Raposos","Sociedade Art\u00edstica Brasileira"],"articleSection":["Blog SABRA"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/","url":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/","name":"Instrumentos mais f\u00e1ceis para se aprender a tocar","isPartOf":{"@id":"https:\/\/www.sabra.org.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/#primaryimage"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/04\/instrumentos-mais-faceis-para-se-aprender-a-tocar-20171219145022.jpg.jpg","datePublished":"2023-04-29T01:09:01+00:00","description":"Um dos instrumentos mais populares, o viol\u00e3o n\u00e3o \u00e9 um dos mais f\u00e1ceis para quem quer aprender a tocar algo.","breadcrumb":{"@id":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/#primaryimage","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/04\/instrumentos-mais-faceis-para-se-aprender-a-tocar-20171219145022.jpg.jpg","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/04\/instrumentos-mais-faceis-para-se-aprender-a-tocar-20171219145022.jpg.jpg","width":1619,"height":1080,"caption":"Sociedade Art\u00edstica Brasileira SABRA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.sabra.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Instrumentos mais f\u00e1ceis para se aprender a tocar"}]},{"@type":"WebSite","@id":"https:\/\/www.sabra.org.br\/site\/#website","url":"https:\/\/www.sabra.org.br\/site\/","name":"SABRA - Sociedade Art\u00edstica Brasileira","description":"Escola de M\u00fasica, Orquestra Sinf\u00f4nica, Coral e Patrim\u00f4nio Cultural e Hist\u00f3rico","publisher":{"@id":"https:\/\/www.sabra.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sabra.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.sabra.org.br\/site\/#organization","name":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA","alternateName":"SABRA","url":"https:\/\/www.sabra.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","contentUrl":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2019\/06\/cropped-Logo_SABRA-Copia-1.webp","width":400,"height":128,"caption":"SOCIEDADE ART\u00cdSTICA BRASILEIRA SABRA"},"image":{"@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabrabrasil","https:\/\/x.com\/ContatoSabra","https:\/\/www.instagram.com\/sabrabrasil\/","https:\/\/www.linkedin.com\/company\/25002088\/","https:\/\/br.pinterest.com\/sociedadeartisticabrasileira\/","https:\/\/www.youtube.com\/c\/sabrabrasil"]},{"@type":"Person","@id":"https:\/\/www.sabra.org.br\/site\/#\/schema\/person\/7d1d222c3c8891d4c37c7b41bf6315c2","name":"M\u00e1rcio Miranda Pontes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b45f24496a7625a3a6c436688fbe20344faaeb2979658dc4a9921f984d7df9a?s=96&d=mm&r=g","caption":"M\u00e1rcio Miranda Pontes"},"sameAs":["http:\/\/www.sabra.org.br"],"url":"https:\/\/www.sabra.org.br\/site\/author\/marcio-miranda-pontes\/"}]}},"jetpack_featured_media_url":"https:\/\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/04\/instrumentos-mais-faceis-para-se-aprender-a-tocar-20171219145022.jpg.jpg","jetpack_shortlink":"https:\/\/wp.me\/p95j2Z-1OW","jetpack-related-posts":[{"id":7710,"url":"https:\/\/www.sabra.org.br\/site\/clarinete-instrumento\/","url_meta":{"origin":7002,"position":0},"title":"\u00c9 dif\u00edcil aprender a tocar clarinete?","author":"M\u00e1rcio Miranda Pontes","date":"26 de julho de 2023","format":false,"excerpt":"Se voc\u00ea quer iniciar no mundo da m\u00fasica aprendendo a tocar clarinete mas tem d\u00favidas sobre o assunto, saiba que podemos te ajudar. Confira mais informa\u00e7\u00f5es sobre esse instrumento a seguir:","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"sabra-m\u00fasica-clarinete-instrumentos-tocar-aprender-m\u00fasicos-possuem","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/07\/e-dificil-aprender-a-tocar-clarinetejpg-20230504105610.jpg-jpg.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/07\/e-dificil-aprender-a-tocar-clarinetejpg-20230504105610.jpg-jpg.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/07\/e-dificil-aprender-a-tocar-clarinetejpg-20230504105610.jpg-jpg.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/07\/e-dificil-aprender-a-tocar-clarinetejpg-20230504105610.jpg-jpg.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4190,"url":"https:\/\/www.sabra.org.br\/site\/aprender-instrumento\/","url_meta":{"origin":7002,"position":1},"title":"Qual o melhor instrumento musical para iniciantes?","author":"M\u00e1rcio Miranda Pontes","date":"20 de setembro de 2021","format":false,"excerpt":"Qual o melhor instrumento musical para iniciantes? \u00c9 importante destacar que cada instrumento musical possui um certo grau de dificuldade, por\u00e9m, de acordo com caracter\u00edsticas espec\u00edficas, alguns deles podem ser mais f\u00e1ceis de aprender. Pensando nisso, preparamos um conte\u00fado para apresentar os instrumentos musicais ideais para iniciantes. Confira nossas recomenda\u00e7\u00f5es!\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"instrumento-musical-aprender-conhecer-aprendizado-teclado","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/09\/qual-o-melhor-instrumento-musical-para-iniciantes-20210803101037.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/09\/qual-o-melhor-instrumento-musical-para-iniciantes-20210803101037.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/09\/qual-o-melhor-instrumento-musical-para-iniciantes-20210803101037.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/09\/qual-o-melhor-instrumento-musical-para-iniciantes-20210803101037.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13334,"url":"https:\/\/www.sabra.org.br\/site\/quarentena-um-otimo-momento-para-aprender-a-tocar-um-instrumento\/","url_meta":{"origin":7002,"position":2},"title":"Quarentena: um \u00f3timo momento para aprender a tocar um instrumento","author":"","date":"22 de agosto de 2025","format":false,"excerpt":"Com a quarentena causada pela Covid-19, muitas pessoas est\u00e3o procurando a melhor forma de usar o tempo livre. Investir em atividades, cursos e projetos que voc\u00ea sempre quis, mas nunca teve tempo, pode ser uma boa op\u00e7\u00e3o. Ainda melhor se for para aprender algo novo, como um instrumento musical. Ficou\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7731,"url":"https:\/\/www.sabra.org.br\/site\/musicas-faceis-para-instrumento\/","url_meta":{"origin":7002,"position":3},"title":"10 musicas f\u00e1ceis para aprender a tocar","author":"M\u00e1rcio Miranda Pontes","date":"28 de julho de 2023","format":false,"excerpt":"Conhe\u00e7a 10 m\u00fasicas f\u00e1ceis para aprender a tocar. Aprender um novo instrumento \u00e9 uma jornada divertida, mas tamb\u00e9m desafiadora. Por isso, conhe\u00e7a as m\u00fasicas que v\u00e3o te ajudar neste processo.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"sabra-m\u00fasica-aprender-acordes-instrumento-tocar-b\u00e1sicos-musicais-come\u00e7ar-pr\u00e1tica-progress\u00e3o","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/07\/x-musicas-faceis-para-aprender-a-tocarjpg-20230504105610.jpg-jpg.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/07\/x-musicas-faceis-para-aprender-a-tocarjpg-20230504105610.jpg-jpg.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/07\/x-musicas-faceis-para-aprender-a-tocarjpg-20230504105610.jpg-jpg.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2023\/07\/x-musicas-faceis-para-aprender-a-tocarjpg-20230504105610.jpg-jpg.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13307,"url":"https:\/\/www.sabra.org.br\/site\/e-dificil-aprender-a-tocar-piano\/","url_meta":{"origin":7002,"position":4},"title":"\u00c9 dif\u00edcil aprender a tocar piano?","author":"","date":"22 de agosto de 2025","format":false,"excerpt":"Sem d\u00favidas, um dos instrumentos mais lindos de se ouvir \u00e9 o piano. No entanto, muita gente ainda acredita que seja dif\u00edcil aprender a toc\u00e1-lo, especialmente por ser um instrumento de teclas. De fato, o aprendizado pode at\u00e9 n\u00e3o ser t\u00e3o f\u00e1cil \u2014 considerando outros instrumentos mais f\u00e1ceis de aprender.\u2026","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4470,"url":"https:\/\/www.sabra.org.br\/site\/escolher-instrumento\/","url_meta":{"origin":7002,"position":5},"title":"Saiba como escolher o instrumento ideal para tocar","author":"M\u00e1rcio Miranda Pontes","date":"23 de dezembro de 2021","format":false,"excerpt":"Se voc\u00ea est\u00e1 em d\u00favida de qual instrumento escolher para tocar, confira a seguir algumas dicas que v\u00e3o ajud\u00e1-lo a elucidar e tomar a decis\u00e3o certa. Separamos algumas dicas que v\u00e3o ajudar voc\u00ea a refletir melhor e tomar a decis\u00e3o mais certa para o momento.","rel":"","context":"Em &quot;Blog SABRA&quot;","block_context":{"text":"Blog SABRA","link":"https:\/\/www.sabra.org.br\/site\/category\/blog-sabra\/"},"img":{"alt_text":"instrumento-musical-escolher","src":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/12\/saiba-como-escolher-o-instrumento-ideal-para-tocar-20211027111153.jpg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/12\/saiba-como-escolher-o-instrumento-ideal-para-tocar-20211027111153.jpg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/12\/saiba-como-escolher-o-instrumento-ideal-para-tocar-20211027111153.jpg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sabra.org.br\/site\/wp-content\/uploads\/2021\/12\/saiba-como-escolher-o-instrumento-ideal-para-tocar-20211027111153.jpg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/7002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/comments?post=7002"}],"version-history":[{"count":0,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/posts\/7002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media\/7004"}],"wp:attachment":[{"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/media?parent=7002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/categories?post=7002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sabra.org.br\/site\/wp-json\/wp\/v2\/tags?post=7002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}